{"id":5238,"date":"2023-04-25T20:14:18","date_gmt":"2023-04-25T23:14:18","guid":{"rendered":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/04\/25\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\/"},"modified":"2023-04-25T20:14:18","modified_gmt":"2023-04-25T23:14:18","slug":"comissao-debate-iptu-verde-na-cidade-de-salvador-ba","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/04\/25\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\/","title":{"rendered":"Comiss\u00e3o debate IPTU Verde na cidade de Salvador-BA"},"content":{"rendered":"<p style=\"text-align: justify\"><span style=\"font-weight: 400\">A Comiss\u00e3o de Meio Ambiente (CMA) da C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC) participou na \u00faltima ter\u00e7a-feira (18) de debate sobre a atualiza\u00e7\u00e3o do programa IPTU Verde da cidade de Salvador-BA. O presidente da CMA, Nilson Sarti, abriu o evento, que foi promovido pela Associa\u00e7\u00e3o de Dirigentes de Empresas do Mercado Imobili\u00e1rio da Bahia &#8211; ADEMI-BA.\u00a0<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Al\u00e9m disso, o encontrou contou com palestra do\u00a0 engenheiro civil e correspons\u00e1vel pelos estudos de Engenharia \u00e0 Montante do N\u00facleo de Obras de Incorpora\u00e7\u00e3o (NOI) na Civil Construtora, \u00cdcaro Limoeiro.\u00a0<\/span><\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">O profissional apresentou as modifica\u00e7\u00f5es do decreto do IPTU Verde de Salvador e seus principais pontos nos empreendimentos residenciais.\u00a0 &#8220;Essa atualiza\u00e7\u00e3o trouxe maior flexibilidade com um aumento no n\u00famero de itens e altera\u00e7\u00f5es em itens importantes da tabela&#8221;, apontou Limoeiro.\u00a0\u00a0<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">&#8220;Eventos como esse s\u00e3o importantes para trazer a discuss\u00e3o sobre constru\u00e7\u00f5es sustent\u00e1veis, bem como gerar entendimento acerca de como o poder p\u00fablico tem trazido e conduzido isso juntamente com as incorporadoras do estado, encabe\u00e7ada pela ADEMI&#8221;, destacou o engenheiro.\u00a0<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">O evento acontece periodicamente para realizar a atualiza\u00e7\u00e3o do projeto cidades resilientes e a defini\u00e7\u00e3o de novas metas a serem atingidas pela cidade. De acordo com Sarti, a CBIC tem estimulado cada vez mais a iniciativa e a utiliza\u00e7\u00e3o desses instrumentos tamb\u00e9m em outras cidades para o desenvolvimento e melhoria dos projetos, concluiu.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Comiss\u00e3o de Meio Ambiente (CMA) da C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC) participou na \u00faltima ter\u00e7a-feira (18) de debate sobre a atualiza\u00e7\u00e3o do programa IPTU Verde da cidade de Salvador-BA. O presidente da CMA, Nilson Sarti, abriu o evento, que foi promovido pela [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":5239,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[97,175],"tags":[],"class_list":["post-5238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-cbic","category-sustentabilidade-agencia-cbic"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comiss\u00e3o debate IPTU Verde na cidade de Salvador-BA - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/2023\/04\/25\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comiss\u00e3o debate IPTU Verde na cidade de Salvador-BA - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"A Comiss\u00e3o de Meio Ambiente (CMA) da C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC) participou na \u00faltima ter\u00e7a-feira (18) de debate sobre a atualiza\u00e7\u00e3o do programa IPTU Verde da cidade de Salvador-BA. O presidente da CMA, Nilson Sarti, abriu o evento, que foi promovido pela [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/2023\/04\/25\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-25T23:14:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2023\/08\/whatsapp-image-2023-04-20-at-140507.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"963\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"gustavo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"gustavo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/04\\\/25\\\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/04\\\/25\\\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\\\/\"},\"author\":{\"name\":\"gustavo\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/671df35c7bda5d311f455af67beb3604\"},\"headline\":\"Comiss\u00e3o debate IPTU Verde na cidade de Salvador-BA\",\"datePublished\":\"2023-04-25T23:14:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/04\\\/25\\\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\\\/\"},\"wordCount\":252,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/04\\\/25\\\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2023\\\/08\\\/whatsapp-image-2023-04-20-at-140507.jpeg\",\"articleSection\":[\"Ag\u00eancia CBIC\",\"Sustentabilidade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/04\\\/25\\\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/04\\\/25\\\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/04\\\/25\\\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\\\/\",\"name\":\"Comiss\u00e3o debate IPTU Verde na cidade de Salvador-BA - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/04\\\/25\\\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/04\\\/25\\\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2023\\\/08\\\/whatsapp-image-2023-04-20-at-140507.jpeg\",\"datePublished\":\"2023-04-25T23:14:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/671df35c7bda5d311f455af67beb3604\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/04\\\/25\\\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/04\\\/25\\\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/04\\\/25\\\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2023\\\/08\\\/whatsapp-image-2023-04-20-at-140507.jpeg\",\"contentUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2023\\\/08\\\/whatsapp-image-2023-04-20-at-140507.jpeg\",\"width\":1280,\"height\":963},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/04\\\/25\\\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comiss\u00e3o debate IPTU Verde na cidade de Salvador-BA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/671df35c7bda5d311f455af67beb3604\",\"name\":\"gustavo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b2345306fa0fb5f447d3d289e8c14ba785449d3e2ff64d9a02fb03cc029cf754?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b2345306fa0fb5f447d3d289e8c14ba785449d3e2ff64d9a02fb03cc029cf754?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b2345306fa0fb5f447d3d289e8c14ba785449d3e2ff64d9a02fb03cc029cf754?s=96&d=mm&r=g\",\"caption\":\"gustavo\"},\"sameAs\":[\"https:\\\/\\\/cbic.org.br\"],\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/gustavo-rodrigues\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comiss\u00e3o debate IPTU Verde na cidade de Salvador-BA - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/04\/25\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\/","og_locale":"pt_BR","og_type":"article","og_title":"Comiss\u00e3o debate IPTU Verde na cidade de Salvador-BA - Comiss\u00e3o de Meio Ambiente","og_description":"A Comiss\u00e3o de Meio Ambiente (CMA) da C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC) participou na \u00faltima ter\u00e7a-feira (18) de debate sobre a atualiza\u00e7\u00e3o do programa IPTU Verde da cidade de Salvador-BA. O presidente da CMA, Nilson Sarti, abriu o evento, que foi promovido pela [&hellip;]","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/04\/25\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2023-04-25T23:14:18+00:00","og_image":[{"width":1280,"height":963,"url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2023\/08\/whatsapp-image-2023-04-20-at-140507.jpeg","type":"image\/jpeg"}],"author":"gustavo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"gustavo","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/04\/25\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/04\/25\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\/"},"author":{"name":"gustavo","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/671df35c7bda5d311f455af67beb3604"},"headline":"Comiss\u00e3o debate IPTU Verde na cidade de Salvador-BA","datePublished":"2023-04-25T23:14:18+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/04\/25\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\/"},"wordCount":252,"commentCount":0,"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/04\/25\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2023\/08\/whatsapp-image-2023-04-20-at-140507.jpeg","articleSection":["Ag\u00eancia CBIC","Sustentabilidade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cbic.org.br\/sustentabilidade\/2023\/04\/25\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/04\/25\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/04\/25\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\/","name":"Comiss\u00e3o debate IPTU Verde na cidade de Salvador-BA - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/04\/25\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/04\/25\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2023\/08\/whatsapp-image-2023-04-20-at-140507.jpeg","datePublished":"2023-04-25T23:14:18+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/671df35c7bda5d311f455af67beb3604"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/04\/25\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/2023\/04\/25\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/04\/25\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\/#primaryimage","url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2023\/08\/whatsapp-image-2023-04-20-at-140507.jpeg","contentUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2023\/08\/whatsapp-image-2023-04-20-at-140507.jpeg","width":1280,"height":963},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/04\/25\/comissao-debate-iptu-verde-na-cidade-de-salvador-ba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"Comiss\u00e3o debate IPTU Verde na cidade de Salvador-BA"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/671df35c7bda5d311f455af67beb3604","name":"gustavo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b2345306fa0fb5f447d3d289e8c14ba785449d3e2ff64d9a02fb03cc029cf754?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b2345306fa0fb5f447d3d289e8c14ba785449d3e2ff64d9a02fb03cc029cf754?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b2345306fa0fb5f447d3d289e8c14ba785449d3e2ff64d9a02fb03cc029cf754?s=96&d=mm&r=g","caption":"gustavo"},"sameAs":["https:\/\/cbic.org.br"],"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/gustavo-rodrigues\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/5238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=5238"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/5238\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media\/5239"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=5238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=5238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=5238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}