{"id":5228,"date":"2023-05-25T19:23:15","date_gmt":"2023-05-25T22:23:15","guid":{"rendered":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/05\/25\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\/"},"modified":"2023-05-25T19:23:15","modified_gmt":"2023-05-25T22:23:15","slug":"cbic-busca-parceria-com-finlandia-para-construcao-com-madeira","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/05\/25\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\/","title":{"rendered":"CBIC busca parceria com Finl\u00e2ndia para constru\u00e7\u00e3o com madeira"},"content":{"rendered":"<p style=\"text-align: justify\"><span style=\"font-weight: 400\">A C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC) segue em mais uma etapa pela miss\u00e3o empresarial internacional sobre constru\u00e7\u00e3o com madeira. Nesta quinta-feira (25), o presidente da entidade, Jos\u00e9 Carlos Martins e o presidente da Comiss\u00e3o de Meio Ambiente (CMA) da CBIC, estiveram em reuni\u00e3o com o diretor da Confedera\u00e7\u00e3o Finlandesa da Constru\u00e7\u00e3o, Antti Aaltonen, no intuito de firmar parceria sobre o tema.\u00a0<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">De acordo com o presidente da CBIC, o encontro foi uma oportunidade para troca de experi\u00eancias sobre cen\u00e1rios, tecnologias e projetos para a constru\u00e7\u00e3o. &#8220;Esse interc\u00e2mbio de experi\u00eancias \u00e9 fundamental para o Brasil. Estamos em busca de parcerias para levar o melhor do mercado para o nosso setor e contribuir com a agenda da sustentabilidade&#8221;, apontou Martins.\u00a0<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Temas como BIM (<\/span><i><span style=\"font-weight: 400\">Building Information Modeling<\/span><\/i><span style=\"font-weight: 400\">) e transi\u00e7\u00e3o para a constru\u00e7\u00e3o em baixo carbono est\u00e3o na pauta do pr\u00f3ximo encontro, previsto para esta sexta-feira (26).\u00a0<\/span><\/p>\n<p style=\"text-align: justify\"><b>Comitiva na Su\u00e9cia<\/b><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Tecnologias constru\u00eddas com madeira foram destaque da miss\u00e3o na Su\u00e9cia, onde a CBIC visitou, com o grupo de empres\u00e1rios, as cidades de Skelleftea e Estocolmo. O pa\u00eds, que possui uma longa tradi\u00e7\u00e3o em constru\u00e7\u00e3o com madeira, disp\u00f5e de diretrizes de declara\u00e7\u00e3o do clima para o setor da constru\u00e7\u00e3o.\u00a0<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">O grupo visitou a Universidade de Lulea Tekniska, que tem uma unidade de Ci\u00eancia e Processamento da Madeira, al\u00e9m de a\u00e7\u00f5es regionais que promovem o uso e a inova\u00e7\u00e3o em madeira.\u00a0<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Na cidade de Estocolmo, a comitiva esteve na empresa Ligna Energia, que prop\u00f5e comercializar energia verde utilizando materiais sustent\u00e1veis e m\u00e9todos inovadores, como res\u00edduos de florestas. J\u00e1 na cidade Linkoping, o bairro Vallastaden utiliza novas tecnologias construtivas em madeira e energia positiva nas resid\u00eancias.\u00a0<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Durante a programa\u00e7\u00e3o, a diretora da Associa\u00e7\u00e3o de Madeira da Su\u00e9cia, Anna Ryberg, apresentou a\u00e7\u00f5es voltadas para o processo de descarboniza\u00e7\u00e3o do setor, e orientou como promover informa\u00e7\u00f5es sobre o uso da madeira, produtos de madeira e o uso da madeira da constru\u00e7\u00e3o, a fim de contribuir para uma sociedade sustent\u00e1vel. Durante a apresenta\u00e7\u00e3o, Anna ressaltou que os munic\u00edpios suecos desenvolvem conhecimento por meio de estrat\u00e9gias para a constru\u00e7\u00e3o em madeira.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">O tema tem interface com o projeto \u201cCen\u00e1rios e Transi\u00e7\u00e3o para uma Economia da Ind\u00fastria da Constru\u00e7\u00e3o de Baixo Carbono\u201d, da Comiss\u00e3o de Meio Ambiente (CMA) da CBIC, em parceria com o Servi\u00e7o Nacional de Aprendizagem Industrial (Senai Nacional).<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC) segue em mais uma etapa pela miss\u00e3o empresarial internacional sobre constru\u00e7\u00e3o com madeira. Nesta quinta-feira (25), o presidente da entidade, Jos\u00e9 Carlos Martins e o presidente da Comiss\u00e3o de Meio Ambiente (CMA) da CBIC, estiveram em reuni\u00e3o [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":5229,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[97,175],"tags":[],"class_list":["post-5228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-cbic","category-sustentabilidade-agencia-cbic"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CBIC busca parceria com Finl\u00e2ndia para constru\u00e7\u00e3o com madeira - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/2023\/05\/25\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CBIC busca parceria com Finl\u00e2ndia para constru\u00e7\u00e3o com madeira - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"A C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC) segue em mais uma etapa pela miss\u00e3o empresarial internacional sobre constru\u00e7\u00e3o com madeira. Nesta quinta-feira (25), o presidente da entidade, Jos\u00e9 Carlos Martins e o presidente da Comiss\u00e3o de Meio Ambiente (CMA) da CBIC, estiveram em reuni\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/2023\/05\/25\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-25T22:23:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2023\/08\/whatsapp-image-2023-05-25-at-192207.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"423\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"gustavo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"gustavo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/05\\\/25\\\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/05\\\/25\\\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\\\/\"},\"author\":{\"name\":\"gustavo\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/671df35c7bda5d311f455af67beb3604\"},\"headline\":\"CBIC busca parceria com Finl\u00e2ndia para constru\u00e7\u00e3o com madeira\",\"datePublished\":\"2023-05-25T22:23:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/05\\\/25\\\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\\\/\"},\"wordCount\":445,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/05\\\/25\\\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2023\\\/08\\\/whatsapp-image-2023-05-25-at-192207.jpeg\",\"articleSection\":[\"Ag\u00eancia CBIC\",\"Sustentabilidade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/05\\\/25\\\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/05\\\/25\\\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/05\\\/25\\\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\\\/\",\"name\":\"CBIC busca parceria com Finl\u00e2ndia para constru\u00e7\u00e3o com madeira - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/05\\\/25\\\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/05\\\/25\\\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2023\\\/08\\\/whatsapp-image-2023-05-25-at-192207.jpeg\",\"datePublished\":\"2023-05-25T22:23:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/671df35c7bda5d311f455af67beb3604\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/05\\\/25\\\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/05\\\/25\\\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/05\\\/25\\\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2023\\\/08\\\/whatsapp-image-2023-05-25-at-192207.jpeg\",\"contentUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2023\\\/08\\\/whatsapp-image-2023-05-25-at-192207.jpeg\",\"width\":632,\"height\":423},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/05\\\/25\\\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CBIC busca parceria com Finl\u00e2ndia para constru\u00e7\u00e3o com madeira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/671df35c7bda5d311f455af67beb3604\",\"name\":\"gustavo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b2345306fa0fb5f447d3d289e8c14ba785449d3e2ff64d9a02fb03cc029cf754?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b2345306fa0fb5f447d3d289e8c14ba785449d3e2ff64d9a02fb03cc029cf754?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b2345306fa0fb5f447d3d289e8c14ba785449d3e2ff64d9a02fb03cc029cf754?s=96&d=mm&r=g\",\"caption\":\"gustavo\"},\"sameAs\":[\"https:\\\/\\\/cbic.org.br\"],\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/gustavo-rodrigues\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CBIC busca parceria com Finl\u00e2ndia para constru\u00e7\u00e3o com madeira - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/05\/25\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\/","og_locale":"pt_BR","og_type":"article","og_title":"CBIC busca parceria com Finl\u00e2ndia para constru\u00e7\u00e3o com madeira - Comiss\u00e3o de Meio Ambiente","og_description":"A C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC) segue em mais uma etapa pela miss\u00e3o empresarial internacional sobre constru\u00e7\u00e3o com madeira. Nesta quinta-feira (25), o presidente da entidade, Jos\u00e9 Carlos Martins e o presidente da Comiss\u00e3o de Meio Ambiente (CMA) da CBIC, estiveram em reuni\u00e3o [&hellip;]","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/05\/25\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2023-05-25T22:23:15+00:00","og_image":[{"width":632,"height":423,"url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2023\/08\/whatsapp-image-2023-05-25-at-192207.jpeg","type":"image\/jpeg"}],"author":"gustavo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"gustavo","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/05\/25\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/05\/25\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\/"},"author":{"name":"gustavo","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/671df35c7bda5d311f455af67beb3604"},"headline":"CBIC busca parceria com Finl\u00e2ndia para constru\u00e7\u00e3o com madeira","datePublished":"2023-05-25T22:23:15+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/05\/25\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\/"},"wordCount":445,"commentCount":0,"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/05\/25\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2023\/08\/whatsapp-image-2023-05-25-at-192207.jpeg","articleSection":["Ag\u00eancia CBIC","Sustentabilidade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cbic.org.br\/sustentabilidade\/2023\/05\/25\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/05\/25\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/05\/25\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\/","name":"CBIC busca parceria com Finl\u00e2ndia para constru\u00e7\u00e3o com madeira - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/05\/25\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/05\/25\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2023\/08\/whatsapp-image-2023-05-25-at-192207.jpeg","datePublished":"2023-05-25T22:23:15+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/671df35c7bda5d311f455af67beb3604"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/05\/25\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/2023\/05\/25\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/05\/25\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\/#primaryimage","url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2023\/08\/whatsapp-image-2023-05-25-at-192207.jpeg","contentUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2023\/08\/whatsapp-image-2023-05-25-at-192207.jpeg","width":632,"height":423},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/05\/25\/cbic-busca-parceria-com-finlandia-para-construcao-com-madeira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"CBIC busca parceria com Finl\u00e2ndia para constru\u00e7\u00e3o com madeira"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/671df35c7bda5d311f455af67beb3604","name":"gustavo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b2345306fa0fb5f447d3d289e8c14ba785449d3e2ff64d9a02fb03cc029cf754?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b2345306fa0fb5f447d3d289e8c14ba785449d3e2ff64d9a02fb03cc029cf754?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b2345306fa0fb5f447d3d289e8c14ba785449d3e2ff64d9a02fb03cc029cf754?s=96&d=mm&r=g","caption":"gustavo"},"sameAs":["https:\/\/cbic.org.br"],"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/gustavo-rodrigues\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/5228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=5228"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/5228\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media\/5229"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=5228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=5228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=5228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}