{"id":5220,"date":"2023-07-25T16:28:36","date_gmt":"2023-07-25T19:28:36","guid":{"rendered":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/07\/25\/construcao-com-madeira-as-oportunidades-no-brasil\/"},"modified":"2023-07-25T16:28:36","modified_gmt":"2023-07-25T19:28:36","slug":"construcao-com-madeira-as-oportunidades-no-brasil","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/07\/25\/construcao-com-madeira-as-oportunidades-no-brasil\/","title":{"rendered":"Constru\u00e7\u00e3o com madeira: as oportunidades no Brasil"},"content":{"rendered":"<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Seguindo a tend\u00eancia mundial de busca por processos construtivos mais sustent\u00e1veis, a constru\u00e7\u00e3o com madeira j\u00e1 \u00e9 uma realidade no Brasil. O uso deste insumo no setor tem chamado a aten\u00e7\u00e3o pelo potencial de acelerar a industrializa\u00e7\u00e3o, al\u00e9m de proporcionar canteiros de obras mais limpos e produtivos.\u00a0<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Compreendendo a necessidade de adapta\u00e7\u00e3o \u00e0s novas tecnologias e a urg\u00eancia sustent\u00e1vel no mundo, a C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC) tem colocado o meio ambiente como vetor estrat\u00e9gico da constru\u00e7\u00e3o e tem estimulado uma nova mentalidade de empres\u00e1rios e consumidores, segundo o presidente da Comiss\u00e3o de Meio Ambiente (CMA) da CBIC, Nilson Sarti. Para ele, a constru\u00e7\u00e3o com madeira representa uma evolu\u00e7\u00e3o do conceito de sustentabilidade e industrializa\u00e7\u00e3o.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Uma das metodologias utilizadas para esse tipo de constru\u00e7\u00e3o \u00e9 o sistema de <\/span><i><span style=\"font-weight: 400\">light wood frame<\/span><\/i><span style=\"font-weight: 400\">. O m\u00e9todo industrializado \u00e9 composto por placas estruturais que formam pain\u00e9is que podem ser utilizados em paredes de veda\u00e7\u00e3o (externas e internas), sistemas de cobertura ou at\u00e9 mesmo em paredes estruturais.\u00a0<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Esse sistema, que j\u00e1 conta com norma espec\u00edfica no Brasil, a ABNT NBR 16.936 \u2013 Edifica\u00e7\u00f5es em<\/span><i><span style=\"font-weight: 400\"> light wood frame<\/span><\/i><span style=\"font-weight: 400\">, publicada em 11 de julho de 2023, abre novas oportunidades para a consolida\u00e7\u00e3o da utiliza\u00e7\u00e3o da madeira como parte do processo produtivo no setor da constru\u00e7\u00e3o e amplia\u00e7\u00e3o de neg\u00f3cios e estudos sobre a solu\u00e7\u00e3o.\u00a0<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">&#8220;Foram quase 15 anos de dedica\u00e7\u00e3o para o avan\u00e7o desse tema. A norma traz orienta\u00e7\u00f5es para edif\u00edcios de at\u00e9 dois pavimentos, mas j\u00e1 temos estudos para edifica\u00e7\u00f5es maiores, inclusive com o uso da madeira para base estrutural das constru\u00e7\u00f5es&#8221;, apontou o coordenador da Comiss\u00e3o de Estudo da ABNT, o engenheiro civil Eucl\u00e9sio Manoel Finatt.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Al\u00e9m da t\u00e9cnica com uso de <\/span><i><span style=\"font-weight: 400\">wood frame<\/span><\/i><span style=\"font-weight: 400\">, a madeira engenheirada tamb\u00e9m tem ganhado espa\u00e7o nos debates do setor pelo uso da madeira de florestas plantadas. A tecnologia conta com o processamento industrial da madeira resultando em dois principais tipos: <\/span><i><span style=\"font-weight: 400\">Cross Laminated Timber <\/span><\/i><span style=\"font-weight: 400\">(CLT), voltado para a produ\u00e7\u00e3o de paredes e vigas, e a madeira lamelada colada (MLC), poss\u00edvel para a montagem de pisos e paredes. \u201cO uso da madeira, aplicada em suas diversas t\u00e9cnicas, \u00e9 um projeto que muda a hist\u00f3ria da constru\u00e7\u00e3o civil e muda a imagem do Brasil no mundo, quando o assunto \u00e9 desmatamento&#8221;, apontou o consultor da CBIC em sustentabilidade e gest\u00e3o urbana, Silvio Barros.\u00a0<\/span><\/p>\n<p style=\"text-align: justify\"><b><br \/>\nMiss\u00e3o internacional\u00a0<\/b><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Em maio deste ano, a CBIC integrou comitiva internacional composta por diversos integrantes do ecossistema da constru\u00e7\u00e3o com madeira. O grupo visitou pa\u00edses como Alemanha, \u00c1ustria, Su\u00e9cia e Finl\u00e2ndia, locais considerados de refer\u00eancia neste tipo de processo construtivo.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">A primeira etapa na Alemanha durante visita a feira Ligna, considerada a principal feira mundial voltada para ind\u00fastria madeireira e de processamento de madeira, o foco foi em compreender os equipamentos utilizados para esse tipo de empreendimento. A segunda etapa, na \u00c1ustria, onde come\u00e7ou a participa\u00e7\u00e3o da CBIC, o ponto de estudo foram as m\u00e1quinas operando com esse tipo de material.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Na Su\u00e9cia, o grupo de empres\u00e1rios teve a oportunidade de acompanhar as obras locais, constru\u00eddas com madeira, al\u00e9m de presenciar a fabrica\u00e7\u00e3o em produ\u00e7\u00e3o seriada, com a montagem pr\u00e9via dos c\u00f4modos antes de serem encaminhados ao canteiro de obra.\u00a0<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">&#8220;O Brasil conta com uma vantagem competitiva enorme, com capacidade de produzir madeira pr\u00f3pria para esse tipo de empreendimento em um tempo menor do que outros pa\u00edses&#8221;, apontou o Gerente de Assuntos Estrat\u00e9gicos da Federa\u00e7\u00e3o das Ind\u00fastrias do Estado do Paran\u00e1 (Fiep), Jo\u00e3o Arthur Mohr.\u00a0<\/span><\/p>\n<p style=\"text-align: justify\"><br style=\"font-weight: 400\" \/>O tema tem interface com o projeto &#8220;Cen\u00e1rios e Transi\u00e7\u00e3o para uma Economia da Ind\u00fastria da Constru\u00e7\u00e3o de Baixo Carbono&#8221;, da Comiss\u00e3o de Meio Ambiente (CMA) da CBIC, em parceria com o Servi\u00e7o Nacional de Aprendizagem Industrial (Senai Nacional).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seguindo a tend\u00eancia mundial de busca por processos construtivos mais sustent\u00e1veis, a constru\u00e7\u00e3o com madeira j\u00e1 \u00e9 uma realidade no Brasil. O uso deste insumo no setor tem chamado a aten\u00e7\u00e3o pelo potencial de acelerar a industrializa\u00e7\u00e3o, al\u00e9m de proporcionar canteiros de obras mais limpos [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":5221,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[97,175],"tags":[],"class_list":["post-5220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-cbic","category-sustentabilidade-agencia-cbic"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Constru\u00e7\u00e3o com madeira: as oportunidades no Brasil - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/2023\/07\/25\/construcao-com-madeira-as-oportunidades-no-brasil\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Constru\u00e7\u00e3o com madeira: as oportunidades no Brasil - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"Seguindo a tend\u00eancia mundial de busca por processos construtivos mais sustent\u00e1veis, a constru\u00e7\u00e3o com madeira j\u00e1 \u00e9 uma realidade no Brasil. O uso deste insumo no setor tem chamado a aten\u00e7\u00e3o pelo potencial de acelerar a industrializa\u00e7\u00e3o, al\u00e9m de proporcionar canteiros de obras mais limpos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/2023\/07\/25\/construcao-com-madeira-as-oportunidades-no-brasil\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-25T19:28:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2023\/08\/construcao-com-madeira-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"gustavo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"gustavo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/07\\\/25\\\/construcao-com-madeira-as-oportunidades-no-brasil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/07\\\/25\\\/construcao-com-madeira-as-oportunidades-no-brasil\\\/\"},\"author\":{\"name\":\"gustavo\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/671df35c7bda5d311f455af67beb3604\"},\"headline\":\"Constru\u00e7\u00e3o com madeira: as oportunidades no Brasil\",\"datePublished\":\"2023-07-25T19:28:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/07\\\/25\\\/construcao-com-madeira-as-oportunidades-no-brasil\\\/\"},\"wordCount\":684,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/07\\\/25\\\/construcao-com-madeira-as-oportunidades-no-brasil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2023\\\/08\\\/construcao-com-madeira.png\",\"articleSection\":[\"Ag\u00eancia CBIC\",\"Sustentabilidade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/07\\\/25\\\/construcao-com-madeira-as-oportunidades-no-brasil\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/07\\\/25\\\/construcao-com-madeira-as-oportunidades-no-brasil\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/07\\\/25\\\/construcao-com-madeira-as-oportunidades-no-brasil\\\/\",\"name\":\"Constru\u00e7\u00e3o com madeira: as oportunidades no Brasil - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/07\\\/25\\\/construcao-com-madeira-as-oportunidades-no-brasil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/07\\\/25\\\/construcao-com-madeira-as-oportunidades-no-brasil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2023\\\/08\\\/construcao-com-madeira.png\",\"datePublished\":\"2023-07-25T19:28:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/671df35c7bda5d311f455af67beb3604\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/07\\\/25\\\/construcao-com-madeira-as-oportunidades-no-brasil\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/07\\\/25\\\/construcao-com-madeira-as-oportunidades-no-brasil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/07\\\/25\\\/construcao-com-madeira-as-oportunidades-no-brasil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2023\\\/08\\\/construcao-com-madeira.png\",\"contentUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2023\\\/08\\\/construcao-com-madeira.png\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2023\\\/07\\\/25\\\/construcao-com-madeira-as-oportunidades-no-brasil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Constru\u00e7\u00e3o com madeira: as oportunidades no Brasil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/671df35c7bda5d311f455af67beb3604\",\"name\":\"gustavo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b2345306fa0fb5f447d3d289e8c14ba785449d3e2ff64d9a02fb03cc029cf754?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b2345306fa0fb5f447d3d289e8c14ba785449d3e2ff64d9a02fb03cc029cf754?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b2345306fa0fb5f447d3d289e8c14ba785449d3e2ff64d9a02fb03cc029cf754?s=96&d=mm&r=g\",\"caption\":\"gustavo\"},\"sameAs\":[\"https:\\\/\\\/cbic.org.br\"],\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/gustavo-rodrigues\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Constru\u00e7\u00e3o com madeira: as oportunidades no Brasil - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/07\/25\/construcao-com-madeira-as-oportunidades-no-brasil\/","og_locale":"pt_BR","og_type":"article","og_title":"Constru\u00e7\u00e3o com madeira: as oportunidades no Brasil - Comiss\u00e3o de Meio Ambiente","og_description":"Seguindo a tend\u00eancia mundial de busca por processos construtivos mais sustent\u00e1veis, a constru\u00e7\u00e3o com madeira j\u00e1 \u00e9 uma realidade no Brasil. O uso deste insumo no setor tem chamado a aten\u00e7\u00e3o pelo potencial de acelerar a industrializa\u00e7\u00e3o, al\u00e9m de proporcionar canteiros de obras mais limpos [&hellip;]","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/07\/25\/construcao-com-madeira-as-oportunidades-no-brasil\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2023-07-25T19:28:36+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2023\/08\/construcao-com-madeira-1024x576.png","type":"image\/png"}],"author":"gustavo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"gustavo","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/07\/25\/construcao-com-madeira-as-oportunidades-no-brasil\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/07\/25\/construcao-com-madeira-as-oportunidades-no-brasil\/"},"author":{"name":"gustavo","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/671df35c7bda5d311f455af67beb3604"},"headline":"Constru\u00e7\u00e3o com madeira: as oportunidades no Brasil","datePublished":"2023-07-25T19:28:36+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/07\/25\/construcao-com-madeira-as-oportunidades-no-brasil\/"},"wordCount":684,"commentCount":0,"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/07\/25\/construcao-com-madeira-as-oportunidades-no-brasil\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2023\/08\/construcao-com-madeira.png","articleSection":["Ag\u00eancia CBIC","Sustentabilidade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cbic.org.br\/sustentabilidade\/2023\/07\/25\/construcao-com-madeira-as-oportunidades-no-brasil\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/07\/25\/construcao-com-madeira-as-oportunidades-no-brasil\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/07\/25\/construcao-com-madeira-as-oportunidades-no-brasil\/","name":"Constru\u00e7\u00e3o com madeira: as oportunidades no Brasil - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/07\/25\/construcao-com-madeira-as-oportunidades-no-brasil\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/07\/25\/construcao-com-madeira-as-oportunidades-no-brasil\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2023\/08\/construcao-com-madeira.png","datePublished":"2023-07-25T19:28:36+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/671df35c7bda5d311f455af67beb3604"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/07\/25\/construcao-com-madeira-as-oportunidades-no-brasil\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/2023\/07\/25\/construcao-com-madeira-as-oportunidades-no-brasil\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/07\/25\/construcao-com-madeira-as-oportunidades-no-brasil\/#primaryimage","url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2023\/08\/construcao-com-madeira.png","contentUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2023\/08\/construcao-com-madeira.png","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/2023\/07\/25\/construcao-com-madeira-as-oportunidades-no-brasil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"Constru\u00e7\u00e3o com madeira: as oportunidades no Brasil"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/671df35c7bda5d311f455af67beb3604","name":"gustavo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b2345306fa0fb5f447d3d289e8c14ba785449d3e2ff64d9a02fb03cc029cf754?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b2345306fa0fb5f447d3d289e8c14ba785449d3e2ff64d9a02fb03cc029cf754?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b2345306fa0fb5f447d3d289e8c14ba785449d3e2ff64d9a02fb03cc029cf754?s=96&d=mm&r=g","caption":"gustavo"},"sameAs":["https:\/\/cbic.org.br"],"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/gustavo-rodrigues\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/5220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=5220"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/5220\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media\/5221"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=5220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=5220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=5220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}