{"id":4971,"date":"2021-10-13T17:27:56","date_gmt":"2021-10-13T20:27:56","guid":{"rendered":"https:\/\/cbic.org.br\/sustentabilidade\/2021\/10\/13\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\/"},"modified":"2021-10-13T17:27:56","modified_gmt":"2021-10-13T20:27:56","slug":"enic-a-importancia-das-cidades-inteligentes-para-a-sociedade","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2021\/10\/13\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\/","title":{"rendered":"Enic: a import\u00e2ncia das cidades inteligentes para a sociedade"},"content":{"rendered":"<p style=\"text-align: justify\">Como a tecnologia pode melhorar a qualidade de vida das pessoas e interconectar a infraestrutura das cidades? Como os munic\u00edpios brasileiros podem incluir projetos de desenvolvimento urbano cooperativo, integrado e sustent\u00e1vel? Essas s\u00e3o algumas das indaga\u00e7\u00f5es que surgem quando o assunto \u00e9 cidade inteligente.<\/p>\n<p style=\"text-align: justify\">As cidades inteligentes ou <i>smart cities<\/i> s\u00e3o aquelas que fazem o uso otimizado dos recursos e tecnologias integradas, a servi\u00e7o das pessoas, melhorando assim o dia a dia dos cidad\u00e3os. Neste aspecto, incluem projetos como de mobilidade urbana, ilumina\u00e7\u00e3o p\u00fablica, transforma\u00e7\u00e3o digital nas escolas, entre outros exemplos.<\/p>\n<p style=\"text-align: justify\">\u201cO conceito de cidades inteligentes \u00e9 bem amplo, mas em suma seriam as cidades na nova gera\u00e7\u00e3o. O tema atualmente \u00e9 bastante estudado em rela\u00e7\u00e3o ao desenvolvimento urbano. Neste conceito de urbaniza\u00e7\u00e3o, as cidades inteligentes usam o cruzamento de informa\u00e7\u00f5es, controlando opera\u00e7\u00f5es e recursos, de modo estrat\u00e9gico, para melhorar a vida dos moradores e contribuir para o desenvolvimento do pa\u00eds\u201d, explica Jos\u00e9 Eug\u00eanio Gizzi, vice-presidente regional da CBIC.<\/p>\n<p style=\"text-align: justify\">Segundo dados do relat\u00f3rio da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas (ONU) de 2020, cerca de 4 bilh\u00f5es de pessoas vivem em \u00e1reas urbanas, e at\u00e9 2050 h\u00e1 uma expectativa para que se chegue a 7 bilh\u00f5es de pessoas. Por\u00e9m, o processo de urbaniza\u00e7\u00e3o traz consequ\u00eancias e desafios que precisam ser observados com cuidado e estrat\u00e9gias pelos governantes e empres\u00e1rios.<\/p>\n<p style=\"text-align: justify\">\u201cA acelera\u00e7\u00e3o urbana traz consigo degrada\u00e7\u00e3o ambiental, congestionamento, defici\u00eancia no acesso a bens educacionais, falta de saneamento e as cidades inteligentes v\u00eam como uma solu\u00e7\u00e3o vi\u00e1vel, para mitigar tais consequ\u00eancias por meio das tecnologias. As tecnologias integradas t\u00eam o objetivo de integrar servi\u00e7os e solu\u00e7\u00f5es com efici\u00eancia e menos custo, movimentando assim o munic\u00edpio para um novo patamar\u201d, comenta Gizzi.<\/p>\n<p style=\"text-align: justify\">Um estudo conduzido pelo BNDES, em 2018, sobre o Plano Nacional de IoT (internet das coisas), mostrou que at\u00e9 2025 as cidades inteligentes poderiam adicionar \u00e0 economia brasileira entre US$ 900 mil e US$ 1,7 bi, considerando somente a IoT.<\/p>\n<p style=\"text-align: justify\">O relat\u00f3rio <i>Smart City Strategy Index<\/i> 2019 demonstra que 41% das cidades inteligentes est\u00e3o situadas na Europa, 27% na \u00c1sia, 24% na Am\u00e9rica do Norte e apenas 8% nos demais continentes.<\/p>\n<p style=\"text-align: justify\">\u201cOs modelos de cidades inteligentes trabalham iniciativas transversais entre o tecnol\u00f3gico e o social, pois as solu\u00e7\u00f5es precisam ser inclusivas, sustent\u00e1veis e orientadas tanto para o desenvolvimento das pessoas quanto para o pa\u00eds. N\u00f3s temos v\u00e1rios exemplos que podem ser aprimorados como plataformas que ampliam a efici\u00eancia da sa\u00fade p\u00fablica, inclus\u00e3o digital nas escolas, efici\u00eancia energ\u00e9tica, semaforiza\u00e7\u00e3o e ilumina\u00e7\u00e3o p\u00fablica. Mas \u00e9 preciso unir v\u00e1rios setores, discutir, debater para ver essas mudan\u00e7as consolidadas, como a ind\u00fastria de constru\u00e7\u00e3o, gestores p\u00fablicos, setor educacional, etc\u201d, explica Jos\u00e9 Eug\u00eanio Gizzi<\/p>\n<p style=\"text-align: justify\"><b>Painel Enic &#8211; <\/b>No dia 18 de outubro, \u00e0s 18h, o 93\u00ba Encontro Nacional da Ind\u00fastria da Constru\u00e7\u00e3o (ENIC), vai apresentar o painel \u2018Cidades Inteligentes e a Revolu\u00e7\u00e3o dos Ambientes Urbanos\u2019, com Jos\u00e9 Eug\u00eanio Souza de Bueno Gizzi, Igor Calvet, Felipe Andrade Lucci. Dentro do debate, os convidados v\u00e3o abordar as evolu\u00e7\u00f5es do setor e como ampliar o conceito no pa\u00eds.<\/p>\n<p style=\"text-align: justify\">Nesta edi\u00e7\u00e3o, o Enic ser\u00e1 na palma da sua m\u00e3o. \u00c9 o maior evento da ind\u00fastria da constru\u00e7\u00e3o na tela do seu celular \u2013 online e gratuito! <a href=\"http:\/\/cbic.org.br\/enic\">Para se inscrever basta se cadastrar no link<\/a>!<\/p>\n<p style=\"text-align: justify\">O 93\u00ba Enic \u00e9 uma realiza\u00e7\u00e3o da C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC) e conta com apoio do Servi\u00e7o Social da Ind\u00fastria (Sesi Nacional), do Servi\u00e7o Nacional de Aprendizagem Industrial (Senai Nacional) e de entidades do setor, com patroc\u00ednio do Sebrae, Or\u00e7aFascio, Konstroi, Agilean, Brain Intelig\u00eancia Estrat\u00e9gica, M\u00fatua e Predialize.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como a tecnologia pode melhorar a qualidade de vida das pessoas e interconectar a infraestrutura das cidades? Como os munic\u00edpios brasileiros podem incluir projetos de desenvolvimento urbano cooperativo, integrado e sustent\u00e1vel? Essas s\u00e3o algumas das indaga\u00e7\u00f5es que surgem quando o assunto \u00e9 cidade inteligente. As [&hellip;]<\/p>\n","protected":false},"author":1414,"featured_media":1000003,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[97,228,175],"tags":[],"class_list":["post-4971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-cbic","category-industria-imobiliaria-agencia-cbic","category-sustentabilidade-agencia-cbic"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Enic: a import\u00e2ncia das cidades inteligentes para a sociedade - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/13\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enic: a import\u00e2ncia das cidades inteligentes para a sociedade - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"Como a tecnologia pode melhorar a qualidade de vida das pessoas e interconectar a infraestrutura das cidades? Como os munic\u00edpios brasileiros podem incluir projetos de desenvolvimento urbano cooperativo, integrado e sustent\u00e1vel? Essas s\u00e3o algumas das indaga\u00e7\u00f5es que surgem quando o assunto \u00e9 cidade inteligente. As [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/13\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-13T20:27:56+00:00\" \/>\n<meta name=\"author\" content=\"jornalistacbic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jornalistacbic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/10\\\/13\\\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/10\\\/13\\\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\\\/\"},\"author\":{\"name\":\"jornalistacbic\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/654b120bcd86d07c9f9dc286ecc91681\"},\"headline\":\"Enic: a import\u00e2ncia das cidades inteligentes para a sociedade\",\"datePublished\":\"2021-10-13T20:27:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/10\\\/13\\\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\\\/\"},\"wordCount\":655,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/10\\\/13\\\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Ag\u00eancia CBIC\",\"Ind\u00fastria Imobili\u00e1ria\",\"Sustentabilidade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/10\\\/13\\\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/10\\\/13\\\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\\\/\",\"name\":\"Enic: a import\u00e2ncia das cidades inteligentes para a sociedade - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/10\\\/13\\\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/10\\\/13\\\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2021-10-13T20:27:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/654b120bcd86d07c9f9dc286ecc91681\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/10\\\/13\\\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/10\\\/13\\\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/10\\\/13\\\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/10\\\/13\\\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enic: a import\u00e2ncia das cidades inteligentes para a sociedade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/654b120bcd86d07c9f9dc286ecc91681\",\"name\":\"jornalistacbic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa24f0ed442729cb89355c4b9cd7ab747f7f3fa236417c2717409c63e87c39e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa24f0ed442729cb89355c4b9cd7ab747f7f3fa236417c2717409c63e87c39e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa24f0ed442729cb89355c4b9cd7ab747f7f3fa236417c2717409c63e87c39e?s=96&d=mm&r=g\",\"caption\":\"jornalistacbic\"},\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/jornalistacbic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enic: a import\u00e2ncia das cidades inteligentes para a sociedade - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/13\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\/","og_locale":"pt_BR","og_type":"article","og_title":"Enic: a import\u00e2ncia das cidades inteligentes para a sociedade - Comiss\u00e3o de Meio Ambiente","og_description":"Como a tecnologia pode melhorar a qualidade de vida das pessoas e interconectar a infraestrutura das cidades? Como os munic\u00edpios brasileiros podem incluir projetos de desenvolvimento urbano cooperativo, integrado e sustent\u00e1vel? Essas s\u00e3o algumas das indaga\u00e7\u00f5es que surgem quando o assunto \u00e9 cidade inteligente. As [&hellip;]","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/13\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2021-10-13T20:27:56+00:00","author":"jornalistacbic","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jornalistacbic","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/13\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/13\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\/"},"author":{"name":"jornalistacbic","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/654b120bcd86d07c9f9dc286ecc91681"},"headline":"Enic: a import\u00e2ncia das cidades inteligentes para a sociedade","datePublished":"2021-10-13T20:27:56+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/13\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\/"},"wordCount":655,"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/13\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\/#primaryimage"},"thumbnailUrl":"","articleSection":["Ag\u00eancia CBIC","Ind\u00fastria Imobili\u00e1ria","Sustentabilidade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/13\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/13\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\/","name":"Enic: a import\u00e2ncia das cidades inteligentes para a sociedade - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/13\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/13\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\/#primaryimage"},"thumbnailUrl":"","datePublished":"2021-10-13T20:27:56+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/654b120bcd86d07c9f9dc286ecc91681"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/13\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/13\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/13\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/13\/enic-a-importancia-das-cidades-inteligentes-para-a-sociedade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"Enic: a import\u00e2ncia das cidades inteligentes para a sociedade"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/654b120bcd86d07c9f9dc286ecc91681","name":"jornalistacbic","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/5aa24f0ed442729cb89355c4b9cd7ab747f7f3fa236417c2717409c63e87c39e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5aa24f0ed442729cb89355c4b9cd7ab747f7f3fa236417c2717409c63e87c39e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5aa24f0ed442729cb89355c4b9cd7ab747f7f3fa236417c2717409c63e87c39e?s=96&d=mm&r=g","caption":"jornalistacbic"},"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/jornalistacbic\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/4971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/1414"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=4971"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/4971\/revisions"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=4971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=4971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=4971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}