{"id":4969,"date":"2021-10-06T15:59:58","date_gmt":"2021-10-06T18:59:58","guid":{"rendered":"https:\/\/cbic.org.br\/sustentabilidade\/2021\/10\/06\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\/"},"modified":"2021-10-06T15:59:58","modified_gmt":"2021-10-06T18:59:58","slug":"projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2021\/10\/06\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\/","title":{"rendered":"Projeto municipaliza regras de prote\u00e7\u00e3o de margens de rios em \u00e1reas urbanas"},"content":{"rendered":"<p class=\"xmsonormal\" style=\"text-align: justify\">A C\u00e2mara dos Deputados concluiu em agosto a vota\u00e7\u00e3o do Projeto de Lei que transfere para a legisla\u00e7\u00e3o municipal as regras de prote\u00e7\u00e3o de margens de rios em \u00e1reas urbanas, com a rejei\u00e7\u00e3o de todos os destaques.\u00a0O texto aprovado \u00e9 o substitutivo do deputado Darci de Matos (PSD\/SC) ao PL 2510\/19, do deputado Rog\u00e9rio Peninha Mendon\u00e7a (MDB\/SC), que tem como apensado o PL 1877\/21, do deputado Marcelo Ramos.<\/p>\n<p class=\"xmsonormal\" style=\"text-align: justify\">A proposta permite que os munic\u00edpios estabele\u00e7am faixas de prote\u00e7\u00e3o diferentes em \u00e1reas consolidadas urbanas, que j\u00e1 contam com edifica\u00e7\u00f5es, sistema vi\u00e1rio, loteamento e equipamentos de infraestrutura urbana. N\u00e3o poder\u00e3o ser ocupadas \u00e1reas de risco de desastres.<\/p>\n<p class=\"xmsonormal\" style=\"text-align: justify\">Para elaborar a legisla\u00e7\u00e3o municipal, ser\u00e1 necess\u00e1rio ouvir os conselhos estaduais, municipais ou distrital de meio ambiente. As normas dever\u00e3o ainda observar as diretrizes do plano de recursos h\u00eddricos, do plano de bacia, do plano de drenagem ou do plano de saneamento b\u00e1sico, se houver.<\/p>\n<p class=\"xmsonormal\" style=\"text-align: justify\">O projeto tamb\u00e9m permite a continuidade de ocupa\u00e7\u00e3o, nas faixas marginais definidas em lei municipal ou distrital, de im\u00f3veis j\u00e1 existentes at\u00e9 28 de abril de 2021, data da decis\u00e3o do STJ acerca do Tema 1010. Para isso, os propriet\u00e1rios devem arcar com uma compensa\u00e7\u00e3o ambiental determinada pelo \u00f3rg\u00e3o municipal competente, salvo por ato devidamente fundamentado do poder p\u00fablico municipal ou distrital.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8230;<\/p>\n","protected":false},"author":10,"featured_media":1000001,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[97,175],"tags":[],"class_list":["post-4969","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-cbic","category-sustentabilidade-agencia-cbic"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Projeto municipaliza regras de prote\u00e7\u00e3o de margens de rios em \u00e1reas urbanas - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/06\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projeto municipaliza regras de prote\u00e7\u00e3o de margens de rios em \u00e1reas urbanas - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/06\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-06T18:59:58+00:00\" \/>\n<meta name=\"author\" content=\"Sandra Bezerra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sandra Bezerra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/10\\\/06\\\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/10\\\/06\\\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\\\/\"},\"author\":{\"name\":\"Sandra Bezerra\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\"},\"headline\":\"Projeto municipaliza regras de prote\u00e7\u00e3o de margens de rios em \u00e1reas urbanas\",\"datePublished\":\"2021-10-06T18:59:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/10\\\/06\\\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\\\/\"},\"wordCount\":249,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/10\\\/06\\\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Ag\u00eancia CBIC\",\"Sustentabilidade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/10\\\/06\\\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/10\\\/06\\\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\\\/\",\"name\":\"Projeto municipaliza regras de prote\u00e7\u00e3o de margens de rios em \u00e1reas urbanas - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/10\\\/06\\\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/10\\\/06\\\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2021-10-06T18:59:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/10\\\/06\\\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/10\\\/06\\\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/10\\\/06\\\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/10\\\/06\\\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projeto municipaliza regras de prote\u00e7\u00e3o de margens de rios em \u00e1reas urbanas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\",\"name\":\"Sandra Bezerra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"caption\":\"Sandra Bezerra\"},\"sameAs\":[\"https:\\\/\\\/cbic.org.br\"],\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/sandra-bezerra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Projeto municipaliza regras de prote\u00e7\u00e3o de margens de rios em \u00e1reas urbanas - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/06\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\/","og_locale":"pt_BR","og_type":"article","og_title":"Projeto municipaliza regras de prote\u00e7\u00e3o de margens de rios em \u00e1reas urbanas - Comiss\u00e3o de Meio Ambiente","og_description":"...","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/06\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2021-10-06T18:59:58+00:00","author":"Sandra Bezerra","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sandra Bezerra","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/06\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/06\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\/"},"author":{"name":"Sandra Bezerra","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e"},"headline":"Projeto municipaliza regras de prote\u00e7\u00e3o de margens de rios em \u00e1reas urbanas","datePublished":"2021-10-06T18:59:58+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/06\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\/"},"wordCount":249,"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/06\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\/#primaryimage"},"thumbnailUrl":"","articleSection":["Ag\u00eancia CBIC","Sustentabilidade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/06\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/06\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\/","name":"Projeto municipaliza regras de prote\u00e7\u00e3o de margens de rios em \u00e1reas urbanas - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/06\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/06\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\/#primaryimage"},"thumbnailUrl":"","datePublished":"2021-10-06T18:59:58+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/06\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/06\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/06\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/10\/06\/projeto-municipaliza-regras-de-protecao-de-margens-de-rios-em-areas-urbanas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"Projeto municipaliza regras de prote\u00e7\u00e3o de margens de rios em \u00e1reas urbanas"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e","name":"Sandra Bezerra","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","caption":"Sandra Bezerra"},"sameAs":["https:\/\/cbic.org.br"],"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/sandra-bezerra\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/4969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=4969"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/4969\/revisions"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=4969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=4969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=4969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}