{"id":4954,"date":"2021-08-19T17:11:53","date_gmt":"2021-08-19T20:11:53","guid":{"rendered":"https:\/\/cbic.org.br\/sustentabilidade\/2021\/08\/19\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\/"},"modified":"2021-08-19T17:18:23","modified_gmt":"2021-08-19T20:18:23","slug":"marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2021\/08\/19\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\/","title":{"rendered":"Marco Legal da Gera\u00e7\u00e3o Distribu\u00edda \u00e9 aprovado na C\u00e2mara dos Deputados"},"content":{"rendered":"<p>O Plen\u00e1rio da C\u00e2mara dos Deputados aprovou no dia 18\/8, por 476 votos favor\u00e1veis e tr\u00eas contr\u00e1rios, o <strong>Marco Legal da Gera\u00e7\u00e3o Distribu\u00edda<\/strong>. O substitutivo do relator, deputado Lafayette de Andrada (Republicanos\/MG), teve como base o acordo realizado entre o Minist\u00e9rio de Minas e Energia, a Aneel e a associa\u00e7\u00f5es dos segmentos de microgera\u00e7\u00e3o e minigera\u00e7\u00e3o distribu\u00edda, bem como das distribuidoras de energia el\u00e9trica, que resultou em um texto de consenso.<\/p>\n<p>O projeto regulamenta o Sistema de Compensa\u00e7\u00e3o de Energia para os consumidores que optaram por produzir a pr\u00f3pria energia em suas unidades consumidoras, chamado de Gera\u00e7\u00e3o Distribu\u00edda, al\u00e9m de criar regras para os consumidores e as distribuidoras em rela\u00e7\u00e3o \u00e0 conex\u00e3o e a remunera\u00e7\u00e3o \u00e0s concession\u00e1rias pelos usos dos sistemas.<\/p>\n<p>Dentre os principais pontos, destacam-se:<\/p>\n<ul>\n<li>A distribuidora de energia el\u00e9trica dever\u00e1 promover chamadas p\u00fablicas para credenciamento de interessados em comercializar os excedentes de gera\u00e7\u00e3o de energia oriundos da gera\u00e7\u00e3o distribu\u00edda;<\/li>\n<li>A unidade consumidora com microgera\u00e7\u00e3o ou minigera\u00e7\u00e3o distribu\u00edda ligada em tens\u00e3o prim\u00e1ria pode optar por faturamento com aplica\u00e7\u00e3o da tarifa do grupo B, independentemente de haver carga associada;<\/li>\n<li>O excedente de energia el\u00e9trica de um posto tarif\u00e1rio deve ser inicialmente alocado para outros postos tarif\u00e1rios da mesma unidade consumidora que gerou a energia;<\/li>\n<li>Os cr\u00e9ditos de energia el\u00e9trica expiram em 60 meses ap\u00f3s a data do faturamento em que foram gerados e ser\u00e3o revertidos em prol da modicidade tarif\u00e1ria;<\/li>\n<li>N\u00e3o poder\u00e3o aderir ao sistema de compensa\u00e7\u00e3o de energia, os consumidores do mercado livre que tenham exercido a op\u00e7\u00e3o de compra de energia el\u00e9trica;<\/li>\n<li>At\u00e9 31\/12\/2045, a Conta de Desenvolvimento Energ\u00e9tico (CDE) custear\u00e1 as componentes tarif\u00e1rias n\u00e3o associadas ao custo da energia para as instala\u00e7\u00f5es existentes ou que tenham protocolado pedidos at\u00e9 12 meses da publica\u00e7\u00e3o da Lei;<\/li>\n<li>Ap\u00f3s o per\u00edodo, o faturamento de todas as componentes tarif\u00e1rias n\u00e3o associadas ao custo da energia incidir\u00e3o na tarifa dos consumidores;<\/li>\n<li>As bandeiras tarif\u00e1rias incidir\u00e3o somente sobre a diferen\u00e7a positiva entre o montante consumido e a soma da energia el\u00e9trica injetada, desconsiderando os demais custos.<\/li>\n<\/ul>\n<p>A mat\u00e9ria segue para delibera\u00e7\u00e3o do Senado Federal.<\/p>\n<p><span style=\"font-size: 10pt\"><em>(Com informa\u00e7\u00f5es da Foco Assessoria e Consultoria Ltda)<\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8230;<\/p>\n","protected":false},"author":10,"featured_media":1000001,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[97,175],"tags":[],"class_list":["post-4954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-cbic","category-sustentabilidade-agencia-cbic"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marco Legal da Gera\u00e7\u00e3o Distribu\u00edda \u00e9 aprovado na C\u00e2mara dos Deputados - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/19\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marco Legal da Gera\u00e7\u00e3o Distribu\u00edda \u00e9 aprovado na C\u00e2mara dos Deputados - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/19\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-19T20:11:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-19T20:18:23+00:00\" \/>\n<meta name=\"author\" content=\"Sandra Bezerra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sandra Bezerra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/08\\\/19\\\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/08\\\/19\\\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\\\/\"},\"author\":{\"name\":\"Sandra Bezerra\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\"},\"headline\":\"Marco Legal da Gera\u00e7\u00e3o Distribu\u00edda \u00e9 aprovado na C\u00e2mara dos Deputados\",\"datePublished\":\"2021-08-19T20:11:53+00:00\",\"dateModified\":\"2021-08-19T20:18:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/08\\\/19\\\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\\\/\"},\"wordCount\":420,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/08\\\/19\\\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Ag\u00eancia CBIC\",\"Sustentabilidade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/08\\\/19\\\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/08\\\/19\\\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\\\/\",\"name\":\"Marco Legal da Gera\u00e7\u00e3o Distribu\u00edda \u00e9 aprovado na C\u00e2mara dos Deputados - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/08\\\/19\\\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/08\\\/19\\\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2021-08-19T20:11:53+00:00\",\"dateModified\":\"2021-08-19T20:18:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/08\\\/19\\\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/08\\\/19\\\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/08\\\/19\\\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/08\\\/19\\\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marco Legal da Gera\u00e7\u00e3o Distribu\u00edda \u00e9 aprovado na C\u00e2mara dos Deputados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\",\"name\":\"Sandra Bezerra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"caption\":\"Sandra Bezerra\"},\"sameAs\":[\"https:\\\/\\\/cbic.org.br\"],\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/sandra-bezerra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marco Legal da Gera\u00e7\u00e3o Distribu\u00edda \u00e9 aprovado na C\u00e2mara dos Deputados - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/19\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\/","og_locale":"pt_BR","og_type":"article","og_title":"Marco Legal da Gera\u00e7\u00e3o Distribu\u00edda \u00e9 aprovado na C\u00e2mara dos Deputados - Comiss\u00e3o de Meio Ambiente","og_description":"...","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/19\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2021-08-19T20:11:53+00:00","article_modified_time":"2021-08-19T20:18:23+00:00","author":"Sandra Bezerra","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sandra Bezerra","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/19\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/19\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\/"},"author":{"name":"Sandra Bezerra","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e"},"headline":"Marco Legal da Gera\u00e7\u00e3o Distribu\u00edda \u00e9 aprovado na C\u00e2mara dos Deputados","datePublished":"2021-08-19T20:11:53+00:00","dateModified":"2021-08-19T20:18:23+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/19\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\/"},"wordCount":420,"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/19\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\/#primaryimage"},"thumbnailUrl":"","articleSection":["Ag\u00eancia CBIC","Sustentabilidade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/19\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/19\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\/","name":"Marco Legal da Gera\u00e7\u00e3o Distribu\u00edda \u00e9 aprovado na C\u00e2mara dos Deputados - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/19\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/19\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\/#primaryimage"},"thumbnailUrl":"","datePublished":"2021-08-19T20:11:53+00:00","dateModified":"2021-08-19T20:18:23+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/19\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/19\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/19\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/19\/marco-legal-da-geracao-distribuida-e-aprovado-na-camara-dos-deputados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"Marco Legal da Gera\u00e7\u00e3o Distribu\u00edda \u00e9 aprovado na C\u00e2mara dos Deputados"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e","name":"Sandra Bezerra","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","caption":"Sandra Bezerra"},"sameAs":["https:\/\/cbic.org.br"],"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/sandra-bezerra\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/4954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=4954"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/4954\/revisions"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=4954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=4954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=4954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}