{"id":4949,"date":"2021-08-04T11:40:04","date_gmt":"2021-08-04T14:40:04","guid":{"rendered":"https:\/\/cbic.org.br\/sustentabilidade\/2021\/08\/04\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\/"},"modified":"2021-08-04T11:40:04","modified_gmt":"2021-08-04T14:40:04","slug":"conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2021\/08\/04\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\/","title":{"rendered":"Conhe\u00e7a formas de contribuir no combate do aquecimento global na constru\u00e7\u00e3o"},"content":{"rendered":"<p style=\"text-align: justify\">A Comiss\u00e3o de Meio Ambiente da C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CMA\/CBIC) realizou nesta ter\u00e7a-feira (3) uma reuni\u00e3o com um time de especialistas para debater formas de o setor da constru\u00e7\u00e3o ajudar a combater o aquecimento global.<\/p>\n<p>O presidente da CMA, Nilson Sarti, mediou o evento e ressaltou a import\u00e2ncia do tema para o setor \u201cTemos que ver isso como oportunidade. Se nos preparamos, ser\u00e1 uma grande oportunidade para o setor de evoluir e sair na frente. Quem n\u00e3o se preparar, poder\u00e1 estar fora do mercado\u201d.<\/p>\n<p>O encontro contou com a participa\u00e7\u00e3o diretora do Projeto Strategic Partnerships for the Implementation of the Paris Agreement (SPIPA) no Brasil, H\u00e9linah Cardoso, do Professor Doutor da URFJ, Lucas Rosse Caldas, do professor da Poli-USP, diretor do CBCS, e coordenador t\u00e9cnico do Projeto SIDAC, Vanderley John, do assessor t\u00e9cnico da GIZ, Daniel Wagner e da coordenadora t\u00e9cnica do Comit\u00ea de Meio Ambiente (Comasp) do SindusCon-SP, Lilian Sarrouf.<\/p>\n<p>Todos os participantes fizeram apresenta\u00e7\u00f5es sobre o tema. A primeira foi feita pela H\u00e9linah Cardoso com o tema \u201cCoopera\u00e7\u00e3o para o Desenvolvimento Sustent\u00e1vel\u201d sobre o Acordo de Coopera\u00e7\u00e3o T\u00e9cnica entre o Minist\u00e9rio de Minas e Energia e a Ag\u00eancia Alem\u00e3 para Coopera\u00e7\u00e3o Internacional (GIZ).<\/p>\n<p>Dentre os motivos de cooperar, ela citou que o Brasil \u00e9 o 5\u00ba maior emissor de CO2 e tem a maior biodiversidade do mundo. Al\u00e9m disso, apresentou as \u00e1reas de atua\u00e7\u00e3o da coopera\u00e7\u00e3o. S\u00e3o elas:<\/p>\n<p>&#8211; Energias renov\u00e1veis e efici\u00eancia energ\u00e9tica;<br \/>\n&#8211; Prote\u00e7\u00e3o e uso sustent\u00e1vel das florestas tropicais;<br \/>\n&#8211; Programas e iniciativas multissetoriais;<br \/>\n&#8211; Transforma\u00e7\u00e3o urbana;<br \/>\n&#8211; Forma\u00e7\u00e3o profissional;<br \/>\n&#8211; Prote\u00e7\u00e3o da biodiversidade;<br \/>\n&#8211; G\u00eanero e direitos humanos;<br \/>\n&#8211; Clima.<\/p>\n<p>H\u00e9linah tamb\u00e9m apontou os eixos de trabalho da GIZ no setor de energia e os projetos de iniciativas multissetoriais.<\/p>\n<p>J\u00e1 o Professor Doutor Lucas Rosse Caldas realizou apresenta\u00e7\u00e3o sobre \u201cO papel da ind\u00fastria da constru\u00e7\u00e3o na redu\u00e7\u00e3o das emiss\u00f5es de carbono\u201d.<\/p>\n<p>Segundo ele, reduzir as emiss\u00f5es de carbono resulta em: competitividade empresarial; facilidade de acesso a cr\u00e9ditos de financiamento; possibilita um melhor entendimento de todo o processo produtivo &#8211; melhoria cont\u00ednua e redu\u00e7\u00e3o dos custos de produ\u00e7\u00e3o; aumento da efici\u00eancia energ\u00e9tica.<\/p>\n<p>Al\u00e9m disso, Lucas afirma que a busca por fontes de energia renov\u00e1veis leva a uma maior seguran\u00e7a energ\u00e9tica, melhora a imagem da empresa, estimula a inova\u00e7\u00e3o tecnol\u00f3gica e promove o alinhamento com institui\u00e7\u00f5es e iniciativas p\u00fablicas e do setor privado.<\/p>\n<p>Para dar os primeiros passos, Lucas explica que \u00e9 necess\u00e1rio ter o entendimento de todo o sistema e ter o engajamento de todo o setor. Segundo ele, tamb\u00e9m \u00e9 preciso ter metodologias e ferramentas para medir as emiss\u00f5es de carbono. Um exemplo \u00e9 a Avalia\u00e7\u00e3o do Ciclo de Vida (ACV).<\/p>\n<p>De acordo com ele, as ferramentas devem ser evolutivas, confi\u00e1veis, simples de serem utilizadas e acess\u00edveis aos diferentes atores do setor. Al\u00e9m disso, devem ser compat\u00edveis com outras j\u00e1 existentes no setor, que possibilitem o c\u00e1lculo de benchmarks e uma melhoria cont\u00ednua.<\/p>\n<p>\u201cQuanto mais tempo demorarmos a entender a import\u00e2ncia da redu\u00e7\u00e3o das emiss\u00f5es de carbono, mais oportunidades ser\u00e3o perdidas. O carbono j\u00e1 \u00e9 uma moeda de negocia\u00e7\u00e3o e tende a ficar cada vez mais importante\u201d, concluiu Lucas.<\/p>\n<p style=\"text-align: justify\">O professor da Poli-USP, diretor do CBCS, e coordenador t\u00e9cnico do Projeto SIDAC, Vanderley John, fez uma apresenta\u00e7\u00e3o sobre o Sistema de Informa\u00e7\u00e3o do Desempenho Ambiental da Constru\u00e7\u00e3o (SIDAC).<\/p>\n<p>O SIDAC \u00e9 uma ferramenta de gest\u00e3o do desempenho ambiental da constru\u00e7\u00e3o. Segundo Vanderley, \u00e9 pr\u00e1tica, focada em temas ambientais relevantes, facilmente integr\u00e1vel ao ESG e acess\u00edvel a empresas pequenas ou grandes.<\/p>\n<p>Hoje, o SIDAC mede, em sua vers\u00e3o 1.0, o consumo de energia e emiss\u00e3o de CO2. No futuro, vai medir \u00e1gua, res\u00edduos e uso de recursos naturais.<\/p>\n<p>Na vers\u00e3o 1.0, a cesta de materiais engloba: cimento, cal, agregados, concreto, argamassa, bloco de concreto, bloco cer\u00e2mico, telha cer\u00e2mica, vergalh\u00e3o de a\u00e7o e madeira serrada. De acordo com Vanderley, estes itens representam 95% da massa das edifica\u00e7\u00f5es.<\/p>\n<p>Na ocasi\u00e3o, tamb\u00e9m foi apresentada uma ferramenta de c\u00e1lculo de emiss\u00e3o de gases de efeito estufa e consumo energ\u00e9tico, a CECarbon, pelo assessor t\u00e9cnico da GIZ, Daniel Wagner, e pela coordenadora t\u00e9cnica do Comit\u00ea de Meio Ambiente (Comasp) do SindusCon-SP, Lilian Sarrouf.<\/p>\n<p>A CECarbon, lan\u00e7ada em dezembro de 2020, permite calcular as emiss\u00f5es de gases de efeito estufa (GEE) e o consumo energ\u00e9tico relacionados \u00e0 constru\u00e7\u00e3o de uma edifica\u00e7\u00e3o, levando em considera\u00e7\u00e3o o ciclo de vida dos insumos da obra, desde a sua explora\u00e7\u00e3o at\u00e9 o momento do seu uso na fase construtiva. A ferramenta visa contribuir com a gest\u00e3o clim\u00e1tica e energ\u00e9tica da ind\u00fastria da constru\u00e7\u00e3o civil, a partir da padroniza\u00e7\u00e3o de m\u00e9tricas e premissas e da consolida\u00e7\u00e3o consistente de dados entre empresas e outros atores do segmento.<\/p>\n<p>A partir de 2022, Lilian afirmou que os objetivos s\u00e3o potencializar o uso da ferramenta em n\u00edvel nacional e formar base de dados para o setor de edifica\u00e7\u00f5es no Brasil. Al\u00e9m disso, \u00e9 esperado que haja possibilidade de comparabilidade entre obras da mesma tipologia e integra\u00e7\u00e3o com os procedimentos do setor p\u00fablico e privado.<\/p>\n<p>Daniel Wagner refor\u00e7ou que a ferramenta \u00e9 online, din\u00e2mica, confi\u00e1vel e gratuita. Segundo ele, a iniciativa alcan\u00e7a seis dos Objetivos de Desenvolvimento Sustent\u00e1vel da ONU: energia limpa e acess\u00edvel; ind\u00fastria, inova\u00e7\u00e3o e infraestrutura; cidades e comunidades sustent\u00e1veis; consumo e produ\u00e7\u00e3o respons\u00e1veis; a\u00e7\u00e3o contra a mudan\u00e7a global do clima e parcerias e meios de implementa\u00e7\u00e3o.<\/p>\n<p>Wagner tamb\u00e9m destacou que, por ser alinhada com pol\u00edticas p\u00fablicas, atende \u00e0 Portaria do Minist\u00e9rio do Desenvolvimento Regional 959 de 18\/05\/21, do Programa Casa Verde e Amarela, onde h\u00e1 um requisito de execu\u00e7\u00e3o de obra: utiliza\u00e7\u00e3o de ferramenta para c\u00e1lculo da emiss\u00e3o de carbono, para avalia\u00e7\u00e3o da emiss\u00e3o de gases de efeito estufa (GEE).<\/p>\n<p>Os temas que foram tratados na reuni\u00e3o t\u00eam interface com o projeto \u201c<strong>Desenvolvimento sustent\u00e1vel na ind\u00fastria da Constru\u00e7\u00e3o<\/strong>\u201d da Comiss\u00e3o de Meio Ambiente (CMA) da CBIC, com a correaliza\u00e7\u00e3o do Servi\u00e7o Nacional de Aprendizagem Industrial (Senai Nacional).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Comiss\u00e3o de Meio Ambiente da C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CMA\/CBIC) realizou nesta ter\u00e7a-feira (3) uma reuni\u00e3o com um time de especialistas para debater formas de o setor da constru\u00e7\u00e3o ajudar a combater o aquecimento global. O presidente da CMA, Nilson Sarti, mediou [&hellip;]<\/p>\n","protected":false},"author":1414,"featured_media":1000003,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[97,175],"tags":[],"class_list":["post-4949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-cbic","category-sustentabilidade-agencia-cbic"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conhe\u00e7a formas de contribuir no combate do aquecimento global na constru\u00e7\u00e3o - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/04\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conhe\u00e7a formas de contribuir no combate do aquecimento global na constru\u00e7\u00e3o - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"A Comiss\u00e3o de Meio Ambiente da C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CMA\/CBIC) realizou nesta ter\u00e7a-feira (3) uma reuni\u00e3o com um time de especialistas para debater formas de o setor da constru\u00e7\u00e3o ajudar a combater o aquecimento global. O presidente da CMA, Nilson Sarti, mediou [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/04\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-04T14:40:04+00:00\" \/>\n<meta name=\"author\" content=\"jornalistacbic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jornalistacbic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/08\\\/04\\\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/08\\\/04\\\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\\\/\"},\"author\":{\"name\":\"jornalistacbic\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/654b120bcd86d07c9f9dc286ecc91681\"},\"headline\":\"Conhe\u00e7a formas de contribuir no combate do aquecimento global na constru\u00e7\u00e3o\",\"datePublished\":\"2021-08-04T14:40:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/08\\\/04\\\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\\\/\"},\"wordCount\":1117,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/08\\\/04\\\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Ag\u00eancia CBIC\",\"Sustentabilidade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/08\\\/04\\\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/08\\\/04\\\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\\\/\",\"name\":\"Conhe\u00e7a formas de contribuir no combate do aquecimento global na constru\u00e7\u00e3o - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/08\\\/04\\\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/08\\\/04\\\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2021-08-04T14:40:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/654b120bcd86d07c9f9dc286ecc91681\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/08\\\/04\\\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/08\\\/04\\\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/08\\\/04\\\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/08\\\/04\\\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conhe\u00e7a formas de contribuir no combate do aquecimento global na constru\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/654b120bcd86d07c9f9dc286ecc91681\",\"name\":\"jornalistacbic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa24f0ed442729cb89355c4b9cd7ab747f7f3fa236417c2717409c63e87c39e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa24f0ed442729cb89355c4b9cd7ab747f7f3fa236417c2717409c63e87c39e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa24f0ed442729cb89355c4b9cd7ab747f7f3fa236417c2717409c63e87c39e?s=96&d=mm&r=g\",\"caption\":\"jornalistacbic\"},\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/jornalistacbic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conhe\u00e7a formas de contribuir no combate do aquecimento global na constru\u00e7\u00e3o - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/04\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\/","og_locale":"pt_BR","og_type":"article","og_title":"Conhe\u00e7a formas de contribuir no combate do aquecimento global na constru\u00e7\u00e3o - Comiss\u00e3o de Meio Ambiente","og_description":"A Comiss\u00e3o de Meio Ambiente da C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CMA\/CBIC) realizou nesta ter\u00e7a-feira (3) uma reuni\u00e3o com um time de especialistas para debater formas de o setor da constru\u00e7\u00e3o ajudar a combater o aquecimento global. O presidente da CMA, Nilson Sarti, mediou [&hellip;]","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/04\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2021-08-04T14:40:04+00:00","author":"jornalistacbic","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jornalistacbic","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/04\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/04\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\/"},"author":{"name":"jornalistacbic","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/654b120bcd86d07c9f9dc286ecc91681"},"headline":"Conhe\u00e7a formas de contribuir no combate do aquecimento global na constru\u00e7\u00e3o","datePublished":"2021-08-04T14:40:04+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/04\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\/"},"wordCount":1117,"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/04\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\/#primaryimage"},"thumbnailUrl":"","articleSection":["Ag\u00eancia CBIC","Sustentabilidade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/04\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/04\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\/","name":"Conhe\u00e7a formas de contribuir no combate do aquecimento global na constru\u00e7\u00e3o - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/04\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/04\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\/#primaryimage"},"thumbnailUrl":"","datePublished":"2021-08-04T14:40:04+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/654b120bcd86d07c9f9dc286ecc91681"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/04\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/04\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/04\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/08\/04\/conheca-formas-de-contribuir-no-combate-do-aquecimento-global-na-construcao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"Conhe\u00e7a formas de contribuir no combate do aquecimento global na constru\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/654b120bcd86d07c9f9dc286ecc91681","name":"jornalistacbic","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/5aa24f0ed442729cb89355c4b9cd7ab747f7f3fa236417c2717409c63e87c39e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5aa24f0ed442729cb89355c4b9cd7ab747f7f3fa236417c2717409c63e87c39e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5aa24f0ed442729cb89355c4b9cd7ab747f7f3fa236417c2717409c63e87c39e?s=96&d=mm&r=g","caption":"jornalistacbic"},"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/jornalistacbic\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/4949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/1414"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=4949"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/4949\/revisions"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=4949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=4949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=4949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}