{"id":4909,"date":"2021-04-30T18:40:52","date_gmt":"2021-04-30T21:40:52","guid":{"rendered":"https:\/\/cbic.org.br\/sustentabilidade\/2021\/04\/30\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\/"},"modified":"2021-04-30T18:40:52","modified_gmt":"2021-04-30T21:40:52","slug":"brasil-precisa-cumprir-politica-nacional-de-residuos-solidos","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2021\/04\/30\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\/","title":{"rendered":"Brasil precisa cumprir Pol\u00edtica Nacional de Res\u00edduos S\u00f3lidos"},"content":{"rendered":"<p>Reduzir a gera\u00e7\u00e3o de res\u00edduos s\u00f3lidos e aplicar solu\u00e7\u00f5es pr\u00e1ticas de reutiliza\u00e7\u00e3o e reciclagem \u00e9 um grande desafio no Brasil. Segundo dados da Associa\u00e7\u00e3o Brasileira de Empresas de Limpeza P\u00fablica e Res\u00edduos Especiais (Abrelpe), as cidades brasileiras geraram em 2018 cerca de 79 milh\u00f5es de toneladas de Res\u00edduos S\u00f3lidos Urbanos (RSU).<\/p>\n<p>Foram coletados 92% deste total, dos quais apenas 43,3 milh\u00f5es de toneladas, 59,5% do coletado, foi disposto em aterros sanit\u00e1rios. O montante de 29,5 milh\u00f5es de toneladas de res\u00edduos, 40,5% do total coletado, foi despejado inadequadamente em lix\u00f5es ou aterros controlados e ainda cerca de 6,3 milh\u00f5es de toneladas geradas anualmente continuam sem ao menos serem coletadas e seguem sendo depositadas sem controle.<\/p>\n<p>Para mitigar o problema foi aprovado em 2010, ap\u00f3s d\u00e9cadas de discuss\u00e3o, a Pol\u00edtica Nacional de Res\u00edduos S\u00f3lidos (PNRS), que determina o privil\u00e9gio da destina\u00e7\u00e3o para tratamento e, em \u00faltimo caso, o destino para aterros sanit\u00e1rios.<\/p>\n<p>A iniciativa \u00e9 um grande passo na solu\u00e7\u00e3o do problema, mas para colocar a PNRS em pr\u00e1tica s\u00e3o necess\u00e1rios mais investimentos p\u00fablicos e tamb\u00e9m o apoio e colabora\u00e7\u00e3o da sociedade e empresas na diminui\u00e7\u00e3o da gera\u00e7\u00e3o e destina\u00e7\u00e3o correta dos res\u00edduos. As boas pr\u00e1ticas encontram espa\u00e7o para est\u00edmulo neste m\u00eas de abril em que se comemora o Dia Nacional da Conserva\u00e7\u00e3o do Solo (15) e o Dia Mundial do Planeta Terra (22).<\/p>\n<p>Um case de sustentabilidade desenvolvido em Goi\u00e1s \u00e9 o da Consciente Construtora e Incorporadora. Em seu Relat\u00f3rio de Sustentabilidade 2018-2019 apresentado \u00e0 sociedade no final de 2020, a empresa aponta que aumentou substancialmente as a\u00e7\u00f5es de reciclagem e reutiliza\u00e7\u00e3o de res\u00edduos.<\/p>\n<p>Em 2017 a construtora reutilizou 40 m\u00b3 de res\u00edduos; em 2018, aumentou para 265 m\u00b3 e em 2019, foram 505 m\u00b3 de res\u00edduos reutilizados; mais de 10 vezes o volume de 2017. Na obra do Gaia Consciente Home, por exemplo, somente no ano de 2019, foram separados 166 m\u00b3 de madeira e direcionados para o reaproveitamento na Cer\u00e2mica Tapuia, em Trindade, que reutiliza no processo de queima na fabrica\u00e7\u00e3o de tijolos.<\/p>\n<p>Quanto \u00e0 reciclagem, em 2017 foram direcionados para a reciclagem 33.800 kg de res\u00edduos ou mais de 38 m\u00b3. Em 2018, 123 m\u00b3; e em 2019, alcan\u00e7ou a marca de 249 m\u00b3 de res\u00edduos da constru\u00e7\u00e3o civil reciclados.<\/p>\n<p>Segundo a supervisora do Sistema de Gest\u00e3o da Qualidade da Consciente, Amanda Gomes, o procedimento \u00e9 rigoroso. \u201cA empresa segue atentamente as orienta\u00e7\u00f5es do Conselho Nacional do Meio Ambiente (Conama) n\u00ba 275 e 307, que orienta sobre a disposi\u00e7\u00e3o dos mesmos.<\/p>\n<p>O sistema de Gest\u00e3o da Qualidade (SGQ) d\u00e1 o mapeamento met\u00f3dico e detalhado sobre os processos administrativos e da obra, al\u00e9m do controle de desperd\u00edcio e retrabalho. O resultado \u00e9 a diminui\u00e7\u00e3o de desperd\u00edcios de materiais e a consequente diminui\u00e7\u00e3o do impacto ambiental e melhora da performance produtiva\u201d, afirma Amanda Gomes.<\/p>\n<p>Nos canteiros de obras, \u00e9 realizada a segrega\u00e7\u00e3o de res\u00edduos, que s\u00e3o separados em classe A, B, C e D. O res\u00edduo classe A, do qual se tem maior volume nas obras, provenientes de concreto, revestimento cer\u00e2mico e tijolo, \u00e9 direcionado \u00e0 Ecoentulhos, uma empresa que faz o reaproveitamento dos res\u00edduos, por meio de parceria com a construtora.<\/p>\n<p>J\u00e1 os res\u00edduos classe B, como papel\u00e3o, sacos pl\u00e1sticos e mangueira de polietileno PVC, a Consciente reaproveita e envia para Cooperativa Tradi\u00e7\u00e3o, em An\u00e1polis. J\u00e1 a madeira \u00e9 enviada para a Cer\u00e2mica Tapuia, que tamb\u00e9m faz o reaproveitamento. Dessa forma, a empresa, al\u00e9m de beneficiar o meio-ambiente, estimula o desenvolvimento da cadeia de reciclagem de res\u00edduos e fortalece a gera\u00e7\u00e3o de renda para in\u00fameras fam\u00edlias.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 10pt\"><em>(Com informa\u00e7\u00f5es da Comunica\u00e7\u00e3o Sem Fronteiras)\u00a0<\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reduzir a gera\u00e7\u00e3o de res\u00edduos s\u00f3lidos e aplicar solu\u00e7\u00f5es pr\u00e1ticas de reutiliza\u00e7\u00e3o e reciclagem \u00e9 um grande desafio no Brasil. Segundo dados da Associa\u00e7\u00e3o Brasileira de Empresas de Limpeza P\u00fablica e Res\u00edduos Especiais (Abrelpe), as cidades brasileiras geraram em 2018 cerca de 79 milh\u00f5es de [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":1000001,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[97,175],"tags":[],"class_list":["post-4909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-cbic","category-sustentabilidade-agencia-cbic"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brasil precisa cumprir Pol\u00edtica Nacional de Res\u00edduos S\u00f3lidos - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/04\/30\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brasil precisa cumprir Pol\u00edtica Nacional de Res\u00edduos S\u00f3lidos - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"Reduzir a gera\u00e7\u00e3o de res\u00edduos s\u00f3lidos e aplicar solu\u00e7\u00f5es pr\u00e1ticas de reutiliza\u00e7\u00e3o e reciclagem \u00e9 um grande desafio no Brasil. Segundo dados da Associa\u00e7\u00e3o Brasileira de Empresas de Limpeza P\u00fablica e Res\u00edduos Especiais (Abrelpe), as cidades brasileiras geraram em 2018 cerca de 79 milh\u00f5es de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/04\/30\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-30T21:40:52+00:00\" \/>\n<meta name=\"author\" content=\"Sandra Bezerra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sandra Bezerra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/04\\\/30\\\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/04\\\/30\\\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\\\/\"},\"author\":{\"name\":\"Sandra Bezerra\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\"},\"headline\":\"Brasil precisa cumprir Pol\u00edtica Nacional de Res\u00edduos S\u00f3lidos\",\"datePublished\":\"2021-04-30T21:40:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/04\\\/30\\\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\\\/\"},\"wordCount\":649,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/04\\\/30\\\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Ag\u00eancia CBIC\",\"Sustentabilidade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/04\\\/30\\\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/04\\\/30\\\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\\\/\",\"name\":\"Brasil precisa cumprir Pol\u00edtica Nacional de Res\u00edduos S\u00f3lidos - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/04\\\/30\\\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/04\\\/30\\\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2021-04-30T21:40:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/04\\\/30\\\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/04\\\/30\\\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/04\\\/30\\\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2021\\\/04\\\/30\\\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brasil precisa cumprir Pol\u00edtica Nacional de Res\u00edduos S\u00f3lidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\",\"name\":\"Sandra Bezerra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"caption\":\"Sandra Bezerra\"},\"sameAs\":[\"https:\\\/\\\/cbic.org.br\"],\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/sandra-bezerra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brasil precisa cumprir Pol\u00edtica Nacional de Res\u00edduos S\u00f3lidos - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/04\/30\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\/","og_locale":"pt_BR","og_type":"article","og_title":"Brasil precisa cumprir Pol\u00edtica Nacional de Res\u00edduos S\u00f3lidos - Comiss\u00e3o de Meio Ambiente","og_description":"Reduzir a gera\u00e7\u00e3o de res\u00edduos s\u00f3lidos e aplicar solu\u00e7\u00f5es pr\u00e1ticas de reutiliza\u00e7\u00e3o e reciclagem \u00e9 um grande desafio no Brasil. Segundo dados da Associa\u00e7\u00e3o Brasileira de Empresas de Limpeza P\u00fablica e Res\u00edduos Especiais (Abrelpe), as cidades brasileiras geraram em 2018 cerca de 79 milh\u00f5es de [&hellip;]","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/04\/30\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2021-04-30T21:40:52+00:00","author":"Sandra Bezerra","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sandra Bezerra","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/04\/30\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/04\/30\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\/"},"author":{"name":"Sandra Bezerra","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e"},"headline":"Brasil precisa cumprir Pol\u00edtica Nacional de Res\u00edduos S\u00f3lidos","datePublished":"2021-04-30T21:40:52+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/04\/30\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\/"},"wordCount":649,"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/04\/30\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\/#primaryimage"},"thumbnailUrl":"","articleSection":["Ag\u00eancia CBIC","Sustentabilidade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/04\/30\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/04\/30\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\/","name":"Brasil precisa cumprir Pol\u00edtica Nacional de Res\u00edduos S\u00f3lidos - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/04\/30\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/04\/30\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\/#primaryimage"},"thumbnailUrl":"","datePublished":"2021-04-30T21:40:52+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/04\/30\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/04\/30\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/04\/30\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2021\/04\/30\/brasil-precisa-cumprir-politica-nacional-de-residuos-solidos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"Brasil precisa cumprir Pol\u00edtica Nacional de Res\u00edduos S\u00f3lidos"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e","name":"Sandra Bezerra","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","caption":"Sandra Bezerra"},"sameAs":["https:\/\/cbic.org.br"],"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/sandra-bezerra\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/4909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=4909"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/4909\/revisions"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=4909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=4909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=4909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}