{"id":4782,"date":"2020-10-28T18:09:59","date_gmt":"2020-10-28T21:09:59","guid":{"rendered":"https:\/\/cbic.org.br\/sustentabilidade\/2020\/10\/28\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\/"},"modified":"2020-10-28T18:13:17","modified_gmt":"2020-10-28T21:13:17","slug":"regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2020\/10\/28\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\/","title":{"rendered":"Representantes do Norte defendem aprova\u00e7\u00e3o de nova lei do licenciamento ambiental"},"content":{"rendered":"<p style=\"text-align: justify\">Nesta quarta-feira (28\/10), a CBIC promoveu um webinar sobre a <strong>Nova Lei Geral do Licenciamento Ambiental<\/strong>, com foco na regi\u00e3o Norte do pa\u00eds. A iniciativa visa apresentar o andamento da nova lei, as expectativas para aprova\u00e7\u00e3o e os pontos de interesse do setor da constru\u00e7\u00e3o. Na ocasi\u00e3o, representantes do estado defenderam a necessidade de aprova\u00e7\u00e3o da nova lei.<\/p>\n<p style=\"text-align: justify\">O deputado federal, Marcelo Ramos Rodrigues (PL-AM), refor\u00e7ou que nenhum pa\u00eds pode ser sustent\u00e1vel sem garantir a sustentabilidade. \u201cPreserva\u00e7\u00e3o ambiental hoje \u00e9 um ativo para todos os setores exportadores no pa\u00eds. Relacionar a melhoria do licenciamento com mecanismos de preserva\u00e7\u00e3o \u00e9 algo positivo, pois atrai investimentos. Mas precisamos por outro lado rever essa legisla\u00e7\u00e3o que hoje n\u00e3o da seguran\u00e7a jur\u00eddica para quem quer empreender. O modelo de licenciamento ambiental atual \u00e9 complexo e atrasa todo processo. Precisamos garantir seguran\u00e7a jur\u00eddica criando simplifica\u00e7\u00e3o do modelo de legisla\u00e7\u00e3o ambiental\u201d, disse.<\/p>\n<p style=\"text-align: justify\">Ramos acredita que com a aprova\u00e7\u00e3o ser\u00e1 preciso consolidar a lei no poder judici\u00e1rio e nas esferas administrativas. \u201cOs crit\u00e9rios de preserva\u00e7\u00e3o t\u00eam que ter um ponto de equil\u00edbrio, n\u00e3o podem ser ideologizados. Ou seja, n\u00e3o podemos tratar uma \u00e1rea remota de margem de rio como uma \u00e1rea urbana consolidada. Devemos preservar ao m\u00e1ximo as \u00e1reas mais remotas, mas n\u00e3o podemos ignorar \u00e1reas j\u00e1 consolidadas\u201d, pontuou.<\/p>\n<figure id=\"attachment_57934\" aria-describedby=\"caption-attachment-57934\" style=\"width: 983px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" width=\"983\" height=\"712\" class=\"wp-image-4783 size-full\" src=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/10\/12.jpg\" alt=\"\" \/><figcaption id=\"caption-attachment-57934\" class=\"wp-caption-text\">Dep. Marcelo Ramos<\/figcaption><\/figure>\n<p style=\"text-align: justify\">O parlamentar reiterou que a lei j\u00e1 tem um grande consenso na c\u00e2mara, e que os pontos cr\u00edticos devem ser discutidos \u00e0 parte, n\u00e3o podendo frear a vota\u00e7\u00e3o. \u201cN\u00f3s n\u00e3o teremos converg\u00eancia absoluta, mas temos consenso em grande parte do projeto, o que acredito que vai fazer a pauta andar. Minha a\u00e7\u00e3o ser\u00e1 sempre em di\u00e1logo com a CBIC e setor, pois como sempre falo, ambiente de neg\u00f3cios sadio para a constru\u00e7\u00e3o civil \u00e9 emprego na veia, e hostil \u00e9 desemprego na veia. Precisamos dar mais esse ponto de equil\u00edbrio para o setor ser o grande motor da retomada econ\u00f4mica\u201d, destacou.<\/p>\n<p style=\"text-align: justify\">De acordo com o consultor da CBIC, Marcos Saes, o evento refor\u00e7ou o apoio do setor ao\u00a0<a href=\"https:\/\/www.camara.leg.br\/proposicoesWeb\/fichadetramitacao?idProposicao=257161\"><strong>Projeto de Lei 3729\/04<\/strong><\/a>, que tramita na C\u00e2mara Federal h\u00e1 15 anos. \u201cO tema j\u00e1 foi bastante discutido e agora precisamos viabilizar a aprova\u00e7\u00e3o no plen\u00e1rio da c\u00e2mara federal. At\u00e9 porque hoje o Brasil n\u00e3o tem uma lei, e sim um emaranhado de normas que regulam o tema. A falta de uma norma clara e unificada gera um atraso que custa aos cofres da uni\u00e3o R$ 6 bilh\u00f5es por ano\u201d, alertou.<\/p>\n<p style=\"text-align: justify\">Frank do Carmo Souza, presidente do Sinduscon-AM, tamb\u00e9m defendeu a aprova\u00e7\u00e3o da lei. \u201cPrecisamos levar nossos pleitos sobre a quest\u00e3o de forma l\u00facida e a CBIC vem fazendo isso muito bem neste ciclo de debates, onde o Par\u00e1 j\u00e1 \u00e9 a quarta regi\u00e3o a discutir o tema. No que depender da regi\u00e3o Norte queremos ajudar a mat\u00e9ria a evoluir e ser votada, at\u00e9 porque se for aprovada, com a celeridade para concess\u00e3o de licenciamento ambiental, pode gerar at\u00e9 R$ 120 bilh\u00f5es em investimentos em at\u00e9 10 anos\u201d, frisou.<\/p>\n<p style=\"text-align: justify\">Para o presidente da comiss\u00e3o de Meio Ambiente da CBIC, Nilson Sarti, a lei \u00e9 muito boa, r\u00edgida e importante para a sociedade. \u201cO setor n\u00e3o quer flexibiliza\u00e7\u00e3o, quer uniformiza\u00e7\u00e3o, simplifica\u00e7\u00e3o, transpar\u00eancia e seguran\u00e7a jur\u00eddica. Queremos que o funcion\u00e1rio publico fa\u00e7a a an\u00e1lise de forma t\u00e9cnica e que tenha o conforto de analisar as demandas sem se preocupar com a criminaliza\u00e7\u00e3o. \u00c9 urgente buscar prioridade para essa pauta, para come\u00e7ar 2021 com essa nova lei que pode viabilizar a retomada dos investimentos no pa\u00eds\u201d, afirmou.<\/p>\n<p style=\"text-align: justify\">Presidente da Federa\u00e7\u00e3o das Ind\u00fastrias do Estado do Amazonas (FIEAM), Ant\u00f4nio Carlos da Silva, reiterou a fala do deputado Marcelo Ramos, apoiando a aprova\u00e7\u00e3o da lei de licenciamento ambiental, dada a grande relev\u00e2ncia do tema. \u201cA inseguran\u00e7a jur\u00eddica que hoje existe diz respeito a falta de uma uniformidade nas regras. Garantir um olhar atento \u00e0s peculiaridades regionais tamb\u00e9m \u00e9 essencial, pois existem pontos que n\u00e3o podem ser tratados da mesma forma para o licenciamento. A nova lei vai trazer significativas melhorias para as atividades industrial do pa\u00eds. Defendemos a aprova\u00e7\u00e3o, com seguran\u00e7a jur\u00eddica primando pela previsibilidade, transpar\u00eancia e uniformidade para a concess\u00e3o de licen\u00e7as\u201d, disse.<\/p>\n<p style=\"text-align: justify\">J\u00e1 o assessor da presid\u00eancia do Instituto de Prote\u00e7\u00e3o Ambiental do Amazonas (IPAAM), Sheron Vitorino, ressaltou que o grande marco que a nova lei pode trazer \u00e9 a desburocratiza\u00e7\u00e3o por meio da uniformiza\u00e7\u00e3o e digitaliza\u00e7\u00e3o do sistema. \u201cEssas ferramentas facilitariam muito a forma de concess\u00e3o, pois hoje o emaranhado de normas atrasa e dificulta o trabalho\u201d, explicou.<\/p>\n<p style=\"text-align: justify\">Vitorino afirmou ainda que as possibilidades das modalidades de licenciamento s\u00e3o bem vistas, onde a padroniza\u00e7\u00e3o vai facilitar muito a concess\u00e3o do licenciamento. \u201cCustomizar um sistema a partir dos marcos legais \u00e9 muito dif\u00edcil, por isso quando se fala em uma lei geral conseguimos enxergar um melhor caminho. Al\u00e9m disso, o maior valor para os t\u00e9cnicos \u00e9 a seguran\u00e7a jur\u00eddica que essa lei vai gerar. O analista ambiental \u00e9 fundamental no processo, mas precisa trabalhar com garantias\u201d, concluiu.<\/p>\n<p style=\"text-align: justify\">A regi\u00e3o Norte \u00e9 a quarta a receber o webinar, que j\u00e1 passou pelo Sul, Sudeste e Centro-Oeste. A iniciativa tem interface com o projeto<strong>\u00a0\u2018Melhorias do Mercado Imobili\u00e1rio\u2019<\/strong>\u00a0realizado pela CBIC, por meio das Comiss\u00f5es da Ind\u00fastria Imobili\u00e1ria (CII), de Habita\u00e7\u00e3o de Interesse Social (CHIS) e de Meio Ambiente (CMA), com a correaliza\u00e7\u00e3o do Servi\u00e7o Nacional da Ind\u00fastria (Senai).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8230;<\/p>\n","protected":false},"author":1414,"featured_media":4785,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[97,228,175],"tags":[],"class_list":["post-4782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-cbic","category-industria-imobiliaria-agencia-cbic","category-sustentabilidade-agencia-cbic"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Representantes do Norte defendem aprova\u00e7\u00e3o de nova lei do licenciamento ambiental - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/10\/28\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Representantes do Norte defendem aprova\u00e7\u00e3o de nova lei do licenciamento ambiental - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/10\/28\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-28T21:09:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-28T21:13:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/10\/11-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1026\" \/>\n\t<meta property=\"og:image:height\" content=\"582\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jornalistacbic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jornalistacbic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/10\\\/28\\\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/10\\\/28\\\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\\\/\"},\"author\":{\"name\":\"jornalistacbic\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/654b120bcd86d07c9f9dc286ecc91681\"},\"headline\":\"Representantes do Norte defendem aprova\u00e7\u00e3o de nova lei do licenciamento ambiental\",\"datePublished\":\"2020-10-28T21:09:59+00:00\",\"dateModified\":\"2020-10-28T21:13:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/10\\\/28\\\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\\\/\"},\"wordCount\":989,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/10\\\/28\\\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2020\\\/10\\\/11-1.jpg\",\"articleSection\":[\"Ag\u00eancia CBIC\",\"Ind\u00fastria Imobili\u00e1ria\",\"Sustentabilidade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/10\\\/28\\\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/10\\\/28\\\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/10\\\/28\\\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\\\/\",\"name\":\"Representantes do Norte defendem aprova\u00e7\u00e3o de nova lei do licenciamento ambiental - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/10\\\/28\\\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/10\\\/28\\\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2020\\\/10\\\/11-1.jpg\",\"datePublished\":\"2020-10-28T21:09:59+00:00\",\"dateModified\":\"2020-10-28T21:13:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/654b120bcd86d07c9f9dc286ecc91681\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/10\\\/28\\\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/10\\\/28\\\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/10\\\/28\\\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2020\\\/10\\\/11-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2020\\\/10\\\/11-1.jpg\",\"width\":1026,\"height\":582},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/10\\\/28\\\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Representantes do Norte defendem aprova\u00e7\u00e3o de nova lei do licenciamento ambiental\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/654b120bcd86d07c9f9dc286ecc91681\",\"name\":\"jornalistacbic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa24f0ed442729cb89355c4b9cd7ab747f7f3fa236417c2717409c63e87c39e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa24f0ed442729cb89355c4b9cd7ab747f7f3fa236417c2717409c63e87c39e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa24f0ed442729cb89355c4b9cd7ab747f7f3fa236417c2717409c63e87c39e?s=96&d=mm&r=g\",\"caption\":\"jornalistacbic\"},\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/jornalistacbic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Representantes do Norte defendem aprova\u00e7\u00e3o de nova lei do licenciamento ambiental - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/10\/28\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\/","og_locale":"pt_BR","og_type":"article","og_title":"Representantes do Norte defendem aprova\u00e7\u00e3o de nova lei do licenciamento ambiental - Comiss\u00e3o de Meio Ambiente","og_description":"...","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/10\/28\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2020-10-28T21:09:59+00:00","article_modified_time":"2020-10-28T21:13:17+00:00","og_image":[{"width":1026,"height":582,"url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/10\/11-1.jpg","type":"image\/jpeg"}],"author":"jornalistacbic","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jornalistacbic","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/10\/28\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/10\/28\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\/"},"author":{"name":"jornalistacbic","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/654b120bcd86d07c9f9dc286ecc91681"},"headline":"Representantes do Norte defendem aprova\u00e7\u00e3o de nova lei do licenciamento ambiental","datePublished":"2020-10-28T21:09:59+00:00","dateModified":"2020-10-28T21:13:17+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/10\/28\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\/"},"wordCount":989,"commentCount":0,"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/10\/28\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/10\/11-1.jpg","articleSection":["Ag\u00eancia CBIC","Ind\u00fastria Imobili\u00e1ria","Sustentabilidade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/10\/28\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/10\/28\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/10\/28\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\/","name":"Representantes do Norte defendem aprova\u00e7\u00e3o de nova lei do licenciamento ambiental - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/10\/28\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/10\/28\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/10\/11-1.jpg","datePublished":"2020-10-28T21:09:59+00:00","dateModified":"2020-10-28T21:13:17+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/654b120bcd86d07c9f9dc286ecc91681"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/10\/28\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/10\/28\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/10\/28\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\/#primaryimage","url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/10\/11-1.jpg","contentUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/10\/11-1.jpg","width":1026,"height":582},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/10\/28\/regiao-norte-defende-aprovacao-de-nova-lei-do-licenciamento-ambiental\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"Representantes do Norte defendem aprova\u00e7\u00e3o de nova lei do licenciamento ambiental"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/654b120bcd86d07c9f9dc286ecc91681","name":"jornalistacbic","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/5aa24f0ed442729cb89355c4b9cd7ab747f7f3fa236417c2717409c63e87c39e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5aa24f0ed442729cb89355c4b9cd7ab747f7f3fa236417c2717409c63e87c39e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5aa24f0ed442729cb89355c4b9cd7ab747f7f3fa236417c2717409c63e87c39e?s=96&d=mm&r=g","caption":"jornalistacbic"},"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/jornalistacbic\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/4782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/1414"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=4782"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/4782\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media\/4785"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=4782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=4782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=4782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}