{"id":4591,"date":"2020-08-12T20:31:56","date_gmt":"2020-08-12T23:31:56","guid":{"rendered":"https:\/\/cbic.org.br\/sustentabilidade\/2020\/08\/12\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\/"},"modified":"2020-08-13T15:50:29","modified_gmt":"2020-08-13T18:50:29","slug":"empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2020\/08\/12\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\/","title":{"rendered":"Novo Selo Casa Azul + Caixa \u00e9 apresentado a empres\u00e1rios da constru\u00e7\u00e3o"},"content":{"rendered":"<p>As melhorias realizadas no <strong>Selo Casa Azul + Caixa<\/strong>, as vantagens da certifica\u00e7\u00e3o e os principais desafios enfrentadas pelas empresas do setor da constru\u00e7\u00e3o na sua obten\u00e7\u00e3o foram foco do <strong>\u2018Di\u00e1logos CBIC&#8217;<\/strong> desta quarta-feira (12), realizado pela Comiss\u00e3o de Meio Ambiente (CMA) da C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC).<\/p>\n<p>Dentre as vantagens da certifica\u00e7\u00e3o para as empresas do mercado imobili\u00e1rio est\u00e3o o fortalecimento da imagem e da reputa\u00e7\u00e3o e a <strong>redu\u00e7\u00e3o da taxa de juros de 0,25% do financiamento \u00e0 produ\u00e7\u00e3o<\/strong>, via Sistema Brasileiro de Poupan\u00e7a e Empr\u00e9stimo (SBPE). J\u00e1 para os adquirentes, al\u00e9m de melhor qualidade de vida, conforto ambiental e redu\u00e7\u00e3o de despesas mensais, condi\u00e7\u00f5es especiais para o financiamento da unidade vinculada a empreendimentos certificados no SBPE.<\/p>\n<p>Ao refor\u00e7ar a import\u00e2ncia da Caixa, que det\u00e9m cerca de 70% a 80% do mercado imobili\u00e1rio, estar completamente engajada neste assunto da sustentabilidade, o presidente da CMA\/CBIC, <strong>Nilson Sarti<\/strong><span style=\"font-family: georgia, palatino, serif\">, <\/span>refor\u00e7ou que a CBIC leva o tema muito a s\u00e9rio e vem trabalhando h\u00e1 anos no sentido de amadurecer o debate e mostrar que esse \u00e9 o caminho.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_54353\" aria-describedby=\"caption-attachment-54353\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"546\" class=\"wp-image-4528 size-large\" src=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/08\/WhatsApp-Image-2020-08-12-at-16.44.18-1024x546.jpeg\" alt=\"\" \/><figcaption id=\"caption-attachment-54353\" class=\"wp-caption-text\">Erika Regina Yokoda, arquiteta da Caixa<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Criado em 2009, o Selo Casa Azul + Caixa foi o primeiro sistema de certifica\u00e7\u00e3o de sustentabilidade desenvolvido para a realidade da constru\u00e7\u00e3o habitacional brasileira. Atualmente, h\u00e1 43 empreendimentos de habita\u00e7\u00e3o de interesse social e de mercado certificados com o selo, sendo 22 na regi\u00e3o Sudeste, nove no Nordeste, nove no Sul e tr\u00eas no Centro-Oeste. Desde a remodela\u00e7\u00e3o do Selo, no primeiro semestre de 2020, j\u00e1 s\u00e3o 10 os empreendimentos certificados.<\/p>\n<p>\u201cO novo formato do Selo \u00a0tem como principais objetivos gerar benef\u00edcios ambientais, sociais e econ\u00f4micos, tanto ao cliente pessoa f\u00edsica quanto \u00e0s empresas parceiras, e fortalecer ainda mais a marca da Caixa como agente e indutor da produ\u00e7\u00e3o sustent\u00e1vel, inovadora e socialmente respons\u00e1vel, destaca a arquiteta da Caixa, <strong>Erika Regina Yokoda<\/strong>. Al\u00e9m da <a href=\"https:\/\/cbic.org.br\/wp-content\/uploads\/2020\/08\/Apresenta\u00e7\u00e3o-Externa-Selo2020_v002-3.pdf\">apresenta\u00e7\u00e3o realizada pela Caixa<\/a>, conhe\u00e7a tamb\u00e9m\u00a0 o <a href=\"https:\/\/cbic.org.br\/wp-content\/uploads\/2020\/08\/Guia_Selo_Casa_Azul_CAIXA_Junho_2020.pdf\">Guia Selo Casa Azul + Caixa<\/a>.<\/p>\n<p>Para participar da certifica\u00e7\u00e3o \u00e9 preciso seguir as regras dos programas e linhas de financiamento da Caixa Econ\u00f4mica Federal e atender \u00e0s Normas de Desempenho (NBR 15.575), bem como seguir as diretrizes do Sistema Nacional de Avalia\u00e7\u00e3o T\u00e9cnica (Sinat) nos casos de uso de sistemas inovadores, e apresentar Pol\u00edtica Socioambiental do FGTS, se for um empreendimento com uso desses recursos, e o C\u00f3digo de pr\u00e1ticas Caixa. No que se refere \u00e0s vistorias, elas s\u00e3o feitas com o olhar mais especifico para atendimento ao selo.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>N\u00edveis de classifica\u00e7\u00e3o do Selo Casa Azul + Caixa<\/strong><\/h2>\n<p>A nova estrutura est\u00e1 dividida em quatro n\u00edveis de classifica\u00e7\u00e3o. S\u00e3o eles: Bronze, que acumula 50 pontos ou dois identificadores+), Prata (60 pontos ou tr\u00eas+), Ouro (80 pontos ou 4+) e Diamante (100 pontos e obrigatoriamente o identificador <em>+<\/em>Inova\u00e7\u00e3o<em>).<\/em> Veja quais s\u00e3o os identificadores+:<\/p>\n<ul>\n<li>Qualidade Urbana<\/li>\n<li>Efici\u00eancia Energ\u00e9tica<\/li>\n<li>Gest\u00e3o Eficiente da \u00c1gua<\/li>\n<li>Produ\u00e7\u00e3o Sustent\u00e1vel<\/li>\n<li>Desenvolvimento social<\/li>\n<li>Inova\u00e7\u00e3o<\/li>\n<\/ul>\n<p>O presidente da Comiss\u00e3o de Habita\u00e7\u00e3o de Interesse Social (CHIS) da CBIC, <strong>Carlos Henrique Passos<\/strong>, elogiou o debate e parabenizou a Caixa pela reformula\u00e7\u00e3o do sistema. &#8220;A mudan\u00e7a motivar\u00e1 as empresas. \u00c9 importante manter a qualidade e o dinamismo do programa e essa interlocu\u00e7\u00e3o da Caixa com a CMA\/CBIC vai ajudar na sua atualiza\u00e7\u00e3o e na sintonia com o mercado, para que ele possa perceber as vantagens da sustentabilidade\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" width=\"1024\" height=\"435\" class=\"aligncenter wp-image-4530 size-large\" src=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/08\/WhatsApp-Image-2020-08-12-at-16.44.17-1-1024x435.jpeg\" alt=\"\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Rodrigo Cervi\u00f1o Peleteiro<\/strong>, da MVL Incorporadora e Inova Empreendimentos, apresentou o <em>case<\/em> do Jaguah Residence, na orla de Jaguaribe, em Salvador (BA), primeiro empreendimento baiano a obter a certifica\u00e7\u00e3o do Selo Casa Azul + Caixa, na categoria Ouro.<\/p>\n<p>Segundo Rodrigo Peleteiro, o incentivo para a busca da certifica\u00e7\u00e3o foi a redu\u00e7\u00e3o dos juros, tanto para a empresa quanto para o cliente, na tomada do financiamento dos empr\u00e9stimos. Al\u00e9m disso, o est\u00edmulo percebido na pesquisa da empresa, que aponta que o cliente topa pagar mais por um im\u00f3vel sustent\u00e1vel, somado ao IPTU Verde e \u00e0 Outorga Verde fizeram com que a empresa percebesse vantagens e inclu\u00edsse os itens de sustentabilidade do Selo no seu produto<em>.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" width=\"1009\" height=\"673\" class=\"aligncenter wp-image-4532 size-full\" src=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/08\/WhatsApp-Image-2020-08-12-at-16.44.17.jpeg\" alt=\"\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>J\u00e1 <strong>Felipe Grossi<\/strong>, da Encorp Engenharia e Constru\u00e7\u00f5es Ltda, detalhou o <em>case<\/em> do Condom\u00ednio Clube Residencial Morana Iguatemi, em Porto Alegre (RS), com 200 unidades e que obteve o n\u00edvel Ouro, com o identificador + Inova\u00e7\u00e3o.<\/p>\n<p>A empresa, especializada em empreendimentos do programa Minha Casa, Minha Vida (MCMV), percebeu que \u00e9 poss\u00edvel entregar produto com qualidade e sustentabilidade, dentro do seu or\u00e7amento. Dentre as vantagens observadas, maior possibilidade de atender aos indicadores e se alinhar aos objetivos da Caixa, estabelecer uma rela\u00e7\u00e3o de parceria com a institui\u00e7\u00e3o e obter o reconhecimento do cliente do MCMV.<\/p>\n<p>A gerente nacional da Caixa, Ang\u00e9lica Djeane Phelippe Correa, refor\u00e7ou a import\u00e2ncia do di\u00e1logo com o setor. \u201cEsperamos ter motivado os participantes ao terem conhecido mais o Selo Casa Azul + Caixa&#8221;, mencionou, refor\u00e7ando que o processo de melhoria \u00e9 constante e que a institui\u00e7\u00e3o est\u00e1 \u00e0 disposi\u00e7\u00e3o para dialogar sobre o assunto.<\/p>\n<p>Ficou acertado que as sugest\u00f5es apresentadas ser\u00e3o estudadas e que representantes da Caixa participar\u00e3o de <em>road show<\/em> promovido pela CBIC para disseminar o produto e ampliar o debate nas regi\u00f5es brasileiras.<\/p>\n<p>O <strong>Di\u00e1logos CBIC<\/strong> tamb\u00e9m contou com a participa\u00e7\u00e3o da gerente Executiva respons\u00e1vel pelo Selo Casa Azul + Caixa, Silvia Merendas. A iniciativa tem interface com o projeto\u00a0<strong>\u2018Melhorias do Mercado Imobili\u00e1rio\u2019<\/strong>\u00a0realizado pela CBIC, por meio das Comiss\u00f5es da Ind\u00fastria Imobili\u00e1ria (CII), de Habita\u00e7\u00e3o de Interesse Social (CHIS) e de Meio Ambiente e Sustentabilidade (CMA), com a correaliza\u00e7\u00e3o do Servi\u00e7o Nacional da Ind\u00fastria (Senai).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8230;<\/p>\n","protected":false},"author":10,"featured_media":4534,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[97,284,228,175],"tags":[302],"class_list":["post-4591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-cbic","category-habitacao-de-interesse-social-agencia-cbic","category-industria-imobiliaria-agencia-cbic","category-sustentabilidade-agencia-cbic","tag-selo-casa-azul-caixa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novo Selo Casa Azul + Caixa \u00e9 apresentado a empres\u00e1rios da constru\u00e7\u00e3o - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/08\/12\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novo Selo Casa Azul + Caixa \u00e9 apresentado a empres\u00e1rios da constru\u00e7\u00e3o - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/08\/12\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-12T23:31:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-13T18:50:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/08\/WhatsApp-Image-2020-08-12-at-16.44.18-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"723\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sandra Bezerra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sandra Bezerra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/08\\\/12\\\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/08\\\/12\\\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\\\/\"},\"author\":{\"name\":\"Sandra Bezerra\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\"},\"headline\":\"Novo Selo Casa Azul + Caixa \u00e9 apresentado a empres\u00e1rios da constru\u00e7\u00e3o\",\"datePublished\":\"2020-08-12T23:31:56+00:00\",\"dateModified\":\"2020-08-13T18:50:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/08\\\/12\\\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\\\/\"},\"wordCount\":1004,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/08\\\/12\\\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2020\\\/08\\\/WhatsApp-Image-2020-08-12-at-16.44.18-1.jpeg\",\"keywords\":[\"Selo Casa Azul + Caixa\"],\"articleSection\":[\"Ag\u00eancia CBIC\",\"Habita\u00e7\u00e3o de Interesse Social\",\"Ind\u00fastria Imobili\u00e1ria\",\"Sustentabilidade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/08\\\/12\\\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/08\\\/12\\\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/08\\\/12\\\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\\\/\",\"name\":\"Novo Selo Casa Azul + Caixa \u00e9 apresentado a empres\u00e1rios da constru\u00e7\u00e3o - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/08\\\/12\\\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/08\\\/12\\\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2020\\\/08\\\/WhatsApp-Image-2020-08-12-at-16.44.18-1.jpeg\",\"datePublished\":\"2020-08-12T23:31:56+00:00\",\"dateModified\":\"2020-08-13T18:50:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/08\\\/12\\\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/08\\\/12\\\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/08\\\/12\\\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2020\\\/08\\\/WhatsApp-Image-2020-08-12-at-16.44.18-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2020\\\/08\\\/WhatsApp-Image-2020-08-12-at-16.44.18-1.jpeg\",\"width\":1280,\"height\":723},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/08\\\/12\\\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novo Selo Casa Azul + Caixa \u00e9 apresentado a empres\u00e1rios da constru\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\",\"name\":\"Sandra Bezerra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"caption\":\"Sandra Bezerra\"},\"sameAs\":[\"https:\\\/\\\/cbic.org.br\"],\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/sandra-bezerra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novo Selo Casa Azul + Caixa \u00e9 apresentado a empres\u00e1rios da constru\u00e7\u00e3o - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/08\/12\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\/","og_locale":"pt_BR","og_type":"article","og_title":"Novo Selo Casa Azul + Caixa \u00e9 apresentado a empres\u00e1rios da constru\u00e7\u00e3o - Comiss\u00e3o de Meio Ambiente","og_description":"...","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/08\/12\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2020-08-12T23:31:56+00:00","article_modified_time":"2020-08-13T18:50:29+00:00","og_image":[{"width":1280,"height":723,"url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/08\/WhatsApp-Image-2020-08-12-at-16.44.18-1.jpeg","type":"image\/jpeg"}],"author":"Sandra Bezerra","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sandra Bezerra","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/08\/12\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/08\/12\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\/"},"author":{"name":"Sandra Bezerra","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e"},"headline":"Novo Selo Casa Azul + Caixa \u00e9 apresentado a empres\u00e1rios da constru\u00e7\u00e3o","datePublished":"2020-08-12T23:31:56+00:00","dateModified":"2020-08-13T18:50:29+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/08\/12\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\/"},"wordCount":1004,"commentCount":0,"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/08\/12\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/08\/WhatsApp-Image-2020-08-12-at-16.44.18-1.jpeg","keywords":["Selo Casa Azul + Caixa"],"articleSection":["Ag\u00eancia CBIC","Habita\u00e7\u00e3o de Interesse Social","Ind\u00fastria Imobili\u00e1ria","Sustentabilidade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/08\/12\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/08\/12\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/08\/12\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\/","name":"Novo Selo Casa Azul + Caixa \u00e9 apresentado a empres\u00e1rios da constru\u00e7\u00e3o - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/08\/12\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/08\/12\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/08\/WhatsApp-Image-2020-08-12-at-16.44.18-1.jpeg","datePublished":"2020-08-12T23:31:56+00:00","dateModified":"2020-08-13T18:50:29+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/08\/12\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/08\/12\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/08\/12\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\/#primaryimage","url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/08\/WhatsApp-Image-2020-08-12-at-16.44.18-1.jpeg","contentUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/08\/WhatsApp-Image-2020-08-12-at-16.44.18-1.jpeg","width":1280,"height":723},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/08\/12\/empresas-apontam-vantagens-da-sustentabilidade-na-construcao-8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"Novo Selo Casa Azul + Caixa \u00e9 apresentado a empres\u00e1rios da constru\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e","name":"Sandra Bezerra","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","caption":"Sandra Bezerra"},"sameAs":["https:\/\/cbic.org.br"],"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/sandra-bezerra\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/4591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=4591"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/4591\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media\/4534"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=4591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=4591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=4591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}