{"id":4420,"date":"2020-04-16T18:31:09","date_gmt":"2020-04-16T21:31:09","guid":{"rendered":"https:\/\/cbic.org.br\/sustentabilidade\/2020\/04\/16\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\/"},"modified":"2020-05-19T22:01:11","modified_gmt":"2020-05-20T01:01:11","slug":"covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2020\/04\/16\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\/","title":{"rendered":"Covid-19: Codese-DF doa cinco respiradores ao Governo do DF  \u00a0"},"content":{"rendered":"<p>O presidente do Conselho de Desenvolvimento Econ\u00f4mico, Sustent\u00e1vel e Estrat\u00e9gico do Distrito Federal (Codese-DF), Paulo Roberto de Morais Muniz, entregou no \u00faltimo dia 8 ao Governo do Distrito Federal <strong>cinco respiradores que v\u00e3o ajudar no combate ao\u00a0coronav\u00edrus na capital federal<\/strong>. A assinatura de doa\u00e7\u00e3o dos equipamentos, no Pal\u00e1cio do Buriti, contou com a presen\u00e7a do governador Ibaneis Rocha, do secret\u00e1rio de Sa\u00fade, Francisco Ara\u00fajo, e do secret\u00e1rio da Casa Civil, Valdet\u00e1rio Monteiro.<\/p>\n<p>A iniciativa \u00e9 resultado da campanha <strong>#JuntospeloDF<\/strong> <strong>que j\u00e1 arrecadou R$ 280.596,45<\/strong> e envolve empresas de todas as \u00e1reas do setor produtivo, associa\u00e7\u00f5es, entidades e pessoas.<\/p>\n<p>Ao agradecer o gesto em favor da popula\u00e7\u00e3o do DF, o governador Ibaneis Rocha ressaltou que os \u201cequipamentos s\u00e3o necess\u00e1rios n\u00e3o s\u00f3 no tratamento do coronav\u00edrus, mas que depois ser\u00e3o \u00fateis para atender a popula\u00e7\u00e3o do DF em outros tratamentos\u201d.<\/p>\n<p>O subsecret\u00e1rio de Infraestrutura, Isaque Costa de Albuquerque, tamb\u00e9m enalteceu a iniciativa. \u201cGostaria de fazer um agradecimento especial ao presidente da Codese, Paulo Muniz, ao superintendente Ruiter Thuin e \u00e0 secret\u00e1ria executiva Rosane, pelo esfor\u00e7o em juntar empresas para efetivar essa doa\u00e7\u00e3o de cinco ventiladores pulmonar\u201d, diz<\/p>\n<p>A maioria dos aparelhos foi instalada no Hospital Regional da Asa Norte, unidade refer\u00eancia para tratamento de pacientes com coronav\u00edrus.<\/p>\n<figure id=\"attachment_49098\" aria-describedby=\"caption-attachment-49098\" style=\"width: 960px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-49098 size-full\" src=\"https:\/\/cbic.org.br\/wp-content\/uploads\/2020\/04\/respiradores.jpg\" alt=\"\" \/><figcaption id=\"caption-attachment-49098\" class=\"wp-caption-text\">Foto: Divulga\u00e7\u00e3o Secretaria Nacional de Sa\u00fade do DF<\/figcaption><\/figure>\n<p>Os respiradores s\u00e3o fundamentais no tratamento de pacientes com Covid-19. Sua principal fun\u00e7\u00e3o \u00e9 ajudar os pulm\u00f5es a inspirar e expirar o oxig\u00eanio quando a pessoa perde a capacidade de operar normalmente seu sistema respirat\u00f3rio. Por isso, a eventual falta desses aparelhos nas Unidades de Tratamento Intensivo (UTIs) tem sido a grande preocupa\u00e7\u00e3o das autoridades de sa\u00fade quando aumentar a procura de pacientes por tratamento.<\/p>\n<p>Al\u00e9m dos respiradores, foram viabilizados recursos para a Universidade de Bras\u00edlia (UnB) produzir <strong>mais de 2 mil m\u00e1scaras em acetato<\/strong>. \u201cEstamos ajudando a F\u00e1brica Social a viabilizar a confec\u00e7\u00e3o de m\u00e1scaras e aventais para a Secretaria de Sa\u00fade\u201d, menciona Paulo Muniz.<\/p>\n<p>\u201cA nossa miss\u00e3o como sociedade civil organizada tamb\u00e9m \u00e9 a qualidade de vida e condi\u00e7\u00f5es dignas aos cidad\u00e3os, em gest\u00e3o compartilhada com o poder p\u00fablico. Com mais essa campanha seguimos firmes em nosso prop\u00f3sito de participar ativamente do planejamento econ\u00f4mico sustent\u00e1vel de Bras\u00edlia e entorno, atuando e propondo a\u00e7\u00f5es efetivas da nossa capital federal\u201d, destaca Muniz.<\/p>\n<p>A campanha <a href=\"http:\/\/www.juntospelodf.com.br\">#JuntospeloDF<\/a> continua. Doa\u00e7\u00f5es podem ser feitas pelo <a href=\"http:\/\/www.juntospelodf.com.br\">site<\/a>. Participe!<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Codese-DF<\/strong><\/h2>\n<p>Fruto do projeto <strong>\u2018O Futuro da Minha Cidade\u2019<\/strong>, da C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC), inspirado no modelo bem sucedido da cidade de Maring\u00e1\/PR, o <a href=\"http:\/\/codesedf.org.br\/\">Codese-DF<\/a> foi criado com a participa\u00e7\u00e3o de mais de 50 entidades. Suas atribui\u00e7\u00f5es s\u00e3o exercidas em parceria com entidades do setor produtivo, sociedade civil e academia. \u00a0Seu objetivo central \u00e9 participar ativamente do planejamento econ\u00f4mico sustent\u00e1vel de Bras\u00edlia e entorno, a curto, m\u00e9dio e longo prazo.<\/p>\n<p>A iniciativa integra o <strong>Mapeamento de Boas Pr\u00e1ticas em Responsabilidade Social<\/strong> no setor da constru\u00e7\u00e3o durante a pandemia do coronav\u00edrus e \u00e9 parte integrante do <strong>\u2018Projeto Responsabilidade Social e a Valoriza\u00e7\u00e3o do Trabalhador\u2019<\/strong>, realizado pela C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC), em correaliza\u00e7\u00e3o com Servi\u00e7o Social a Ind\u00fastria (Sesi Nacional).<\/p>\n<p><em>(Com informa\u00e7\u00f5es da Ag\u00eancia Bras\u00edlia)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8230;<\/p>\n","protected":false},"author":10,"featured_media":4377,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[97,183,175],"tags":[184,294,174],"class_list":["post-4420","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-cbic","category-responsabilidade-social-agencia-cbic","category-sustentabilidade-agencia-cbic","tag-codese-df","tag-covid-19","tag-o-futuro-da-minha-cidade"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Covid-19: Codese-DF doa cinco respiradores ao Governo do DF \u00a0 - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2020\/04\/16\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Covid-19: Codese-DF doa cinco respiradores ao Governo do DF \u00a0 - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2020\/04\/16\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-16T21:31:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-20T01:01:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/04\/WhatsApp-Image-2020-04-16-at-11.59.47-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sandra Bezerra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sandra Bezerra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2020\\\/04\\\/16\\\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2020\\\/04\\\/16\\\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\\\/\"},\"author\":{\"name\":\"Sandra Bezerra\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\"},\"headline\":\"Covid-19: Codese-DF doa cinco respiradores ao Governo do DF \u00a0\",\"datePublished\":\"2020-04-16T21:31:09+00:00\",\"dateModified\":\"2020-05-20T01:01:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2020\\\/04\\\/16\\\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\\\/\"},\"wordCount\":603,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2020\\\/04\\\/16\\\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2020\\\/04\\\/WhatsApp-Image-2020-04-16-at-11.59.47-1.jpeg\",\"keywords\":[\"Codese-DF\",\"Covid-19\",\"O Futuro da Minha Cidade\"],\"articleSection\":[\"Ag\u00eancia CBIC\",\"Responsabilidade Social\",\"Sustentabilidade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2020\\\/04\\\/16\\\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2020\\\/04\\\/16\\\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2020\\\/04\\\/16\\\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\\\/\",\"name\":\"Covid-19: Codese-DF doa cinco respiradores ao Governo do DF \u00a0 - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2020\\\/04\\\/16\\\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2020\\\/04\\\/16\\\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2020\\\/04\\\/WhatsApp-Image-2020-04-16-at-11.59.47-1.jpeg\",\"datePublished\":\"2020-04-16T21:31:09+00:00\",\"dateModified\":\"2020-05-20T01:01:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2020\\\/04\\\/16\\\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2020\\\/04\\\/16\\\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2020\\\/04\\\/16\\\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2020\\\/04\\\/WhatsApp-Image-2020-04-16-at-11.59.47-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2020\\\/04\\\/WhatsApp-Image-2020-04-16-at-11.59.47-1.jpeg\",\"caption\":\"Da esquerda para a direita: presidente Paulo Muniz (Codese-DF); governador Ibaneis Rocha; secret\u00e1rio de Sa\u00fade Francisco Araujo e secret\u00e1rio da Casa Civil Valdet\u00e1rio Andrade Monteiro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2020\\\/04\\\/16\\\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Covid-19: Codese-DF doa cinco respiradores ao Governo do DF \u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\",\"name\":\"Sandra Bezerra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"caption\":\"Sandra Bezerra\"},\"sameAs\":[\"https:\\\/\\\/cbic.org.br\"],\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/sandra-bezerra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Covid-19: Codese-DF doa cinco respiradores ao Governo do DF \u00a0 - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2020\/04\/16\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Covid-19: Codese-DF doa cinco respiradores ao Governo do DF \u00a0 - Comiss\u00e3o de Meio Ambiente","og_description":"...","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2020\/04\/16\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2020-04-16T21:31:09+00:00","article_modified_time":"2020-05-20T01:01:11+00:00","og_image":[{"url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/04\/WhatsApp-Image-2020-04-16-at-11.59.47-1.jpeg","width":1,"height":1,"type":"image\/jpeg"}],"author":"Sandra Bezerra","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sandra Bezerra","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2020\/04\/16\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2020\/04\/16\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\/"},"author":{"name":"Sandra Bezerra","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e"},"headline":"Covid-19: Codese-DF doa cinco respiradores ao Governo do DF \u00a0","datePublished":"2020-04-16T21:31:09+00:00","dateModified":"2020-05-20T01:01:11+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2020\/04\/16\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\/"},"wordCount":603,"commentCount":0,"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2020\/04\/16\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/04\/WhatsApp-Image-2020-04-16-at-11.59.47-1.jpeg","keywords":["Codese-DF","Covid-19","O Futuro da Minha Cidade"],"articleSection":["Ag\u00eancia CBIC","Responsabilidade Social","Sustentabilidade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2020\/04\/16\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2020\/04\/16\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2020\/04\/16\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\/","name":"Covid-19: Codese-DF doa cinco respiradores ao Governo do DF \u00a0 - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2020\/04\/16\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2020\/04\/16\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/04\/WhatsApp-Image-2020-04-16-at-11.59.47-1.jpeg","datePublished":"2020-04-16T21:31:09+00:00","dateModified":"2020-05-20T01:01:11+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2020\/04\/16\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2020\/04\/16\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2020\/04\/16\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\/#primaryimage","url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/04\/WhatsApp-Image-2020-04-16-at-11.59.47-1.jpeg","contentUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/04\/WhatsApp-Image-2020-04-16-at-11.59.47-1.jpeg","caption":"Da esquerda para a direita: presidente Paulo Muniz (Codese-DF); governador Ibaneis Rocha; secret\u00e1rio de Sa\u00fade Francisco Araujo e secret\u00e1rio da Casa Civil Valdet\u00e1rio Andrade Monteiro"},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2020\/04\/16\/covid-19-codese-df-doa-cinco-respiradores-ao-governo-do-df-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"Covid-19: Codese-DF doa cinco respiradores ao Governo do DF \u00a0"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e","name":"Sandra Bezerra","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","caption":"Sandra Bezerra"},"sameAs":["https:\/\/cbic.org.br"],"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/sandra-bezerra\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/4420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=4420"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/4420\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media\/4377"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=4420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=4420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=4420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}