{"id":4137,"date":"2020-01-24T18:39:20","date_gmt":"2020-01-24T21:39:20","guid":{"rendered":"https:\/\/cbic.org.br\/sustentabilidade\/2020\/01\/24\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\/"},"modified":"2020-01-24T18:39:20","modified_gmt":"2020-01-24T21:39:20","slug":"codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2020\/01\/24\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\/","title":{"rendered":"Codese diminuir\u00e1 depend\u00eancia econ\u00f4mica da Zona Franca de Manaus"},"content":{"rendered":"<p>Em que dire\u00e7\u00e3o Manaus deve navegar nos pr\u00f3ximos quatro anos? Foi para come\u00e7ar a responder essa pergunta que o Conselho Econ\u00f4mico de Desenvolvimento Econ\u00f4mico, Sustent\u00e1vel e Estrat\u00e9gico de Manaus (Codese) realizou ontem e hoje (23 e 24), na Zona Centro-Sul da capital, \u00a0o workshop <strong>\u2018Uma Nova Manaus\u2019<\/strong>. O evento serviu como pontap\u00e9 inicial para a elabora\u00e7\u00e3o da \u2018Carta de Navega\u00e7\u00e3o 2021-2024\u2019.<\/p>\n<p>A proposta colaborativa visa a implementa\u00e7\u00e3o de pol\u00edticas p\u00fablicas na cidade de Manaus nos pr\u00f3ximos quatro anos.<\/p>\n<p>Tr\u00eas metas fundamentais compor\u00e3o o documento. S\u00e3o elas:<\/p>\n<ul>\n<li>Implantar e consolidar novas matrizes econ\u00f4micas a partir de produtos essencialmente regionais que respondam por pelo menos por dois ter\u00e7os do Produto Interno Bruto (PIB) da capital<\/li>\n<li>Situar a cidade entre as 10 melhores do Brasil para se viver<\/li>\n<li>Colocar Manaus entre as 20 melhores cidades para se fazer neg\u00f3cios no pa\u00eds<\/li>\n<\/ul>\n<p>A carta, que ser\u00e1 elaborada em conjunto com diversos atores e segmentos da sociedade manauara e deve ser conclu\u00edda at\u00e9 julho deste ano, ser\u00e1 encaminhada aos candidatos a prefeito de Manaus no pleito de 2020.<\/p>\n<p>\u201cO Codese \u00e9 o bra\u00e7o executivo desse projeto. Mas quem deve dizer para onde a cidade deve caminhar \u00e9 a sociedade civil organizada. Nesse sentido, o Codese se prontifica a ser esse porta-voz, esse aglutinador das ideias, dos pensamentos e das solu\u00e7\u00f5es para os problemas da cidade\u201d, afirma o presidente do Codese Manaus, Romero Reis.<\/p>\n<p>Nesta semana, o grupo de trabalho que deve dirigir os trabalhos e \u00e9 formado por profissionais de diversas \u00e1reas, com Infraestrutura, Planejamento Urbano e Tecnologia, j\u00e1 realizou visitas a Universidade Federal do Amazonas (Ufam), Universidade do Estado do Amazonas (UEA), Instituto Federal de Educa\u00e7\u00e3o, Ci\u00eancia e Tecnologia (Ifam) e ao Servi\u00e7o Brasileiro de Apoio \u00e0s Micro e Pequenas Empresas (Sebrae).<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Para al\u00e9m da Zona Franca<\/strong><\/h2>\n<p>Sobre as metas propostas, Romero Reis ressalta que, a despeito da necessidade de apoiar e fortalecer o modelo j\u00e1 estabelecido da Zona Franca de Manaus, \u00e9 imprescind\u00edvel diversificar a matriz econ\u00f4mica da capital, cujas voca\u00e7\u00f5es v\u00e3o desde o turismo at\u00e9 a biotecnologia, com potencial de se tornar um polo digital na regi\u00e3o.<\/p>\n<p>\u201cA curto e m\u00e9dio prazo, a Zona Franca \u00e9 um modelo que deve ser apoiado e desenvolvido, mas, em raz\u00e3o dos riscos que o modelo tem hoje, precisamos consolidar matrizes econ\u00f4micas capazes de gerar emprego e renda at\u00e9 numa propor\u00e7\u00e3o maior do que foi a Zona Franca nos \u00faltimos anos\u201d, diz ele.<\/p>\n<p>\u201cSe o Distrito (Industrial de Manaus) possui at\u00e9 100 bilh\u00f5es de faturamento por ano, queremos chegar a 200 bilh\u00f5es com piscicultura, turismo, minera\u00e7\u00e3o, biotecnologia, polo digital\u201d, diz ele, em alus\u00e3o \u00e0 primeira das tr\u00eas metas propostas no documento.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Metodologia \u00e9 diferencial<\/strong><\/h2>\n<p>Consultora respons\u00e1vel pela condu\u00e7\u00e3o do processo de constru\u00e7\u00e3o conjunta da proposta para a cidade de Manaus no pr\u00f3ximo quadri\u00eanio, a arquiteta e urbanista Silmara Silveira explica que a metodologia foi desenvolvida com em sua experi\u00eancia de mais de 20 anos de gest\u00e3o p\u00fablica, nas esferas municipal, estadual e federal. No entanto, o ponto de partida \u00e9 sempre o territ\u00f3rio do munic\u00edpio, que ela sublinha como sendo o espa\u00e7o onde a pol\u00edtica p\u00fablica de fato acontece.<\/p>\n<p>\u201cO territ\u00f3rio da cidade \u00e9 muito diverso. Tem brancos, negros, pardos, mulheres, jovens, velhos, trabalhadores, desempregados. Ent\u00e3o, nosso objetivo \u00e9 estabelecer uma metodologia que consiga articular o que \u00e9 convergente em toda essa diversidade, possibilitando diferentes personagens, atores e entidades a desenvolver um pensamento, um diagn\u00f3stico, que possa ser implementado de forma articulada e integrada\u201d, explicou Silmara.<\/p>\n<p>\u201c\u00c9 preciso lembra que as pessoas n\u00e3o moram no pa\u00eds, elas moram na cidade. E saber valorizar sua cidade \u00e9 fundamental para ter uma qualidade de vida adequada, que afinal \u00e9 o que felicidade para as pessoas\u201d, diz.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Codese Manaus<\/strong><\/h2>\n<p>O Codese Manaus \u00e9 uma associa\u00e7\u00e3o de direito privado, sem fins lucrativos, sem v\u00ednculo pol\u00edtico-partid\u00e1rio ou religioso, formada pela sociedade civil organizada, por interm\u00e9dio de entidades representantes e representativas de segmentos capazes de contribuir para o planejamento e busca de solu\u00e7\u00f5es para o futuro da cidade de Manaus.<\/p>\n<p>Tem como objetivo possibilitar \u00e0 sociedade ser protagonista do futuro da cidade, elaborando e atualizando, de forma cont\u00ednua e participativa, planos, estudos, projetos e iniciativas decorrentes de tais prop\u00f3sitos.<\/p>\n<p>Criado em 2015, o Codese \u00e9 fruto do projeto <strong><em>\u2018O Futuro da Minha Cidade\u2019<\/em><\/strong> da Comiss\u00e3o de Meio Ambiente (CMA) da C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC), em correaliza\u00e7\u00e3o com o Servi\u00e7o Social da Ind\u00fastria (Sesi Nacional) e patroc\u00ednio da Caixa Econ\u00f4mica Federal.<\/p>\n<p>Institu\u00eddo em 2012, \u2018O Futuro da Minha Cidade\u2019 visa desenvolver e fortalecer o protagonismo na sociedade civil organizada para pensar e atuar no planejamento de um futuro de pelo menos 20 anos para as cidades, de forma apartid\u00e1ria, superando as gest\u00f5es p\u00fablicas.<\/p>\n<p>O projeto surgiu da experi\u00eancia bem sucedida da cidade de Maring\u00e1-PR, por meio do seu Conselho de Desenvolvimento Econ\u00f4mico (Codem\/Codese), que possui um car\u00e1ter deliberativo e consultivo e tem como finalidade propor e fazer executar pol\u00edtica de desenvolvimento econ\u00f4mico, social e planejamento urbano e tem como caracter\u00edsticas a participa\u00e7\u00e3o volunt\u00e1ria, vis\u00e3o de futuro e planejamento, suporte t\u00e9cnico profissional, representatividade pol\u00edtica apartid\u00e1ria, foco no desenvolvimento econ\u00f4mico e representatividade da sociedade organizada.<\/p>\n<p>&nbsp;<\/p>\n<p><em>(Com informa\u00e7\u00f5es do Codese Manaus)<\/em><\/p>\n<p><em>(Foto: Divulga\u00e7\u00e3o Codese Manaus)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em que dire\u00e7\u00e3o Manaus deve navegar nos pr\u00f3ximos quatro anos? Foi para come\u00e7ar a responder essa pergunta que o Conselho Econ\u00f4mico de Desenvolvimento Econ\u00f4mico, Sustent\u00e1vel e Estrat\u00e9gico de Manaus (Codese) realizou ontem e hoje (23 e 24), na Zona Centr&#8230;<\/p>\n","protected":false},"author":10,"featured_media":4134,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[97,175],"tags":[174],"class_list":["post-4137","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-cbic","category-sustentabilidade-agencia-cbic","tag-o-futuro-da-minha-cidade"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Codese diminuir\u00e1 depend\u00eancia econ\u00f4mica da Zona Franca de Manaus - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/01\/24\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Codese diminuir\u00e1 depend\u00eancia econ\u00f4mica da Zona Franca de Manaus - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"Em que dire\u00e7\u00e3o Manaus deve navegar nos pr\u00f3ximos quatro anos? Foi para come\u00e7ar a responder essa pergunta que o Conselho Econ\u00f4mico de Desenvolvimento Econ\u00f4mico, Sustent\u00e1vel e Estrat\u00e9gico de Manaus (Codese) realizou ontem e hoje (23 e 24), na Zona Centr...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/01\/24\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-24T21:39:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/01\/WhatsApp-Image-2020-01-24-at-15.21.42-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sandra Bezerra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sandra Bezerra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/01\\\/24\\\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/01\\\/24\\\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\\\/\"},\"author\":{\"name\":\"Sandra Bezerra\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\"},\"headline\":\"Codese diminuir\u00e1 depend\u00eancia econ\u00f4mica da Zona Franca de Manaus\",\"datePublished\":\"2020-01-24T21:39:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/01\\\/24\\\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\\\/\"},\"wordCount\":936,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/01\\\/24\\\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2020\\\/01\\\/WhatsApp-Image-2020-01-24-at-15.21.42-1.jpeg\",\"keywords\":[\"O Futuro da Minha Cidade\"],\"articleSection\":[\"Ag\u00eancia CBIC\",\"Sustentabilidade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/01\\\/24\\\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/01\\\/24\\\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/01\\\/24\\\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\\\/\",\"name\":\"Codese diminuir\u00e1 depend\u00eancia econ\u00f4mica da Zona Franca de Manaus - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/01\\\/24\\\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/01\\\/24\\\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2020\\\/01\\\/WhatsApp-Image-2020-01-24-at-15.21.42-1.jpeg\",\"datePublished\":\"2020-01-24T21:39:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/01\\\/24\\\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/01\\\/24\\\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/01\\\/24\\\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2020\\\/01\\\/WhatsApp-Image-2020-01-24-at-15.21.42-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2020\\\/01\\\/WhatsApp-Image-2020-01-24-at-15.21.42-1.jpeg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2020\\\/01\\\/24\\\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Codese diminuir\u00e1 depend\u00eancia econ\u00f4mica da Zona Franca de Manaus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\",\"name\":\"Sandra Bezerra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"caption\":\"Sandra Bezerra\"},\"sameAs\":[\"https:\\\/\\\/cbic.org.br\"],\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/sandra-bezerra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Codese diminuir\u00e1 depend\u00eancia econ\u00f4mica da Zona Franca de Manaus - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/01\/24\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Codese diminuir\u00e1 depend\u00eancia econ\u00f4mica da Zona Franca de Manaus - Comiss\u00e3o de Meio Ambiente","og_description":"Em que dire\u00e7\u00e3o Manaus deve navegar nos pr\u00f3ximos quatro anos? Foi para come\u00e7ar a responder essa pergunta que o Conselho Econ\u00f4mico de Desenvolvimento Econ\u00f4mico, Sustent\u00e1vel e Estrat\u00e9gico de Manaus (Codese) realizou ontem e hoje (23 e 24), na Zona Centr...","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/01\/24\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2020-01-24T21:39:20+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/01\/WhatsApp-Image-2020-01-24-at-15.21.42-1.jpeg","type":"image\/jpeg"}],"author":"Sandra Bezerra","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sandra Bezerra","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/01\/24\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/01\/24\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\/"},"author":{"name":"Sandra Bezerra","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e"},"headline":"Codese diminuir\u00e1 depend\u00eancia econ\u00f4mica da Zona Franca de Manaus","datePublished":"2020-01-24T21:39:20+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/01\/24\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\/"},"wordCount":936,"commentCount":0,"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/01\/24\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/01\/WhatsApp-Image-2020-01-24-at-15.21.42-1.jpeg","keywords":["O Futuro da Minha Cidade"],"articleSection":["Ag\u00eancia CBIC","Sustentabilidade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/01\/24\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/01\/24\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/01\/24\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\/","name":"Codese diminuir\u00e1 depend\u00eancia econ\u00f4mica da Zona Franca de Manaus - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/01\/24\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/01\/24\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/01\/WhatsApp-Image-2020-01-24-at-15.21.42-1.jpeg","datePublished":"2020-01-24T21:39:20+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/01\/24\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/01\/24\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/01\/24\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\/#primaryimage","url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/01\/WhatsApp-Image-2020-01-24-at-15.21.42-1.jpeg","contentUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2020\/01\/WhatsApp-Image-2020-01-24-at-15.21.42-1.jpeg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2020\/01\/24\/codese-diminuira-dependencia-economica-da-zona-franca-de-manaus-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"Codese diminuir\u00e1 depend\u00eancia econ\u00f4mica da Zona Franca de Manaus"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e","name":"Sandra Bezerra","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","caption":"Sandra Bezerra"},"sameAs":["https:\/\/cbic.org.br"],"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/sandra-bezerra\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/4137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=4137"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/4137\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media\/4134"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=4137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=4137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=4137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}