{"id":3905,"date":"2019-11-22T17:13:16","date_gmt":"2019-11-22T20:13:16","guid":{"rendered":"https:\/\/cbic.org.br\/sustentabilidade\/2019\/11\/22\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\/"},"modified":"2019-11-22T17:13:16","modified_gmt":"2019-11-22T20:13:16","slug":"cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2019\/11\/22\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\/","title":{"rendered":"Presidente da CBIC analisa cen\u00e1rio e pautas que impactar\u00e3o o setor no Matx Podcast"},"content":{"rendered":"<p>Em entrevista a Felipe Cavalcante, para o Epis\u00f3dio Especial do <a href=\"https:\/\/www.matx.com.br\/podcast\/episode\/f1ead56b\/jose-carlos-martins-presidente-da-cbic-fala-sobre-as-principais-tendencias-e-assuntos-de-interesse-dos-setores-imobiliario-e-de-construcao\">Matx Podcast<\/a> do dia 21 de novembro, o presidente da C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC), Jos\u00e9 Carlos Martins, aborda os desafios de liderar um segmento t\u00e3o relevante como o da constru\u00e7\u00e3o civil e analisa o cen\u00e1rio e as pautas que impactar\u00e3o a ind\u00fastria da constru\u00e7\u00e3o nesse momento de tantas mudan\u00e7as no Pa\u00eds.<\/p>\n<p><strong>\u201cUma verdadeira aula sobre os bastidores do setor e do que devemos esperar nos pr\u00f3ximos anos\u201d<\/strong>, destaca Felipe Cavalcante, que tamb\u00e9m \u00e9 presidente de honra da Associa\u00e7\u00e3o para o Desenvolvimento Imobili\u00e1rio e Tur\u00edstico do Brasil (ADIT Brasil).<\/p>\n<p>As <strong>perspectivas para o Fundo de Garantia do Tempo de Servi\u00e7o (FGTS) e as novas tend\u00eancias para o funding no setor, com a queda da taxa de juros<\/strong>, s\u00e3o alguns dos assuntos tratados por Martins em seu primeiro podcast, que tamb\u00e9m aborda quest\u00f5es como:<\/p>\n<ul>\n<li>A \u00e9tica no setor da constru\u00e7\u00e3o e como a CBIC lida com a imagem p\u00fablica desse mercado<\/li>\n<li>Reforma tribut\u00e1ria e o setor de habita\u00e7\u00e3o social<\/li>\n<li>Nova Lei de Licita\u00e7\u00f5es<\/li>\n<li>Contrata\u00e7\u00e3o de obras sem recursos para termin\u00e1-las<\/li>\n<li>Nova Lei Geral de Licenciamento Ambiental<\/li>\n<li>Lei de Abuso de Autoridade<\/li>\n<li>Li\u00e7\u00f5es aprendidas com a crise e o que deve ser evitado nesse novo ciclo<\/li>\n<li>O futuro dos sindicatos e entidades de classes<\/li>\n<li>A quest\u00e3o dos cart\u00f3rios<\/li>\n<\/ul>\n<p>O <em>podcast<\/em> \u00e9 uma parceria entre a Matx Academy e a ADIT Brasil, entidade representativa dos setores de investimentos imobili\u00e1rios, multipropriedade e timeshare, loteamentos e comunidades planejadas, direito imobili\u00e1rio e investimentos hoteleiros.<\/p>\n<p>Confira a \u00edntegra da entrevista, no <a href=\"https:\/\/www.matx.com.br\/podcast\/episode\/f1ead56b\/jose-carlos-martins-presidente-da-cbic-fala-sobre-as-principais-tendencias-e-assuntos-de-interesse-dos-setores-imobiliario-e-de-construcao\">Matx Podcast<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em entrevista a Felipe Cavalcante, para o Epis\u00f3dio Especial do &lt;a href=&quot;https:\/\/www.matx.com.br\/podcast\/episode\/f1ead56b\/jose-carlos-martins-presidente-da-cbic-fala-sobre-as-principais-tendencias-e-assuntos-de-interesse-dos-setores-imobiliario-e-de-c&#8230;<\/p>\n","protected":false},"author":10,"featured_media":3897,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[97,228,248,226,249,246,183,175],"tags":[247],"class_list":["post-3905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-cbic","category-industria-imobiliaria-agencia-cbic","category-infraestrutura-agencia-cbic","category-inovacao-agencia-cbic","category-juridico-agencia-cbic","category-politicas-trabalhistas-agencia-cbic","category-responsabilidade-social-agencia-cbic","category-sustentabilidade-agencia-cbic","tag-podcast"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presidente da CBIC analisa cen\u00e1rio e pautas que impactar\u00e3o o setor no Matx Podcast - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/11\/22\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presidente da CBIC analisa cen\u00e1rio e pautas que impactar\u00e3o o setor no Matx Podcast - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"Em entrevista a Felipe Cavalcante, para o Epis\u00f3dio Especial do &lt;a href=&quot;https:\/\/www.matx.com.br\/podcast\/episode\/f1ead56b\/jose-carlos-martins-presidente-da-cbic-fala-sobre-as-principais-tendencias-e-assuntos-de-interesse-dos-setores-imobiliario-e-de-c...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/11\/22\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-22T20:13:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/11\/WhatsApp-Image-2019-11-22-at-16.59.21.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"738\" \/>\n\t<meta property=\"og:image:height\" content=\"748\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sandra Bezerra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sandra Bezerra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/11\\\/22\\\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/11\\\/22\\\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\\\/\"},\"author\":{\"name\":\"Sandra Bezerra\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\"},\"headline\":\"Presidente da CBIC analisa cen\u00e1rio e pautas que impactar\u00e3o o setor no Matx Podcast\",\"datePublished\":\"2019-11-22T20:13:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/11\\\/22\\\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\\\/\"},\"wordCount\":305,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/11\\\/22\\\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/11\\\/WhatsApp-Image-2019-11-22-at-16.59.21.jpeg\",\"keywords\":[\"Podcast\"],\"articleSection\":[\"Ag\u00eancia CBIC\",\"Ind\u00fastria Imobili\u00e1ria\",\"Infraestrutura\",\"Inova\u00e7\u00e3o\",\"Jur\u00eddico\",\"Pol\u00edticas Trabalhistas\",\"Responsabilidade Social\",\"Sustentabilidade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/11\\\/22\\\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/11\\\/22\\\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/11\\\/22\\\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\\\/\",\"name\":\"Presidente da CBIC analisa cen\u00e1rio e pautas que impactar\u00e3o o setor no Matx Podcast - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/11\\\/22\\\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/11\\\/22\\\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/11\\\/WhatsApp-Image-2019-11-22-at-16.59.21.jpeg\",\"datePublished\":\"2019-11-22T20:13:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/11\\\/22\\\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/11\\\/22\\\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/11\\\/22\\\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/11\\\/WhatsApp-Image-2019-11-22-at-16.59.21.jpeg\",\"contentUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/11\\\/WhatsApp-Image-2019-11-22-at-16.59.21.jpeg\",\"width\":738,\"height\":748},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/11\\\/22\\\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presidente da CBIC analisa cen\u00e1rio e pautas que impactar\u00e3o o setor no Matx Podcast\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\",\"name\":\"Sandra Bezerra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"caption\":\"Sandra Bezerra\"},\"sameAs\":[\"https:\\\/\\\/cbic.org.br\"],\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/sandra-bezerra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presidente da CBIC analisa cen\u00e1rio e pautas que impactar\u00e3o o setor no Matx Podcast - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/11\/22\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Presidente da CBIC analisa cen\u00e1rio e pautas que impactar\u00e3o o setor no Matx Podcast - Comiss\u00e3o de Meio Ambiente","og_description":"Em entrevista a Felipe Cavalcante, para o Epis\u00f3dio Especial do &lt;a href=&quot;https:\/\/www.matx.com.br\/podcast\/episode\/f1ead56b\/jose-carlos-martins-presidente-da-cbic-fala-sobre-as-principais-tendencias-e-assuntos-de-interesse-dos-setores-imobiliario-e-de-c...","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/11\/22\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2019-11-22T20:13:16+00:00","og_image":[{"width":738,"height":748,"url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/11\/WhatsApp-Image-2019-11-22-at-16.59.21.jpeg","type":"image\/jpeg"}],"author":"Sandra Bezerra","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sandra Bezerra","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/11\/22\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/11\/22\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\/"},"author":{"name":"Sandra Bezerra","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e"},"headline":"Presidente da CBIC analisa cen\u00e1rio e pautas que impactar\u00e3o o setor no Matx Podcast","datePublished":"2019-11-22T20:13:16+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/11\/22\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\/"},"wordCount":305,"commentCount":0,"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/11\/22\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/11\/WhatsApp-Image-2019-11-22-at-16.59.21.jpeg","keywords":["Podcast"],"articleSection":["Ag\u00eancia CBIC","Ind\u00fastria Imobili\u00e1ria","Infraestrutura","Inova\u00e7\u00e3o","Jur\u00eddico","Pol\u00edticas Trabalhistas","Responsabilidade Social","Sustentabilidade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/11\/22\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/11\/22\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/11\/22\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\/","name":"Presidente da CBIC analisa cen\u00e1rio e pautas que impactar\u00e3o o setor no Matx Podcast - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/11\/22\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/11\/22\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/11\/WhatsApp-Image-2019-11-22-at-16.59.21.jpeg","datePublished":"2019-11-22T20:13:16+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/11\/22\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/11\/22\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/11\/22\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\/#primaryimage","url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/11\/WhatsApp-Image-2019-11-22-at-16.59.21.jpeg","contentUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/11\/WhatsApp-Image-2019-11-22-at-16.59.21.jpeg","width":738,"height":748},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/11\/22\/cbic-analisa-cenario-e-pautas-que-impactarao-o-setor-no-matx-podcast-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"Presidente da CBIC analisa cen\u00e1rio e pautas que impactar\u00e3o o setor no Matx Podcast"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e","name":"Sandra Bezerra","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","caption":"Sandra Bezerra"},"sameAs":["https:\/\/cbic.org.br"],"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/sandra-bezerra\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/3905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=3905"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/3905\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media\/3897"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=3905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=3905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=3905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}