{"id":3505,"date":"2019-08-21T18:12:38","date_gmt":"2019-08-21T21:12:38","guid":{"rendered":"https:\/\/cbic.org.br\/sustentabilidade\/2019\/08\/21\/cbic-participa-de-semana-do-clima-em-salvador-2\/"},"modified":"2019-08-21T18:12:38","modified_gmt":"2019-08-21T21:12:38","slug":"cbic-participa-de-semana-do-clima-em-salvador-2","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2019\/08\/21\/cbic-participa-de-semana-do-clima-em-salvador-2\/","title":{"rendered":"CBIC participa de \u2018Semana do clima\u2019 em Salvador"},"content":{"rendered":"<p style=\"text-align: justify\">Com o objetivo de dialogar e buscar solu\u00e7\u00f5es para enfrentar os desafios relacionados com as pol\u00edticas de desenvolvimento de baixas emiss\u00f5es de gases, teve in\u00edcio na \u00faltima segunda-feira, 19, em Salvador, a Semana Latino-Americana e Caribenha sobre Mudan\u00e7a do Clima. O evento, que segue at\u00e9 sexta-feira (23), conta com a participa\u00e7\u00e3o do vice-presidente da \u00e1rea de Meio Ambiente da C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC), Nilson Sarti.<\/p>\n<p style=\"text-align: justify\">Segundo Sarti, cientistas, dirigentes pol\u00edticos, entidades governamentais e n\u00e3o governamentais est\u00e3o reunidos para debater medidas ambientais frente \u00e0s mudan\u00e7as clim\u00e1ticas. Ele explica um dos temas mais importantes da semana \u00e9 a discuss\u00e3o da redu\u00e7\u00e3o da emiss\u00e3o de gases do efeito estufa e a resili\u00eancia urbana com adapta\u00e7\u00e3o \u00e0s mudan\u00e7as clim\u00e1ticas.<\/p>\n<p style=\"text-align: justify\">Na manh\u00e3 desta quarta-feira (21), Nilson Sarti assistiu ao painel \u2018Caminhos para o baixo carbono e futuro resiliente na Am\u00e9rica latina e \u00e1reas urbanas e assentamentos do Caribe\u2019, que abordou uma estrat\u00e9gia de transi\u00e7\u00e3o para a cidade de baixo carbono, economia urbana verde e inclusiva, pois 60% da \u00e1rea a ser urbanizada at\u00e9 2030 ainda n\u00e3o foi constru\u00edda. \u201cAs cidades est\u00e3o ficando cada vez mais inteligentes, preocupadas com o meio ambiente e comprometidas com as metas de sustentabilidade\u201d, explicou Sarti.<\/p>\n<p style=\"text-align: justify\">Estar \u00e0 par das inova\u00e7\u00f5es na \u00e1rea \u00e9 essencial para o setor, em um mundo que est\u00e1 cada vez mais demandando solu\u00e7\u00f5es sustent\u00e1veis. \u201cO planejamento urbano moderno deve incluir um enfoque abrangente e preventivo da gest\u00e3o de riscos. As condi\u00e7\u00f5es clim\u00e1ticas, efici\u00eancia energ\u00e9tica e reuso da \u00e1gua das edifica\u00e7\u00f5es s\u00e3o alguns pontos que n\u00e3o podem mais ser ignorados\u201d, enfatizou.<\/p>\n<p style=\"text-align: justify\">Os resultados da Semana do Clima ser\u00e3o levados para discuss\u00f5es da C\u00fapula de A\u00e7\u00e3o Clim\u00e1tica da ONU, que ser\u00e1 realizada em 23 de setembro, em Nova York, bem como a COP-25, marcada para os dias 2 a 13 de dezembro, no Chile.<\/p>\n<p style=\"text-align: justify\">Os dois eventos t\u00eam como objetivo impulsionar a ambi\u00e7\u00e3o clim\u00e1tica mundial a fim de acelerar a implementa\u00e7\u00e3o do Acordo de Paris e a Agenda 2030 para o desenvolvimento sustent\u00e1vel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com o objetivo de dialogar e buscar solu\u00e7\u00f5es para enfrentar os desafios relacionados com as pol\u00edticas de desenvolvimento de baixas emiss\u00f5es de gases, teve in\u00edcio na \u00faltima segunda-feira, 19, em Salvador, a Semana Latino-Americana e Caribenha sobre Mudan\u00e7a do Clima. O evento, que segue at\u00e9 [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3504,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[97,5,175],"tags":[],"class_list":["post-3505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-cbic","category-imprensa","category-sustentabilidade-agencia-cbic"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CBIC participa de \u2018Semana do clima\u2019 em Salvador - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/08\/21\/cbic-participa-de-semana-do-clima-em-salvador-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CBIC participa de \u2018Semana do clima\u2019 em Salvador - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"Com o objetivo de dialogar e buscar solu\u00e7\u00f5es para enfrentar os desafios relacionados com as pol\u00edticas de desenvolvimento de baixas emiss\u00f5es de gases, teve in\u00edcio na \u00faltima segunda-feira, 19, em Salvador, a Semana Latino-Americana e Caribenha sobre Mudan\u00e7a do Clima. O evento, que segue at\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/08\/21\/cbic-participa-de-semana-do-clima-em-salvador-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-21T21:12:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/08\/semana-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"PH Freitas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"PH Freitas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/08\\\/21\\\/cbic-participa-de-semana-do-clima-em-salvador-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/08\\\/21\\\/cbic-participa-de-semana-do-clima-em-salvador-2\\\/\"},\"author\":{\"name\":\"PH Freitas\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/2cae51852e9e895aa18e04d83ad8328e\"},\"headline\":\"CBIC participa de \u2018Semana do clima\u2019 em Salvador\",\"datePublished\":\"2019-08-21T21:12:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/08\\\/21\\\/cbic-participa-de-semana-do-clima-em-salvador-2\\\/\"},\"wordCount\":372,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/08\\\/21\\\/cbic-participa-de-semana-do-clima-em-salvador-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/08\\\/semana-3.jpg\",\"articleSection\":[\"Ag\u00eancia CBIC\",\"Imprensa\",\"Sustentabilidade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/08\\\/21\\\/cbic-participa-de-semana-do-clima-em-salvador-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/08\\\/21\\\/cbic-participa-de-semana-do-clima-em-salvador-2\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/08\\\/21\\\/cbic-participa-de-semana-do-clima-em-salvador-2\\\/\",\"name\":\"CBIC participa de \u2018Semana do clima\u2019 em Salvador - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/08\\\/21\\\/cbic-participa-de-semana-do-clima-em-salvador-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/08\\\/21\\\/cbic-participa-de-semana-do-clima-em-salvador-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/08\\\/semana-3.jpg\",\"datePublished\":\"2019-08-21T21:12:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/2cae51852e9e895aa18e04d83ad8328e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/08\\\/21\\\/cbic-participa-de-semana-do-clima-em-salvador-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/08\\\/21\\\/cbic-participa-de-semana-do-clima-em-salvador-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/08\\\/21\\\/cbic-participa-de-semana-do-clima-em-salvador-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/08\\\/semana-3.jpg\",\"contentUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/08\\\/semana-3.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/08\\\/21\\\/cbic-participa-de-semana-do-clima-em-salvador-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CBIC participa de \u2018Semana do clima\u2019 em Salvador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/2cae51852e9e895aa18e04d83ad8328e\",\"name\":\"PH Freitas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g\",\"caption\":\"PH Freitas\"},\"sameAs\":[\"https:\\\/\\\/cbic.org.br\"],\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/ph-freitas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CBIC participa de \u2018Semana do clima\u2019 em Salvador - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/08\/21\/cbic-participa-de-semana-do-clima-em-salvador-2\/","og_locale":"pt_BR","og_type":"article","og_title":"CBIC participa de \u2018Semana do clima\u2019 em Salvador - Comiss\u00e3o de Meio Ambiente","og_description":"Com o objetivo de dialogar e buscar solu\u00e7\u00f5es para enfrentar os desafios relacionados com as pol\u00edticas de desenvolvimento de baixas emiss\u00f5es de gases, teve in\u00edcio na \u00faltima segunda-feira, 19, em Salvador, a Semana Latino-Americana e Caribenha sobre Mudan\u00e7a do Clima. O evento, que segue at\u00e9 [&hellip;]","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/08\/21\/cbic-participa-de-semana-do-clima-em-salvador-2\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2019-08-21T21:12:38+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/08\/semana-3.jpg","type":"image\/jpeg"}],"author":"PH Freitas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"PH Freitas","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/08\/21\/cbic-participa-de-semana-do-clima-em-salvador-2\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/08\/21\/cbic-participa-de-semana-do-clima-em-salvador-2\/"},"author":{"name":"PH Freitas","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/2cae51852e9e895aa18e04d83ad8328e"},"headline":"CBIC participa de \u2018Semana do clima\u2019 em Salvador","datePublished":"2019-08-21T21:12:38+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/08\/21\/cbic-participa-de-semana-do-clima-em-salvador-2\/"},"wordCount":372,"commentCount":0,"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/08\/21\/cbic-participa-de-semana-do-clima-em-salvador-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/08\/semana-3.jpg","articleSection":["Ag\u00eancia CBIC","Imprensa","Sustentabilidade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/08\/21\/cbic-participa-de-semana-do-clima-em-salvador-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/08\/21\/cbic-participa-de-semana-do-clima-em-salvador-2\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/08\/21\/cbic-participa-de-semana-do-clima-em-salvador-2\/","name":"CBIC participa de \u2018Semana do clima\u2019 em Salvador - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/08\/21\/cbic-participa-de-semana-do-clima-em-salvador-2\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/08\/21\/cbic-participa-de-semana-do-clima-em-salvador-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/08\/semana-3.jpg","datePublished":"2019-08-21T21:12:38+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/2cae51852e9e895aa18e04d83ad8328e"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/08\/21\/cbic-participa-de-semana-do-clima-em-salvador-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/08\/21\/cbic-participa-de-semana-do-clima-em-salvador-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/08\/21\/cbic-participa-de-semana-do-clima-em-salvador-2\/#primaryimage","url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/08\/semana-3.jpg","contentUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/08\/semana-3.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/08\/21\/cbic-participa-de-semana-do-clima-em-salvador-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"CBIC participa de \u2018Semana do clima\u2019 em Salvador"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/2cae51852e9e895aa18e04d83ad8328e","name":"PH Freitas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g","caption":"PH Freitas"},"sameAs":["https:\/\/cbic.org.br"],"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/ph-freitas\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/3505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=3505"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/3505\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media\/3504"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=3505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=3505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=3505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}