{"id":3255,"date":"2019-05-06T14:56:29","date_gmt":"2019-05-06T17:56:29","guid":{"rendered":"https:\/\/cbic.org.br\/sustentabilidade\/?p=3255"},"modified":"2019-05-06T14:56:29","modified_gmt":"2019-05-06T17:56:29","slug":"o-iphan-no-licenciamento-ambiental-parte-2","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2019\/05\/06\/o-iphan-no-licenciamento-ambiental-parte-2\/","title":{"rendered":"O IPHAN no Licenciamento Ambiental (Parte 2)"},"content":{"rendered":"<p><iframe src=\"https:\/\/www.youtube.com\/embed\/Lb2bxyILaZE?start=10&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[2],"tags":[],"class_list":["post-3255","post","type-post","status-publish","format-video","hentry","category-cma-videos","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O IPHAN no Licenciamento Ambiental (Parte 2) - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/05\/06\/o-iphan-no-licenciamento-ambiental-parte-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O IPHAN no Licenciamento Ambiental (Parte 2) - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/05\/06\/o-iphan-no-licenciamento-ambiental-parte-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-06T17:56:29+00:00\" \/>\n<meta name=\"author\" content=\"Bruna vieira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bruna vieira\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2019\\\/05\\\/06\\\/o-iphan-no-licenciamento-ambiental-parte-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2019\\\/05\\\/06\\\/o-iphan-no-licenciamento-ambiental-parte-2\\\/\"},\"author\":{\"name\":\"Bruna vieira\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/47adfbc23fc998584b61d65979bd7e44\"},\"headline\":\"O IPHAN no Licenciamento Ambiental (Parte 2)\",\"datePublished\":\"2019-05-06T17:56:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2019\\\/05\\\/06\\\/o-iphan-no-licenciamento-ambiental-parte-2\\\/\"},\"wordCount\":17,\"commentCount\":0,\"articleSection\":[\"CMA V\u00eddeos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2019\\\/05\\\/06\\\/o-iphan-no-licenciamento-ambiental-parte-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2019\\\/05\\\/06\\\/o-iphan-no-licenciamento-ambiental-parte-2\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2019\\\/05\\\/06\\\/o-iphan-no-licenciamento-ambiental-parte-2\\\/\",\"name\":\"O IPHAN no Licenciamento Ambiental (Parte 2) - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"datePublished\":\"2019-05-06T17:56:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/47adfbc23fc998584b61d65979bd7e44\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2019\\\/05\\\/06\\\/o-iphan-no-licenciamento-ambiental-parte-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2019\\\/05\\\/06\\\/o-iphan-no-licenciamento-ambiental-parte-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2019\\\/05\\\/06\\\/o-iphan-no-licenciamento-ambiental-parte-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O IPHAN no Licenciamento Ambiental (Parte 2)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/47adfbc23fc998584b61d65979bd7e44\",\"name\":\"Bruna vieira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f424a16cc622dfcca495cc34756573f82160959e68c9068f0cbedb5cece8e593?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f424a16cc622dfcca495cc34756573f82160959e68c9068f0cbedb5cece8e593?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f424a16cc622dfcca495cc34756573f82160959e68c9068f0cbedb5cece8e593?s=96&d=mm&r=g\",\"caption\":\"Bruna vieira\"},\"sameAs\":[\"https:\\\/\\\/cbic.org.br\"],\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/caio-bona\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O IPHAN no Licenciamento Ambiental (Parte 2) - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/05\/06\/o-iphan-no-licenciamento-ambiental-parte-2\/","og_locale":"pt_BR","og_type":"article","og_title":"O IPHAN no Licenciamento Ambiental (Parte 2) - Comiss\u00e3o de Meio Ambiente","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/05\/06\/o-iphan-no-licenciamento-ambiental-parte-2\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2019-05-06T17:56:29+00:00","author":"Bruna vieira","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Bruna vieira"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/05\/06\/o-iphan-no-licenciamento-ambiental-parte-2\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/05\/06\/o-iphan-no-licenciamento-ambiental-parte-2\/"},"author":{"name":"Bruna vieira","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/47adfbc23fc998584b61d65979bd7e44"},"headline":"O IPHAN no Licenciamento Ambiental (Parte 2)","datePublished":"2019-05-06T17:56:29+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/05\/06\/o-iphan-no-licenciamento-ambiental-parte-2\/"},"wordCount":17,"commentCount":0,"articleSection":["CMA V\u00eddeos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/05\/06\/o-iphan-no-licenciamento-ambiental-parte-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/05\/06\/o-iphan-no-licenciamento-ambiental-parte-2\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/05\/06\/o-iphan-no-licenciamento-ambiental-parte-2\/","name":"O IPHAN no Licenciamento Ambiental (Parte 2) - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"datePublished":"2019-05-06T17:56:29+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/47adfbc23fc998584b61d65979bd7e44"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/05\/06\/o-iphan-no-licenciamento-ambiental-parte-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/05\/06\/o-iphan-no-licenciamento-ambiental-parte-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/05\/06\/o-iphan-no-licenciamento-ambiental-parte-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"O IPHAN no Licenciamento Ambiental (Parte 2)"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/47adfbc23fc998584b61d65979bd7e44","name":"Bruna vieira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f424a16cc622dfcca495cc34756573f82160959e68c9068f0cbedb5cece8e593?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f424a16cc622dfcca495cc34756573f82160959e68c9068f0cbedb5cece8e593?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f424a16cc622dfcca495cc34756573f82160959e68c9068f0cbedb5cece8e593?s=96&d=mm&r=g","caption":"Bruna vieira"},"sameAs":["https:\/\/cbic.org.br"],"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/caio-bona\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/3255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=3255"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/3255\/revisions"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=3255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=3255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=3255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}