{"id":3188,"date":"2019-04-25T19:24:38","date_gmt":"2019-04-25T22:24:38","guid":{"rendered":"https:\/\/cbic.org.br\/sustentabilidade\/2019\/04\/25\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\/"},"modified":"2019-04-25T19:24:43","modified_gmt":"2019-04-25T22:24:43","slug":"consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2019\/04\/25\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\/","title":{"rendered":"Consulta p\u00fablica das normas ABNT sobre reuso de \u00e1gua em edifica\u00e7\u00f5es"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" class=\"alignleft wp-image-3189 size-medium\" src=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/04\/Sem-T\u00edtulo-2-300x300.jpg\" alt=\"\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0 <\/strong><\/p>\n<p><strong>Virginia Sodr\u00e9, s\u00f3cia diretora da InfinityTech<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" width=\"150\" height=\"150\" class=\"alignleft wp-image-3191 size-thumbnail\" src=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/04\/fff-150x150.jpg\" alt=\"\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Pl\u00ednio Tomaz,\u00a0coordenador da norma de \u00e1gua de chuva<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" width=\"150\" height=\"150\" class=\"alignleft wp-image-3193 size-thumbnail\" src=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/04\/aaa-150x150.jpg\" alt=\"\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Lilian Sarrouf, coordenadora das duas novas normas de \u00e1gua<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">As crises de abastecimento ocorridas nos \u00faltimos anos t\u00eam levado a popula\u00e7\u00e3o de centros urbanos brasileiros a conviver com o racionamento no fornecimento de \u00e1gua. O adensamento populacional e o consequente acr\u00e9scimo de vaz\u00f5es retiradas para atendimento \u00e0s mais diversas demandas pressionam os mananciais al\u00e9m de suas capacidades e resulta em quadros de escassez h\u00eddrica severos, o que ocorre at\u00e9 mesmo em \u00e1reas abundantes em recursos h\u00eddricos.<\/p>\n<p style=\"text-align: justify\">\nEste cen\u00e1rio cr\u00f4nico e prolongado vem estimulando o mercado da constru\u00e7\u00e3o a buscar solu\u00e7\u00f5es que reduzam o consumo de \u00e1gua e aumentem a resili\u00eancia h\u00eddrica das edifica\u00e7\u00f5es, ou seja, alternativas que mitiguem a vulnerabilidade a crises e problem\u00e1ticas h\u00eddricas. Al\u00e9m disso, estas solu\u00e7\u00f5es tamb\u00e9m trazem atratividade ao neg\u00f3cio, j\u00e1 que acabam por agregar valor na venda e reduzem os custos com \u00e1gua para o usu\u00e1rio final.<\/p>\n<p style=\"text-align: justify\">\nAs \u00faltimas duas d\u00e9cadas foram marcadas por not\u00e1veis esfor\u00e7os de cria\u00e7\u00e3o de legisla\u00e7\u00f5es, principalmente municipais, que estabelecem a obrigatoriedade de aplica\u00e7\u00e3o de medidas de uso eficiente de \u00e1gua e utiliza\u00e7\u00e3o de fontes alternativas em edifica\u00e7\u00f5es. Essa movimenta\u00e7\u00e3o positiva, no entanto, ocorre \u00e0 margem de refer\u00eancias nacionais sobre o assunto, visto que ainda \u00e9 escasso ou inexistente arcabou\u00e7o normativo e legal nacional que oriente e instrua os diversos segmentos e atores envolvidos no tema.<\/p>\n<p style=\"text-align: justify\">\nFrente a isso, o Sindicato da Ind\u00fastria da Constru\u00e7\u00e3o Civil do Estado de S\u00e3o Paulo (SindusCon-SP), a C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC) e o Comit\u00ea de Constru\u00e7\u00e3o (CB2) da Associa\u00e7\u00e3o Brasileira de Normas T\u00e9cnicas (ABNT), atuando proativamente nesse contexto, elaboraram duas normas que abordam, promovem e difundem pr\u00e1ticas ligadas \u00e0 gest\u00e3o integrada de recursos h\u00eddricos: conserva\u00e7\u00e3o de \u00e1gua em edifica\u00e7\u00f5es (ABNT NBR 16.782) e uso de fontes alternativas n\u00e3o pot\u00e1veis em edifica\u00e7\u00f5es (ABNT NBR 16.783). Estas normas est\u00e3o em consulta nacional at\u00e9 dia 13 de maio de 2019 e podem ser acessadas em: <a href=\"https:\/\/www.abntonline.com.br\/consultanacional\/\">https:\/\/www.abntonline.com.br\/consultanacional\/<\/a>. Al\u00e9m destas, a norma ABNT NBR 15.527 &#8211; Aproveitamento de \u00e1gua de chuva para fins n\u00e3o pot\u00e1veis passou por revis\u00e3o ap\u00f3s 12 anos de sua primeira vers\u00e3o e ser\u00e1 publicada em breve.<\/p>\n<p style=\"text-align: justify\">\nA norma de conserva\u00e7\u00e3o de \u00e1gua (ABNT NBR 16.782) estabelece orienta\u00e7\u00f5es, diretrizes, requisitos e procedimentos para a realiza\u00e7\u00e3o da conserva\u00e7\u00e3o em edif\u00edcios, novos e existentes, combinando a\u00e7\u00f5es de gest\u00e3o da demanda e gest\u00e3o da oferta, conforme viabilidade t\u00e9cnica e econ\u00f4mica caso a caso. No caso da norma de fontes alternativas de \u00e1gua n\u00e3o pot\u00e1vel (ABNT NBR 16.783), s\u00e3o abordados aspectos de qualidade de \u00e1gua, dimensionamento, uso, opera\u00e7\u00e3o e manuten\u00e7\u00e3o de sistemas n\u00e3o pot\u00e1veis em edifica\u00e7\u00f5es. A \u00e1gua de chuva, ainda que tamb\u00e9m seja fonte n\u00e3o pot\u00e1vel e conste na respectiva norma, \u00e9 abordada com exclusividade pela ABNT NBR 15.527.<\/p>\n<p style=\"text-align: justify\">\nEspera-se que estas iniciativas contribuam de forma positiva para a consolida\u00e7\u00e3o de condutas mais eficientes e seguras no que se refere \u00e0 conserva\u00e7\u00e3o de \u00e1gua e aos usos de fontes n\u00e3o pot\u00e1veis, estimulando boas pr\u00e1ticas, diminuindo riscos, prezando pela viabilidade t\u00e9cnica e econ\u00f4mica das solu\u00e7\u00f5es e atuando em prol da gest\u00e3o integrada de recursos h\u00eddricos em edifica\u00e7\u00f5es.<br \/>\nLilian Sarrouf, coordenadora das duas novas normas, avaliou sua participa\u00e7\u00e3o na elabora\u00e7\u00e3o das publica\u00e7\u00f5es e a import\u00e2ncia da iniciativa:<\/p>\n<p style=\"text-align: justify\">\n\u201cFoi muito gratificante como coordenadora desta comiss\u00e3o trabalhar com equipes de todas as \u00e1reas. O aprendizado foi muito grande. Acredito que o recado que fica \u00e9 que todos n\u00f3s queremos, sim, a conserva\u00e7\u00e3o de \u00e1guas, o uso de fontes alternativas e uma constru\u00e7\u00e3o mais sustent\u00e1vel, mas queremos de forma correta e adequada para que aconte\u00e7a de fato!\u201d\u00a0Pl\u00ednio Tomaz, coordenador da primeira vers\u00e3o da norma de \u00e1gua de chuva e da revis\u00e3o realizada este ano, tamb\u00e9m avaliou sua participa\u00e7\u00e3o e a import\u00e2ncia das normas:<\/p>\n<p style=\"text-align: justify\">\n\u201cTrabalhar na revis\u00e3o da NBR 15.527 de \u00e1gua de chuva foi importante. Ela fez 10 anos no ano passado quando se iniciou o estudo da revis\u00e3o, e nestes 10 anos foram muitos aprendizados que proporcionaram propostas de melhorias para a norma, tanto de reda\u00e7\u00e3o de itens e requisitos que estavam tendo dupla interpreta\u00e7\u00e3o, tanto de li\u00e7\u00f5es novas aprendidas relacionadas \u00e0 qualidade e ao dimensionamento. Estes pontos acabaram sendo os centrais da comiss\u00e3o durante a revis\u00e3o.<\/p>\n<p style=\"text-align: justify\">\nFora isso, foi importante a representatividade. Foram muitas pessoas que participaram, mais de 40 individuais e todas as institui\u00e7\u00f5es muito bem representadas: projetistas, associa\u00e7\u00f5es, fabricantes, universidades, ent\u00e3o isso tamb\u00e9m \u00e9 um fator que pesa bastante para a gente ver a consist\u00eancia e o sucesso do trabalho.\u201d<\/p>\n<p style=\"text-align: justify\">\nVisando contribuir com o conjunto da cadeia produtiva e a sociedade, a CBIC publicar\u00e1 um guia orientativo sobre as normas supracitadas, tendo como objetivo auxiliar a leitura e compreens\u00e3o dos pontos abordados nas publica\u00e7\u00f5es por meio de utiliza\u00e7\u00e3o linguagem mais acess\u00edvel ao p\u00fablico n\u00e3o t\u00e9cnico e de recursos gr\u00e1ficos, exemplos, cases etc. Sobre o guia, Pl\u00ednio Tomaz complementa:<\/p>\n<p style=\"text-align: justify\">\n\u201c(&#8230;) espero que agora com o guia que est\u00e1 sendo elaborado pela CBIC a gente possa abordar e ampliar alguns conceitos, algumas situa\u00e7\u00f5es que n\u00e3o couberam na norma, mas que s\u00e3o importantes, como quest\u00f5es de dimensionamento, quest\u00f5es relativas \u00e0 escolha de equipamentos, \u00e0s premissas de projeto etc. O guia s\u00f3 vai ampliar o conhecimento sobre o assunto. \u00c9 uma \u00f3tima iniciativa da CBIC.\u201d<\/p>\n<p style=\"text-align: justify\">\nO Guia Orientativo das Normas de \u00c1gua ser\u00e1 disponibilizado ap\u00f3s a publica\u00e7\u00e3o das normas que atualmente encontram-se em Consulta P\u00fablica no link<br \/>\n<a href=\"https:\/\/www.abntonline.com.br\/consultanacional\/#\">https:\/\/www.abntonline.com.br\/consultanacional\/#<\/a><\/p>\n<p style=\"text-align: justify\">\nImportante ressaltar que al\u00e9m da participa\u00e7\u00e3o na Consulta P\u00fablica das normas de &#8216;reuso&#8217; de \u00e1gua, \u00e9 essencial analisar a exist\u00eancia de legisla\u00e7\u00f5es vigentes ou projetos de leis que estejam tramitando em munic\u00edpios ou estados que possam ser conflitantes ou contradit\u00f3rios ao texto proposto nas normas. N\u00f3s estamos realizando esse levantamento no \u00e2mbito federal e em alguns munic\u00edpios e estados que j\u00e1 sinalizaram a exist\u00eancia deste tipo de documento. Caso identifiquem alguma situa\u00e7\u00e3o, gentileza repassar as informa\u00e7\u00f5es para a Comiss\u00e3o de Meio Ambiente e Sustentabilidade da CBIC por meio do endere\u00e7o cma@cbic.org.br para que possamos em conjunto e propor solu\u00e7\u00f5es para o tema.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; \u00a0 Virginia Sodr\u00e9, s\u00f3cia diretora da InfinityTech &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Pl\u00ednio Tomaz,\u00a0coordenador da norma de \u00e1gua de chuva &nbsp; &nbsp; &nbsp; &nbsp; Lilian Sarrouf, coordenadora das duas novas normas de \u00e1gua &nbsp; &nbsp; As crises de abastecimento ocorridas nos [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[97,175],"tags":[],"class_list":["post-3188","post","type-post","status-publish","format-standard","hentry","category-agencia-cbic","category-sustentabilidade-agencia-cbic"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Consulta p\u00fablica das normas ABNT sobre reuso de \u00e1gua em edifica\u00e7\u00f5es - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/04\/25\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consulta p\u00fablica das normas ABNT sobre reuso de \u00e1gua em edifica\u00e7\u00f5es - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"&nbsp; &nbsp; &nbsp; \u00a0 Virginia Sodr\u00e9, s\u00f3cia diretora da InfinityTech &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Pl\u00ednio Tomaz,\u00a0coordenador da norma de \u00e1gua de chuva &nbsp; &nbsp; &nbsp; &nbsp; Lilian Sarrouf, coordenadora das duas novas normas de \u00e1gua &nbsp; &nbsp; As crises de abastecimento ocorridas nos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/04\/25\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-25T22:24:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-25T22:24:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/04\/Sem-T\u00edtulo-2-300x300.jpg\" \/>\n<meta name=\"author\" content=\"PH Freitas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"PH Freitas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/04\\\/25\\\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/04\\\/25\\\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\\\/\"},\"author\":{\"name\":\"PH Freitas\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/2cae51852e9e895aa18e04d83ad8328e\"},\"headline\":\"Consulta p\u00fablica das normas ABNT sobre reuso de \u00e1gua em edifica\u00e7\u00f5es\",\"datePublished\":\"2019-04-25T22:24:38+00:00\",\"dateModified\":\"2019-04-25T22:24:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/04\\\/25\\\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\\\/\"},\"wordCount\":1150,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/04\\\/25\\\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/04\\\/fff-150x150.jpg\",\"articleSection\":[\"Ag\u00eancia CBIC\",\"Sustentabilidade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/04\\\/25\\\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/04\\\/25\\\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/04\\\/25\\\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\\\/\",\"name\":\"Consulta p\u00fablica das normas ABNT sobre reuso de \u00e1gua em edifica\u00e7\u00f5es - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/04\\\/25\\\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/04\\\/25\\\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/04\\\/fff-150x150.jpg\",\"datePublished\":\"2019-04-25T22:24:38+00:00\",\"dateModified\":\"2019-04-25T22:24:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/2cae51852e9e895aa18e04d83ad8328e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/04\\\/25\\\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/04\\\/25\\\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/04\\\/25\\\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/04\\\/fff.jpg\",\"contentUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/04\\\/fff.jpg\",\"width\":484,\"height\":484},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/04\\\/25\\\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consulta p\u00fablica das normas ABNT sobre reuso de \u00e1gua em edifica\u00e7\u00f5es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/2cae51852e9e895aa18e04d83ad8328e\",\"name\":\"PH Freitas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g\",\"caption\":\"PH Freitas\"},\"sameAs\":[\"https:\\\/\\\/cbic.org.br\"],\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/ph-freitas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Consulta p\u00fablica das normas ABNT sobre reuso de \u00e1gua em edifica\u00e7\u00f5es - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/04\/25\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\/","og_locale":"pt_BR","og_type":"article","og_title":"Consulta p\u00fablica das normas ABNT sobre reuso de \u00e1gua em edifica\u00e7\u00f5es - Comiss\u00e3o de Meio Ambiente","og_description":"&nbsp; &nbsp; &nbsp; \u00a0 Virginia Sodr\u00e9, s\u00f3cia diretora da InfinityTech &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Pl\u00ednio Tomaz,\u00a0coordenador da norma de \u00e1gua de chuva &nbsp; &nbsp; &nbsp; &nbsp; Lilian Sarrouf, coordenadora das duas novas normas de \u00e1gua &nbsp; &nbsp; As crises de abastecimento ocorridas nos [&hellip;]","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/04\/25\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2019-04-25T22:24:38+00:00","article_modified_time":"2019-04-25T22:24:43+00:00","og_image":[{"url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/04\/Sem-T\u00edtulo-2-300x300.jpg","type":"","width":"","height":""}],"author":"PH Freitas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"PH Freitas","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/04\/25\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/04\/25\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\/"},"author":{"name":"PH Freitas","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/2cae51852e9e895aa18e04d83ad8328e"},"headline":"Consulta p\u00fablica das normas ABNT sobre reuso de \u00e1gua em edifica\u00e7\u00f5es","datePublished":"2019-04-25T22:24:38+00:00","dateModified":"2019-04-25T22:24:43+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/04\/25\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\/"},"wordCount":1150,"commentCount":0,"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/04\/25\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/04\/fff-150x150.jpg","articleSection":["Ag\u00eancia CBIC","Sustentabilidade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/04\/25\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/04\/25\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/04\/25\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\/","name":"Consulta p\u00fablica das normas ABNT sobre reuso de \u00e1gua em edifica\u00e7\u00f5es - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/04\/25\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/04\/25\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/04\/fff-150x150.jpg","datePublished":"2019-04-25T22:24:38+00:00","dateModified":"2019-04-25T22:24:43+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/2cae51852e9e895aa18e04d83ad8328e"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/04\/25\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/04\/25\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/04\/25\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\/#primaryimage","url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/04\/fff.jpg","contentUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/04\/fff.jpg","width":484,"height":484},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/04\/25\/consulta-publica-das-normas-abnt-sobre-reuso-de-agua-em-edificacoes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"Consulta p\u00fablica das normas ABNT sobre reuso de \u00e1gua em edifica\u00e7\u00f5es"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/2cae51852e9e895aa18e04d83ad8328e","name":"PH Freitas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g","caption":"PH Freitas"},"sameAs":["https:\/\/cbic.org.br"],"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/ph-freitas\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/3188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=3188"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/3188\/revisions"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=3188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=3188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=3188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}