{"id":3153,"date":"2019-04-12T05:46:35","date_gmt":"2019-04-12T08:46:35","guid":{"rendered":"https:\/\/cbic.org.br\/sustentabilidade\/?p=3153"},"modified":"2019-04-12T05:46:35","modified_gmt":"2019-04-12T08:46:35","slug":"comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2019\/04\/12\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\/","title":{"rendered":"Comiss\u00e3o de Meio Ambiente do Senado aprova financiamento do FGTS para empresas que usam energia solar"},"content":{"rendered":"<p><span style=\"font-size: 14pt\">Empresas que utilizam energia solar fotovoltaica em sua matriz energ\u00e9tica poder\u00e3o ser financiadas com recursos do Fundo de Garantia do Tempo de Servi\u00e7o (FGTS). \u00c9 o que prev\u00ea o Projeto de Lei do Senado\u00a0<a class=\"external-link\" href=\"https:\/\/www25.senado.leg.br\/web\/atividade\/materias\/-\/materia\/134889\">(PLS) 524\/2018<\/a>, aprovado nesta quarta-feira (10) pela Comiss\u00e3o de Meio Ambiente (CMA).<\/span><\/p>\n<p><span style=\"font-size: 14pt\">A proposta altera a\u00a0<a class=\"external-link\" href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/LEIS\/L8036consol.htm\">Lei n\u00ba 8.036, de 1990<\/a>\u00a0para viabilizar a aplica\u00e7\u00e3o de recursos do fundo em opera\u00e7\u00f5es de cr\u00e9dito destinadas a projetos de gera\u00e7\u00e3o de energia el\u00e9trica a partir de fontes renov\u00e1veis. O PLS determina a aplica\u00e7\u00e3o de pelo menos 1% dos recursos do FGTS em opera\u00e7\u00f5es de cr\u00e9dito destinadas a empresas que utilizem energia el\u00e9trica oriunda preponderantemente de usina fotovoltaica.<\/span><\/p>\n<p><span style=\"font-size: 14pt\">Autora do projeto, a senadora Rose de Freitas (Pode-ES) destaca a import\u00e2ncia da amplia\u00e7\u00e3o do uso de energia solar na matriz energ\u00e9tica brasileira como forma de reduzir o uso de outras formas \u201cmais agressivas ao meio ambiente\u201d.<\/span><\/p>\n<p><span style=\"font-size: 14pt\">O relator da proposta, senador Jaques Wagner (PT-BA), ampliou o incentivo tamb\u00e9m para pessoas jur\u00eddicas de direito privado, e n\u00e3o apenas exclusivamente para empresas. O objetivo de Wagner \u00e9 contemplar tamb\u00e9m uma s\u00e9rie de institui\u00e7\u00f5es que n\u00e3o ostentam a forma empresarial, mas que podem ser alcan\u00e7adas pela proposta, a exemplo de institui\u00e7\u00f5es de ensino, sa\u00fade e cooperativas.<\/span><\/p>\n<p><span style=\"font-size: 14pt\">\u201cDe modo a viabilizar a amplia\u00e7\u00e3o do acesso a essas fontes por toda a popula\u00e7\u00e3o. Assim, haveria maior ganho ambiental, com maior gera\u00e7\u00e3o de energia limpa, e mitiga\u00e7\u00e3o dos impactos tarif\u00e1rios nos consumidores atendidos pelas distribuidoras\u201d, avalia Jaques Wagner no relat\u00f3rio.<\/span><\/p>\n<p><span style=\"font-size: 14pt\">O relator destacou ainda os compromissos assumidos pelo Brasil no Acordo de Paris relacionados \u00e0s energias renov\u00e1veis: atingir participa\u00e7\u00e3o de 45% de todas as energias renov\u00e1veis na matriz energ\u00e9tica em 2030; expandir o uso de fontes renov\u00e1veis (exceto energia h\u00eddrica) na matriz total de energia para 28 a 33% de participa\u00e7\u00e3o at\u00e9 2030; e aumentar a participa\u00e7\u00e3o de energia de biomassa sustent\u00e1vel (bioenergia) na matriz energ\u00e9tica para 18% at\u00e9 2030.<\/span><\/p>\n<p><span style=\"font-size: 14pt\">A mat\u00e9ria segue para an\u00e1lise da Comiss\u00e3o de Assuntos Sociais (CAS) onde receber\u00e1 decis\u00e3o terminativa.<\/span><\/p>\n<p>Fonte:https:\/\/www12.senado.leg.br\/noticias\/materias\/2019\/04\/10\/cma-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Empresas que utilizam energia solar fotovoltaica em sua matriz energ\u00e9tica poder\u00e3o ser financiadas com recursos do Fundo de Garantia do Tempo de Servi\u00e7o (FGTS). \u00c9 o que prev\u00ea o Projeto de Lei do Senado\u00a0(PLS) 524\/2018, aprovado nesta quarta-feira (10) pela Comiss\u00e3o de Meio Ambiente (CMA). [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":3154,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[5,8,98],"tags":[199,200],"class_list":["post-3153","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-imprensa","category-meio-ambiente","category-sustentabilidade","tag-energia-solar-fotovoltaica","tag-fgts"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comiss\u00e3o de Meio Ambiente do Senado aprova financiamento do FGTS para empresas que usam energia solar - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/04\/12\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comiss\u00e3o de Meio Ambiente do Senado aprova financiamento do FGTS para empresas que usam energia solar - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"Empresas que utilizam energia solar fotovoltaica em sua matriz energ\u00e9tica poder\u00e3o ser financiadas com recursos do Fundo de Garantia do Tempo de Servi\u00e7o (FGTS). \u00c9 o que prev\u00ea o Projeto de Lei do Senado\u00a0(PLS) 524\/2018, aprovado nesta quarta-feira (10) pela Comiss\u00e3o de Meio Ambiente (CMA). [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/04\/12\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-12T08:46:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/04\/imagem_materia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"860\" \/>\n\t<meta property=\"og:image:height\" content=\"570\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mariana Silveira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mariana Silveira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2019\\\/04\\\/12\\\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2019\\\/04\\\/12\\\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\\\/\"},\"author\":{\"name\":\"Mariana Silveira\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/603bd268fcca3c96db068d487ad37a97\"},\"headline\":\"Comiss\u00e3o de Meio Ambiente do Senado aprova financiamento do FGTS para empresas que usam energia solar\",\"datePublished\":\"2019-04-12T08:46:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2019\\\/04\\\/12\\\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\\\/\"},\"wordCount\":389,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2019\\\/04\\\/12\\\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/04\\\/imagem_materia.jpg\",\"keywords\":[\"energia solar fotovoltaica\",\"fgts\"],\"articleSection\":[\"Imprensa\",\"Meio Ambiente\",\"Sustentabilidade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2019\\\/04\\\/12\\\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2019\\\/04\\\/12\\\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2019\\\/04\\\/12\\\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente do Senado aprova financiamento do FGTS para empresas que usam energia solar - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2019\\\/04\\\/12\\\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2019\\\/04\\\/12\\\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/04\\\/imagem_materia.jpg\",\"datePublished\":\"2019-04-12T08:46:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/603bd268fcca3c96db068d487ad37a97\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2019\\\/04\\\/12\\\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2019\\\/04\\\/12\\\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2019\\\/04\\\/12\\\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/04\\\/imagem_materia.jpg\",\"contentUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/04\\\/imagem_materia.jpg\",\"width\":860,\"height\":570},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/es_ES\\\/2019\\\/04\\\/12\\\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comiss\u00e3o de Meio Ambiente do Senado aprova financiamento do FGTS para empresas que usam energia solar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/603bd268fcca3c96db068d487ad37a97\",\"name\":\"Mariana Silveira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f6b9548cb32a896eaaa8be55dc306cac3d5af83910785081e1cbc92018986a2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f6b9548cb32a896eaaa8be55dc306cac3d5af83910785081e1cbc92018986a2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f6b9548cb32a896eaaa8be55dc306cac3d5af83910785081e1cbc92018986a2?s=96&d=mm&r=g\",\"caption\":\"Mariana Silveira\"},\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/mariana-silveira\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comiss\u00e3o de Meio Ambiente do Senado aprova financiamento do FGTS para empresas que usam energia solar - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/04\/12\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\/","og_locale":"pt_BR","og_type":"article","og_title":"Comiss\u00e3o de Meio Ambiente do Senado aprova financiamento do FGTS para empresas que usam energia solar - Comiss\u00e3o de Meio Ambiente","og_description":"Empresas que utilizam energia solar fotovoltaica em sua matriz energ\u00e9tica poder\u00e3o ser financiadas com recursos do Fundo de Garantia do Tempo de Servi\u00e7o (FGTS). \u00c9 o que prev\u00ea o Projeto de Lei do Senado\u00a0(PLS) 524\/2018, aprovado nesta quarta-feira (10) pela Comiss\u00e3o de Meio Ambiente (CMA). [&hellip;]","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/04\/12\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2019-04-12T08:46:35+00:00","og_image":[{"width":860,"height":570,"url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/04\/imagem_materia.jpg","type":"image\/jpeg"}],"author":"Mariana Silveira","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mariana Silveira","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/04\/12\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/04\/12\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\/"},"author":{"name":"Mariana Silveira","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/603bd268fcca3c96db068d487ad37a97"},"headline":"Comiss\u00e3o de Meio Ambiente do Senado aprova financiamento do FGTS para empresas que usam energia solar","datePublished":"2019-04-12T08:46:35+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/04\/12\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\/"},"wordCount":389,"commentCount":0,"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/04\/12\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/04\/imagem_materia.jpg","keywords":["energia solar fotovoltaica","fgts"],"articleSection":["Imprensa","Meio Ambiente","Sustentabilidade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/04\/12\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/04\/12\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/04\/12\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\/","name":"Comiss\u00e3o de Meio Ambiente do Senado aprova financiamento do FGTS para empresas que usam energia solar - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/04\/12\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/04\/12\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/04\/imagem_materia.jpg","datePublished":"2019-04-12T08:46:35+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/603bd268fcca3c96db068d487ad37a97"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/04\/12\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/04\/12\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/04\/12\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\/#primaryimage","url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/04\/imagem_materia.jpg","contentUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/04\/imagem_materia.jpg","width":860,"height":570},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/es_ES\/2019\/04\/12\/comissao-de-meio-ambiente-do-senado-aprova-financiamento-do-fgts-para-empresas-que-usam-energia-solar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"Comiss\u00e3o de Meio Ambiente do Senado aprova financiamento do FGTS para empresas que usam energia solar"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/603bd268fcca3c96db068d487ad37a97","name":"Mariana Silveira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/2f6b9548cb32a896eaaa8be55dc306cac3d5af83910785081e1cbc92018986a2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2f6b9548cb32a896eaaa8be55dc306cac3d5af83910785081e1cbc92018986a2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2f6b9548cb32a896eaaa8be55dc306cac3d5af83910785081e1cbc92018986a2?s=96&d=mm&r=g","caption":"Mariana Silveira"},"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/mariana-silveira\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/3153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=3153"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/3153\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media\/3154"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=3153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=3153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=3153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}