{"id":3008,"date":"2019-03-11T15:24:07","date_gmt":"2019-03-11T18:24:07","guid":{"rendered":"https:\/\/cbic.org.br\/sustentabilidade\/2019\/03\/11\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\/"},"modified":"2019-03-11T15:24:15","modified_gmt":"2019-03-11T18:24:15","slug":"artigo-cidades-de-futuro-e-o-futuro-das-cidades","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2019\/03\/11\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\/","title":{"rendered":"Artigo: Cidades de futuro e O Futuro das Cidades"},"content":{"rendered":"<h2>CBIC no Congresso de Smart Cities<\/h2>\n<p><strong><img decoding=\"async\" width=\"150\" height=\"150\" class=\"alignleft wp-image-3009 size-thumbnail\" src=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/03\/Silvio_Barros-150x150.jpeg\" alt=\"\" \/><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Silvio Barros \u00e9 engenheiro civil, com especializa\u00e7\u00e3o em Engenharia Sanit\u00e1ria e Ambiental, ex-prefeito de Maring\u00e1 e idealizador e consultor do projeto O Futuro da Minha Cidade<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">De modo geral quando falamos das Cidades do Futuro nos referimos a como ser\u00e3o os aglomerados urbanos novos, aqueles que est\u00e3o sendo projetados e constru\u00eddos agora, levando em conta todas as tecnologias e aprendizado acumulado ao longo da hist\u00f3ria humana. N\u00e3o necessariamente cidades que est\u00e3o sendo feitas partindo do zero, destinadas a comunidades rurais e que n\u00e3o incorporam todas as modernidades tecnol\u00f3gicas, mas que j\u00e1 simbolizam um extraordin\u00e1rio avan\u00e7o nas condi\u00e7\u00f5es de vida de popula\u00e7\u00f5es inteiras que ainda hoje s\u00e3o privadas de energia el\u00e9trica e cozinham com lenha suas refei\u00e7\u00f5es todos os dias.\u00a0 Na verdade, para n\u00f3s cidades do futuro s\u00e3o como <em>Masdar<\/em> nos Emirados \u00c1rabes, ou <em>Gujarat<\/em> na India, ou <em>Songdoo<\/em> na Coreia do Sul, ou ainda <em>Forest City<\/em> na Malasia ou <em>Xiongan<\/em> na China. Essas cidades quebram os paradigmas e j\u00e1 nascem dentro dos conceitos da Economia Compartilhada, da Economia Digital, da Economia Circular, da Economia Criativa e da quarta revolu\u00e7\u00e3o industrial.<\/p>\n<p style=\"text-align: justify\">O outro lado dessa mesma moeda diz respeito ao Futuro da Cidades (que j\u00e1 existem), onde vivemos hoje, que foram constru\u00eddas h\u00e1 muitos anos ou mesmo s\u00e9culos e que ao longo do tempo tiveram (e ainda est\u00e3o tendo) um crescimento desordenado, ca\u00f3tico, mas que precisam desesperadamente adequar sua estrutura, seus servi\u00e7os e sua vida \u00e0 modernidade.<\/p>\n<p style=\"text-align: justify\">Esses dois tipos de cidade t\u00eam algo em comum, al\u00e9m da expectativa das pessoas por uma substantiva melhoria na qualidade de vida dos seus moradores, essas cidades colocar\u00e3o em pr\u00e1tica as ferramentas das <em>Smart Cities<\/em>, a l\u00f3gica das cidades inteligentes, onde a mobilidade, a conectividade, a seguran\u00e7a, comunica\u00e7\u00e3o, <em>blockchain<\/em>, internet das coisas <em>IOT<\/em>, ser\u00e3o parte integrante da rotina urbana e essenciais ao bom funcionamento tamb\u00e9m dos servi\u00e7os p\u00fablicos.<\/p>\n<p style=\"text-align: justify\">Nas cidades de hoje, o grande desafio, no entanto, n\u00e3o \u00e9 o COMO fazer isso e sim o QUANDO. As tecnologias j\u00e1 existem, muitas delas j\u00e1 dominadas e testadas, mas parece que s\u00f3 chegar\u00e3o a ser realidade para n\u00f3s daqui h\u00e1 muitos anos. Acontece que o tempo \u00e9 o fator determinante na competitividade, na capacidade de reter talentos, de atrair neg\u00f3cios e de manter empregos. \u00c9 a velocidade das mudan\u00e7as o principal diferencial de sucesso nesse processo de transi\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify\">Milhares de cidades est\u00e3o, justamente agora, revisando seus planos diretores que valer\u00e3o para os pr\u00f3ximos 10 anos, por\u00e9m, inexplicavelmente, esses novos paradigmas sequer est\u00e3o sendo considerados na nova base jur\u00eddica de ordena\u00e7\u00e3o do espa\u00e7o urbano. Por que? Quanto vai custar esta omiss\u00e3o em empregos, recursos e perda de competitividade? De quem afinal \u00e9 a responsabilidade de inserir no debate e na constru\u00e7\u00e3o dos novos planos diretores esta vis\u00e3o?<\/p>\n<p style=\"text-align: justify\">A CBIC entende que esse tipo de planejamento futuro n\u00e3o pode ser exclusivamente demandado das prefeituras, os governos t\u00eam prazo de validade de quatro anos, mas a sociedade organizada tem compromisso com o futuro e, portanto, deve assumir papel estrat\u00e9gico no protagonismo deste planejamento e at\u00e9 mesmo lider\u00e1-lo, sempre que poss\u00edvel trabalhando e desenvolvendo os planos em parceria com o poder p\u00fablico.<\/p>\n<p style=\"text-align: justify\">\u00c9 o setor privado e o terceiro setor que mais afinidades t\u00eam com o conceito de planejamento estrat\u00e9gico de longo prazo e de diferenciais de competitividade associados a aumento de produtividade e redu\u00e7\u00e3o de custos, conceitos ainda muito distantes da gest\u00e3o p\u00fablica infelizmente.<\/p>\n<p style=\"text-align: justify\">Atrav\u00e9s do programa O Futuro da Minha Cidade, a CBIC, em correaliza\u00e7\u00e3o com o Sese Nacional, patroc\u00ednio da Caixa Econ\u00f4mica Federal e a participa\u00e7\u00e3o dos Sinduscons, Ademis e outras entidades representativas, t\u00eam procurado instigar cidades brasileiras a sair da sua zona de conforto e assumir o desafio de desenhar o seu pr\u00f3prio futuro.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"1000\" class=\"aligncenter wp-image-3011 size-full\" src=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/03\/O_Futuro_da_Minha_Cidade.png\" alt=\"Card sobre o III Workshop O Futuro da Minha Cidade, em Curitiba \" \/><\/p>\n<p style=\"text-align: justify\">Buscando promover ainda uma maior troca de experi\u00eancias entre comunidades que j\u00e1 aceitaram esse desafio, ser\u00e1 realizado dias 21 e 22 de mar\u00e7o, em paralelo ao evento Smart City Expo Curitiba, o 3\u00ba Workshop de Boas Pr\u00e1ticas na constru\u00e7\u00e3o desta nova governan\u00e7a, com o objetivo de disseminar o conhecimento e as pr\u00e1ticas j\u00e1 desenvolvidas por aqueles munic\u00edpios que j\u00e1 est\u00e3o com o Projeto implementado e promover a qualifica\u00e7\u00e3o e o engajamento dos munic\u00edpios que est\u00e3o iniciando o processo. Participe!<\/p>\n","protected":false},"excerpt":{"rendered":"<h2>CBIC no Congresso de Smart Cities<\/h2>\n<p><strong>Silvio Barros \u00e9 engenheiro<br \/>\n<\/strong><\/p>\n<p style=\"text-align: justify\">De modo geral quando falamos das Cidades do Futuro nos referimos a como ser\u00e3o os aglomerados urbanos novos, aqueles que est\u00e3o se&#8230;<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[180,97,5,175],"tags":[],"class_list":["post-3008","post","type-post","status-publish","format-standard","hentry","category-agencia-cbic-pt","category-agencia-cbic","category-imprensa","category-sustentabilidade-agencia-cbic"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Artigo: Cidades de futuro e O Futuro das Cidades - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/03\/11\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Artigo: Cidades de futuro e O Futuro das Cidades - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"CBIC no Congresso de Smart Cities Silvio Barros \u00e9 engenheiro  De modo geral quando falamos das Cidades do Futuro nos referimos a como ser\u00e3o os aglomerados urbanos novos, aqueles que est\u00e3o se...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/03\/11\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-11T18:24:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-11T18:24:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/03\/Silvio_Barros-150x150.jpeg\" \/>\n<meta name=\"author\" content=\"Sandra Bezerra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sandra Bezerra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/03\\\/11\\\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/03\\\/11\\\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\\\/\"},\"author\":{\"name\":\"Sandra Bezerra\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\"},\"headline\":\"Artigo: Cidades de futuro e O Futuro das Cidades\",\"datePublished\":\"2019-03-11T18:24:07+00:00\",\"dateModified\":\"2019-03-11T18:24:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/03\\\/11\\\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\\\/\"},\"wordCount\":778,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/03\\\/11\\\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/03\\\/Silvio_Barros-150x150.jpeg\",\"articleSection\":[\"Ag\u00eancia CBIC\",\"Ag\u00eancia CBIC\",\"Imprensa\",\"Sustentabilidade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/03\\\/11\\\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/03\\\/11\\\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/03\\\/11\\\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\\\/\",\"name\":\"Artigo: Cidades de futuro e O Futuro das Cidades - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/03\\\/11\\\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/03\\\/11\\\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/03\\\/Silvio_Barros-150x150.jpeg\",\"datePublished\":\"2019-03-11T18:24:07+00:00\",\"dateModified\":\"2019-03-11T18:24:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/03\\\/11\\\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/03\\\/11\\\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/03\\\/11\\\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/03\\\/Silvio_Barros.jpeg\",\"contentUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/03\\\/Silvio_Barros.jpeg\",\"width\":505,\"height\":505},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2019\\\/03\\\/11\\\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Artigo: Cidades de futuro e O Futuro das Cidades\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\",\"name\":\"Sandra Bezerra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"caption\":\"Sandra Bezerra\"},\"sameAs\":[\"https:\\\/\\\/cbic.org.br\"],\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/sandra-bezerra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Artigo: Cidades de futuro e O Futuro das Cidades - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/03\/11\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\/","og_locale":"pt_BR","og_type":"article","og_title":"Artigo: Cidades de futuro e O Futuro das Cidades - Comiss\u00e3o de Meio Ambiente","og_description":"CBIC no Congresso de Smart Cities Silvio Barros \u00e9 engenheiro  De modo geral quando falamos das Cidades do Futuro nos referimos a como ser\u00e3o os aglomerados urbanos novos, aqueles que est\u00e3o se...","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/03\/11\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2019-03-11T18:24:07+00:00","article_modified_time":"2019-03-11T18:24:15+00:00","og_image":[{"url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/03\/Silvio_Barros-150x150.jpeg","type":"","width":"","height":""}],"author":"Sandra Bezerra","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sandra Bezerra","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/03\/11\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/03\/11\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\/"},"author":{"name":"Sandra Bezerra","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e"},"headline":"Artigo: Cidades de futuro e O Futuro das Cidades","datePublished":"2019-03-11T18:24:07+00:00","dateModified":"2019-03-11T18:24:15+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/03\/11\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\/"},"wordCount":778,"commentCount":0,"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/03\/11\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/03\/Silvio_Barros-150x150.jpeg","articleSection":["Ag\u00eancia CBIC","Ag\u00eancia CBIC","Imprensa","Sustentabilidade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/03\/11\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/03\/11\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/03\/11\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\/","name":"Artigo: Cidades de futuro e O Futuro das Cidades - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/03\/11\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/03\/11\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/03\/Silvio_Barros-150x150.jpeg","datePublished":"2019-03-11T18:24:07+00:00","dateModified":"2019-03-11T18:24:15+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/03\/11\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/03\/11\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/03\/11\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\/#primaryimage","url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/03\/Silvio_Barros.jpeg","contentUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2019\/03\/Silvio_Barros.jpeg","width":505,"height":505},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2019\/03\/11\/artigo-cidades-de-futuro-e-o-futuro-das-cidades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"Artigo: Cidades de futuro e O Futuro das Cidades"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e","name":"Sandra Bezerra","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","caption":"Sandra Bezerra"},"sameAs":["https:\/\/cbic.org.br"],"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/sandra-bezerra\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/3008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=3008"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/3008\/revisions"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=3008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=3008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=3008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}