{"id":2823,"date":"2018-11-29T12:10:56","date_gmt":"2018-11-29T14:10:56","guid":{"rendered":"https:\/\/cbic.org.br\/sustentabilidade\/2019\/01\/20\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\/"},"modified":"2019-01-23T03:26:19","modified_gmt":"2019-01-23T05:26:19","slug":"setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2018\/11\/29\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\/","title":{"rendered":"Setor debate desenvolvimento urbano sustent\u00e1vel em Santa Rosa"},"content":{"rendered":"<figure id=\"attachment_31069\" aria-describedby=\"caption-attachment-31069\" style=\"width: 1980px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"wp-image-31069 size-full\" src=\"https:\/\/cbic.org.br\/wp-content\/uploads\/2018\/12\/g5q.jpg\" alt=\"\" \/><figcaption id=\"caption-attachment-31069\" class=\"wp-caption-text\">Marcella Arruda, arquiteta urbanista do Instituto A Cidade Precisa de Voc\u00ea e o ex-prefeito de Maring\u00e1, Silvio Barros, instigam participantes a entender que a sociedade precisa ser protagonista da mudan\u00e7a<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: georgia, palatino, serif;font-size: 12pt;color: #000000\">Cerca de 100 pessoas \u2013 representantes do setor p\u00fablico e privado, da academia, lideran\u00e7as pol\u00edticas e apartid\u00e1rias e a comunidade local \u2013 estiveram reunidas em Santa Rosa, Rio Grande do Sul, durante o semin\u00e1rio <strong>O Futuro da Minha Cidade<\/strong>, cuja finalidade consiste em <strong>estimular<\/strong> o p\u00fablico a <strong>pensar<\/strong> sobre <strong>o desenvolvimento urbano sustent\u00e1vel do munic\u00edpio<\/strong> para 20 anos, <strong>com participa\u00e7\u00e3o efetiva da sociedade<\/strong>.<\/span><\/p>\n<p><span style=\"font-family: georgia, palatino, serif;font-size: 12pt;color: #000000\">O projeto <strong>O Futuro da Minha Cidade<\/strong> \u00e9 uma <strong>iniciativa da CBIC, com correaliza\u00e7\u00e3o do Sesi Nacional e patroc\u00ednio nacional da Caixa Econ\u00f4mica Federal<\/strong>.<\/span><\/p>\n<p><span style=\"font-family: georgia, palatino, serif;font-size: 12pt;color: #000000\">No munic\u00edpio de Santa Rosa foi realizado pela Associa\u00e7\u00e3o Comercial, Industrial, Servi\u00e7os e Agroneg\u00f3cios (Acisap) e o Sindicato da Industria da Constru\u00e7\u00e3o e do Mobili\u00e1rio do Noroeste do Rio Grande do Sul (Sinduscom Noroeste), com apoio da Ag\u00eancia de Desenvolvimento de Santa Rosa (AD) e do Governo Municipal de Santa Rosa.<\/span><\/p>\n<p><span style=\"font-family: georgia, palatino, serif;font-size: 12pt;color: #000000\">As autoridades locais foram representadas pelo prefeito municipal, Alcides Vicini; o secret\u00e1rio municipal de Desenvolvimento Econ\u00f4mico, Artur Lorentz; o presidente do Sinduscon Noroeste George Al\u00e9ssio Volweis; o presidente da Acisap, Odaylson Eder; e o presidente da Ag\u00eancia de Desenvolvimento de Santa Rosa, Marcos Paulo Scherer.<\/span><\/p>\n<p><span style=\"font-family: georgia, palatino, serif;font-size: 12pt;color: #000000\">A primeira palestra foi conduzida por <strong>Marcella Arruda<\/strong>, arquiteta urbanista <strong>do Instituto A Cidade Precisa de Voc\u00ea<\/strong>, que falou sobre a import\u00e2ncia da participa\u00e7\u00e3o das pessoas na constru\u00e7\u00e3o de cidades compartilhadas.<\/span><\/p>\n<p><span style=\"font-family: georgia, palatino, serif;font-size: 12pt;color: #000000\">Ela citou as ferramentas que constroem a uni\u00e3o da sociedade.<\/span><\/p>\n<p><span style=\"font-family: georgia, palatino, serif;font-size: 12pt;color: #000000\">Na avalia\u00e7\u00e3o que fez da visita realizada em Santa Rosa, dos espa\u00e7os urbanos e dos projetos s\u00f3cio culturais e de empreendedorismo, percebeu a exist\u00eancia de uma sinergia entre o setor p\u00fablico e os cidad\u00e3os, enalteceu que \u00e9 poss\u00edvel verificar uma colabora\u00e7\u00e3o entre os diversos setores para o seu munic\u00edpio e que esse \u00e9 o segredo de se criar ciclos produtivos para a evolu\u00e7\u00e3o das cidades.<\/span><\/p>\n<p><span style=\"font-family: georgia, palatino, serif;font-size: 12pt;color: #000000\">A segunda palestra foi ministrada pelo ex-prefeito de Maring\u00e1, <strong>Silvio Barros<\/strong>. Ele trouxe o <strong>case de sucesso da administra\u00e7\u00e3o municipal de Maring\u00e1<\/strong>, que serviu de <strong>base para a cria\u00e7\u00e3o do projeto O Futuro da Minha Cidade<\/strong>.<\/span><\/p>\n<p><span style=\"font-family: georgia, palatino, serif;font-size: 12pt;color: #000000\"><strong>Pelo segundo ano consecutivo<\/strong>, a cidade paranaense foi <strong>considerada a melhor do pa\u00eds para se viver<\/strong>.<\/span><\/p>\n<blockquote>\n<p style=\"text-align: left\"><span style=\"font-family: georgia, palatino, serif;font-size: 12pt;color: #000000\">Barros destacou o protagonismo assumido por Maring\u00e1 e a import\u00e2ncia do Conselho de Desenvolvimento Municipal. <em>\u201cA cidade precisa come\u00e7ar a pensar no futuro, 20 anos na frente. Assim como n\u00f3s fazemos planos para a vida, as cidades precisam pensar no futuro\u201d<\/em>, afirmou.<\/span><\/p>\n<p style=\"text-align: right\"><span style=\"font-family: georgia, palatino, serif;font-size: 12pt;color: #000000\">Na oportunidade, instigou os participantes a entender que \u00e9 preciso fazer a mudan\u00e7a acontecer. <em>\u201cSe queremos mudar algo, precisamos ser protagonistas dessa mudan\u00e7a e n\u00e3o esperar que o poder p\u00fablico seja o \u00fanico respons\u00e1vel por ela\u201d<\/em>, disse Barros.<\/span><\/p>\n<\/blockquote>\n<p><span style=\"font-family: georgia, palatino, serif;font-size: 12pt;color: #000000\">Santa Rosa j\u00e1 conta com um movimento popular interessado em organizar a participa\u00e7\u00e3o da sociedade nas proposi\u00e7\u00f5es do planejamento urbano da cidade a longo prazo. Ou seja, o di\u00e1logo entre o Poder P\u00fablico, empresas e cidad\u00e3os est\u00e1 sendo organizado e agora a cidade precisa estabelecer as metas e implement\u00e1-las.<\/span><\/p>\n<p><span style=\"font-family: georgia, palatino, serif;font-size: 12pt;color: #000000\">Ao final do evento, nas palavras do\u00a0presidente da Ag\u00eancia de Desenvolvimento de Santa Rosa, Marcos Paulo Scherer, e dos demais presentes, ficou\u00a0registrado a formata\u00e7\u00e3o das c\u00e2maras tem\u00e1ticas para que todos,\u00a0em conjunto, observem as inova\u00e7\u00f5es, absorvam as tend\u00eancias, promovam uma mudan\u00e7a de paradigma,\u00a0para come\u00e7ar a rever o planejamento estrat\u00e9gico\u00a0e\u00a0estudar os modelos de planejamento para o futuro da\u00a0cidade de Santa Rosa.<\/span><\/p>\n<p><span style=\"font-family: georgia, palatino, serif;font-size: 12pt;color: #000000\">O <strong>in\u00edcio do projeto O Futuro da Minha Cidade<\/strong> foi <strong>em Maring\u00e1<\/strong>, no noroeste do Paran\u00e1.<\/span><\/p>\n<p><span style=\"font-family: georgia, palatino, serif;font-size: 12pt;color: #000000\">O projeto j\u00e1 foi <strong>implementado em 30\u00a0cidades<\/strong>, entre elas, Goi\u00e2nia (GO), Bras\u00edlia (DF), Manaus (AM), Bento Gon\u00e7alves (RS), Natal (RN), S\u00e3o Lu\u00eds (MA), Volta Redonda (RJ) e Rio do Sul (SC).<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8230;<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[97,175],"tags":[],"class_list":["post-2823","post","type-post","status-publish","format-standard","hentry","category-agencia-cbic","category-sustentabilidade-agencia-cbic"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Setor debate desenvolvimento urbano sustent\u00e1vel em Santa Rosa - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/11\/29\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Setor debate desenvolvimento urbano sustent\u00e1vel em Santa Rosa - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/11\/29\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-29T14:10:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-23T05:26:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbic.org.br\/wp-content\/uploads\/2018\/12\/g5q.jpg\" \/>\n<meta name=\"author\" content=\"Sandra Bezerra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sandra Bezerra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/11\\\/29\\\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/11\\\/29\\\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\\\/\"},\"author\":{\"name\":\"Sandra Bezerra\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\"},\"headline\":\"Setor debate desenvolvimento urbano sustent\u00e1vel em Santa Rosa\",\"datePublished\":\"2018-11-29T14:10:56+00:00\",\"dateModified\":\"2019-01-23T05:26:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/11\\\/29\\\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\\\/\"},\"wordCount\":692,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/11\\\/29\\\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/g5q.jpg\",\"articleSection\":[\"Ag\u00eancia CBIC\",\"Sustentabilidade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/11\\\/29\\\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/11\\\/29\\\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/11\\\/29\\\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\\\/\",\"name\":\"Setor debate desenvolvimento urbano sustent\u00e1vel em Santa Rosa - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/11\\\/29\\\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/11\\\/29\\\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/g5q.jpg\",\"datePublished\":\"2018-11-29T14:10:56+00:00\",\"dateModified\":\"2019-01-23T05:26:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/11\\\/29\\\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/11\\\/29\\\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/11\\\/29\\\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/g5q.jpg\",\"contentUrl\":\"https:\\\/\\\/cbic.org.br\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/g5q.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/11\\\/29\\\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Setor debate desenvolvimento urbano sustent\u00e1vel em Santa Rosa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\",\"name\":\"Sandra Bezerra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"caption\":\"Sandra Bezerra\"},\"sameAs\":[\"https:\\\/\\\/cbic.org.br\"],\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/sandra-bezerra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Setor debate desenvolvimento urbano sustent\u00e1vel em Santa Rosa - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/11\/29\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Setor debate desenvolvimento urbano sustent\u00e1vel em Santa Rosa - Comiss\u00e3o de Meio Ambiente","og_description":"...","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/11\/29\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2018-11-29T14:10:56+00:00","article_modified_time":"2019-01-23T05:26:19+00:00","og_image":[{"url":"https:\/\/cbic.org.br\/wp-content\/uploads\/2018\/12\/g5q.jpg","type":"","width":"","height":""}],"author":"Sandra Bezerra","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sandra Bezerra","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/11\/29\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/11\/29\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\/"},"author":{"name":"Sandra Bezerra","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e"},"headline":"Setor debate desenvolvimento urbano sustent\u00e1vel em Santa Rosa","datePublished":"2018-11-29T14:10:56+00:00","dateModified":"2019-01-23T05:26:19+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/11\/29\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\/"},"wordCount":692,"commentCount":0,"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/11\/29\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/wp-content\/uploads\/2018\/12\/g5q.jpg","articleSection":["Ag\u00eancia CBIC","Sustentabilidade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/11\/29\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/11\/29\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/11\/29\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\/","name":"Setor debate desenvolvimento urbano sustent\u00e1vel em Santa Rosa - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/11\/29\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/11\/29\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/wp-content\/uploads\/2018\/12\/g5q.jpg","datePublished":"2018-11-29T14:10:56+00:00","dateModified":"2019-01-23T05:26:19+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/11\/29\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/11\/29\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/11\/29\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\/#primaryimage","url":"https:\/\/cbic.org.br\/wp-content\/uploads\/2018\/12\/g5q.jpg","contentUrl":"https:\/\/cbic.org.br\/wp-content\/uploads\/2018\/12\/g5q.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/11\/29\/setor-debate-desenvolvimento-urbano-sustentavel-em-santa-rosa-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"Setor debate desenvolvimento urbano sustent\u00e1vel em Santa Rosa"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e","name":"Sandra Bezerra","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","caption":"Sandra Bezerra"},"sameAs":["https:\/\/cbic.org.br"],"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/sandra-bezerra\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/2823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=2823"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/2823\/revisions"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=2823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=2823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=2823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}