{"id":2532,"date":"2018-07-20T19:30:37","date_gmt":"2018-07-20T22:30:37","guid":{"rendered":"https:\/\/cbic.org.br\/novo_site\/sustentabilidade\/2018\/07\/20\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\/"},"modified":"2018-07-20T19:37:12","modified_gmt":"2018-07-20T22:37:12","slug":"codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2018\/07\/20\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\/","title":{"rendered":"Codese-DF mobiliza a sociedade civil organizada para pensar projetos sustent\u00e1veis para o futuro da capital do Pa\u00eds"},"content":{"rendered":"<p style=\"text-align: justify\"><em>As iniciativas v\u00e3o contemplar a\u00e7\u00f5es p\u00fablicas e privadas e ser\u00e3o apresentadas aos candidatos ao Governo do Distrito Federal no pr\u00f3ximo m\u00eas de agosto<\/em><\/p>\n<p style=\"text-align: justify\">\u201c2018-2030- O DF que a gente quer\u201d \u00e9 o nome do projeto do Conselho de Desenvolvimento Econ\u00f4mico, Sustent\u00e1vel e Estrat\u00e9gico do Distrito Federal (Codese-DF) e ser\u00e1 apresentado no pr\u00f3ximo dia 4 de agosto, no audit\u00f3rio do Museu Nacional da Rep\u00fablica, em Bras\u00edlia. A proposta de pensar o futuro de Bras\u00edlia nasceu do projeto \u201cO Futuro da Minha Cidade\u201d, realizado pela CBIC, em parceria com o Sinduscon-DF e Ademi-DF, com a correaliza\u00e7\u00e3o do Sesi Nacional e patroc\u00ednio nacional da Caixa Econ\u00f4mica Federal, com base na experi\u00eancia bem sucedida em Maring\u00e1 (PR), que tem como principal objetivo mobilizar a sociedade organizada para ser protagonista na gest\u00e3o das cidades, desenvolvendo solu\u00e7\u00f5es para a sustentabilidade urbana.<\/p>\n<p style=\"text-align: justify\">\u201cNo dia 4 de agosto, faremos uma apresenta\u00e7\u00e3o das propostas para a sociedade. N\u00e3o queremos mais altera\u00e7\u00f5es constantes, de quatro em quatro anos, no planejamento econ\u00f4mico, n\u00f3s queremos fazer algo cont\u00ednuo\u201d, disse o presidente do Codese-DF, Paulo Muniz, durante workshop do Codese-DF, nessa quinta-feira (19), no Sinduscon-DF. Para ele, o Conselho cumpriu sua miss\u00e3o e vai apresentar o documento a todos os candidatos ao Governo do Distrito Federal, ainda no m\u00eas de agosto de 2018, em nome dos setores produtivos e da sociedade civil. \u201cEstamos propondo um projeto de estado, com meta para 2030. Nesses pr\u00f3ximos 4 anos, n\u00f3s podemos plantar a semente e colher mais na frente\u201d, prev\u00ea Muniz.<\/p>\n<figure id=\"attachment_28041\" aria-describedby=\"caption-attachment-28041\" style=\"width: 683px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" width=\"683\" height=\"1024\" class=\"wp-image-2523 size-large\" src=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/07\/8-683x1024.jpg\" alt=\"\" \/><figcaption id=\"caption-attachment-28041\" class=\"wp-caption-text\">Foto: Milca Santos<\/figcaption><\/figure>\n<p style=\"text-align: justify\">A entidade prop\u00f5e uma estrutura de um modelo de trabalho para a implanta\u00e7\u00e3o de programas de planejamento e desenvolvimento sustent\u00e1vel envolvendo principais lideran\u00e7as da capital. Em Bras\u00edlia, o Conselho \u00e9 formado por 55 entidades do DF e 19 c\u00e2maras t\u00e9cnicas, e foi inspirado no modelo de Maring\u00e1 (PR) e no Codese de Goi\u00e1s. O projeto \u00e9 dividido em 19 C\u00e2maras T\u00e9cnicas (CTs) para discutir os problemas da capital e participar ativamente do planejamento e futuro da economia do Distrito Federal.<\/p>\n<p><img decoding=\"async\" width=\"976\" height=\"599\" class=\"aligncenter wp-image-2525 size-full\" src=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/07\/d.png\" alt=\"\" \/><\/p>\n<p style=\"text-align: justify\">A metodologia do projeto tem como refer\u00eancia os Objetivos de Desenvolvimento Sustent\u00e1vel (ODS), criados pelas Na\u00e7\u00f5es Unidas em 2015, e faz parte de uma nova agenda de desenvolvimento sustent\u00e1vel. \u201cOs ODS serviram como orienta\u00e7\u00e3o para cada tema discutido no Codese-DF. Existem programas internacionais que exigem as aplica\u00e7\u00f5es dos ODS e atrav\u00e9s delas conseguimos mensurar o desenvolvimento em cada setor\u201d, explica, Paulo Muniz.<\/p>\n<p style=\"text-align: justify\"><strong>NOVO VICE-PRESIDENTE EMPOSSADO NA DIRETORIA EXECUTIVA DO CODESE-DF<\/strong><\/p>\n<p style=\"text-align: justify\">Dionyzio Klavdianos, vice-presidente do Sinduscon-DF e presidente da Comiss\u00e3o de Materiais, Tecnologia, Qualidade e Produtividade (COMAT) da CBIC, foi empossado como o vice-presidente do Codese-DF. O atual presidente do Sinduscon-DF, Jo\u00e3o Pimenta, indicou Klavdianos para o cargo. Ele foi aceito unanimemente por todos os membros do Codese-DF.<\/p>\n<figure id=\"attachment_28040\" aria-describedby=\"caption-attachment-28040\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" width=\"1024\" height=\"691\" class=\"wp-image-2527 size-large\" src=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/07\/3-1-1024x691.jpg\" alt=\"\" \/><figcaption id=\"caption-attachment-28040\" class=\"wp-caption-text\">Foto: Milca Santos<\/figcaption><\/figure>\n<p style=\"text-align: justify\">O cargo era ocupado pelo presidente do Sinduscon-DF, Luiz Carlos Botelho, que faleceu no dia 5 de julho, em Bras\u00edlia. Botelho que era um grande entusiasta do projeto e foi homenageado durante o evento do Codese-DF para discutir o documento \u201c 2018-2030 &#8211; O DF que a gente quer\u201d. A pedido do presidente Paulo Muniz, foi feito 1 minuto de sil\u00eancio para as homenagens p\u00f3stumas ao irigente.<\/p>\n<p style=\"text-align: justify\">A reportagem conversou com membros de tr\u00eas C\u00e2maras T\u00e9cnicas do Codese-DF e incluiu depoimentos importantes em algumas \u00e1reas em que o Conselho ir\u00e1 atuar no Distrito Federal como Gest\u00e3o P\u00fablica, Esporte e Lazer, e Mobilidade Urbana.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"867\" height=\"1024\" class=\"wp-image-2529 size-large aligncenter\" src=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/07\/1-867x1024.jpg\" alt=\"\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As iniciativas v\u00e3o contemplar a\u00e7\u00f5es p\u00fablicas e privadas e ser\u00e3o apresentadas aos candidatos ao Governo do Distrito Federal no pr\u00f3ximo m\u00eas de agosto \u201c2018-2030- O DF que a gente quer\u201d \u00e9 o nome do projeto do Conselho de Desenvolvimento Econ\u00f4mico, Sustent\u00e1vel e Estrat\u00e9gico do Distrito [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":2537,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[97,5],"tags":[],"class_list":["post-2532","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-cbic","category-imprensa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Codese-DF mobiliza a sociedade civil organizada para pensar projetos sustent\u00e1veis para o futuro da capital do Pa\u00eds - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/07\/20\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Codese-DF mobiliza a sociedade civil organizada para pensar projetos sustent\u00e1veis para o futuro da capital do Pa\u00eds - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"As iniciativas v\u00e3o contemplar a\u00e7\u00f5es p\u00fablicas e privadas e ser\u00e3o apresentadas aos candidatos ao Governo do Distrito Federal no pr\u00f3ximo m\u00eas de agosto \u201c2018-2030- O DF que a gente quer\u201d \u00e9 o nome do projeto do Conselho de Desenvolvimento Econ\u00f4mico, Sustent\u00e1vel e Estrat\u00e9gico do Distrito [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/07\/20\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-20T22:30:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-20T22:37:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/07\/site-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"PH Freitas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"PH Freitas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/07\\\/20\\\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/07\\\/20\\\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\\\/\"},\"author\":{\"name\":\"PH Freitas\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/2cae51852e9e895aa18e04d83ad8328e\"},\"headline\":\"Codese-DF mobiliza a sociedade civil organizada para pensar projetos sustent\u00e1veis para o futuro da capital do Pa\u00eds\",\"datePublished\":\"2018-07-20T22:30:37+00:00\",\"dateModified\":\"2018-07-20T22:37:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/07\\\/20\\\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\\\/\"},\"wordCount\":627,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/07\\\/20\\\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2018\\\/07\\\/site-1-1.jpg\",\"articleSection\":[\"Ag\u00eancia CBIC\",\"Imprensa\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/07\\\/20\\\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/07\\\/20\\\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\\\/\",\"name\":\"Codese-DF mobiliza a sociedade civil organizada para pensar projetos sustent\u00e1veis para o futuro da capital do Pa\u00eds - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/07\\\/20\\\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/07\\\/20\\\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2018\\\/07\\\/site-1-1.jpg\",\"datePublished\":\"2018-07-20T22:30:37+00:00\",\"dateModified\":\"2018-07-20T22:37:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/2cae51852e9e895aa18e04d83ad8328e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/07\\\/20\\\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/07\\\/20\\\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/07\\\/20\\\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2018\\\/07\\\/site-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2018\\\/07\\\/site-1-1.jpg\",\"width\":1980,\"height\":1920,\"caption\":\"Foto: Milca Santos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/07\\\/20\\\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Codese-DF mobiliza a sociedade civil organizada para pensar projetos sustent\u00e1veis para o futuro da capital do Pa\u00eds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/2cae51852e9e895aa18e04d83ad8328e\",\"name\":\"PH Freitas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g\",\"caption\":\"PH Freitas\"},\"sameAs\":[\"https:\\\/\\\/cbic.org.br\"],\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/ph-freitas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Codese-DF mobiliza a sociedade civil organizada para pensar projetos sustent\u00e1veis para o futuro da capital do Pa\u00eds - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/07\/20\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Codese-DF mobiliza a sociedade civil organizada para pensar projetos sustent\u00e1veis para o futuro da capital do Pa\u00eds - Comiss\u00e3o de Meio Ambiente","og_description":"As iniciativas v\u00e3o contemplar a\u00e7\u00f5es p\u00fablicas e privadas e ser\u00e3o apresentadas aos candidatos ao Governo do Distrito Federal no pr\u00f3ximo m\u00eas de agosto \u201c2018-2030- O DF que a gente quer\u201d \u00e9 o nome do projeto do Conselho de Desenvolvimento Econ\u00f4mico, Sustent\u00e1vel e Estrat\u00e9gico do Distrito [&hellip;]","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/07\/20\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2018-07-20T22:30:37+00:00","article_modified_time":"2018-07-20T22:37:12+00:00","og_image":[{"width":1980,"height":1920,"url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/07\/site-1-1.jpg","type":"image\/jpeg"}],"author":"PH Freitas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"PH Freitas","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/07\/20\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/07\/20\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\/"},"author":{"name":"PH Freitas","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/2cae51852e9e895aa18e04d83ad8328e"},"headline":"Codese-DF mobiliza a sociedade civil organizada para pensar projetos sustent\u00e1veis para o futuro da capital do Pa\u00eds","datePublished":"2018-07-20T22:30:37+00:00","dateModified":"2018-07-20T22:37:12+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/07\/20\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\/"},"wordCount":627,"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/07\/20\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/07\/site-1-1.jpg","articleSection":["Ag\u00eancia CBIC","Imprensa"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/07\/20\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/07\/20\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\/","name":"Codese-DF mobiliza a sociedade civil organizada para pensar projetos sustent\u00e1veis para o futuro da capital do Pa\u00eds - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/07\/20\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/07\/20\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/07\/site-1-1.jpg","datePublished":"2018-07-20T22:30:37+00:00","dateModified":"2018-07-20T22:37:12+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/2cae51852e9e895aa18e04d83ad8328e"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/07\/20\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/07\/20\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/07\/20\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\/#primaryimage","url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/07\/site-1-1.jpg","contentUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/07\/site-1-1.jpg","width":1980,"height":1920,"caption":"Foto: Milca Santos"},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/07\/20\/codese-df-mobiliza-a-sociedade-civil-organizada-para-pensar-projetos-sustentaveis-para-o-futuro-da-capital-do-pais-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"Codese-DF mobiliza a sociedade civil organizada para pensar projetos sustent\u00e1veis para o futuro da capital do Pa\u00eds"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/2cae51852e9e895aa18e04d83ad8328e","name":"PH Freitas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g","caption":"PH Freitas"},"sameAs":["https:\/\/cbic.org.br"],"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/ph-freitas\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/2532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=2532"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/2532\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media\/2537"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=2532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=2532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=2532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}