{"id":2426,"date":"2018-05-16T11:04:58","date_gmt":"2018-05-16T14:04:58","guid":{"rendered":"https:\/\/cbic.org.br\/novo_site\/sustentabilidade\/2018\/05\/16\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\/"},"modified":"2018-05-16T11:04:58","modified_gmt":"2018-05-16T14:04:58","slug":"casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2018\/05\/16\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\/","title":{"rendered":"Casa modelo em efici\u00eancia energ\u00e9tica \u00e9 visitada por partipantes do 90\u00ba\u00a0ENIC"},"content":{"rendered":"<p style=\"text-align: justify\">A Comiss\u00e3o de Meio Ambiente da C\u00e2mara Brasileira da Constru\u00e7\u00e3o Civil (CBIC) promoveu nesta quarta-feira uma visita \u00e0 Casa Eficiente, um projeto criado pelo Programa Nacional de Conserva\u00e7\u00e3o de Energia (PROCEL), em parceria com a Universidade Federal de Santa Catarina (UFSC), Eletrosul e Eletrobras.\u00a0 A casa \u00e9 uma vitrine de tecnologia com uma s\u00e9rie de sistemas e solu\u00e7\u00f5es integradas para a efici\u00eancia energ\u00e9tica.<\/p>\n<p>Constru\u00edda para aproveitar as condi\u00e7\u00f5es clim\u00e1ticas de Santa Catarina como radia\u00e7\u00e3o solar, temperatura e umidade relativa do ar, a casa tem 200 metros e custaria em torno de R$ 400 mil, se fosse comercializada. At\u00e9 mesmo as plantas cultivadas no jardim s\u00e3o pensadas para promover um microclima agrad\u00e1vel. Na janela da cozinha, por exemplo, \u00e9 cultivado maracuj\u00e1 que faz sombra no ver\u00e3o e perde as folhas no inverno, permitindo, dessa forma, a absorvi\u00e7\u00e3o de calor. Pelo isolamento t\u00e9rmico, a casa tem uma temperatura agrad\u00e1vel em todas as esta\u00e7\u00f5es do ano.<\/p>\n<p>O aproveitamento de \u00e1gua \u00e9 outro ponto forte do projeto arquitet\u00f4nico. A \u00e1gua da chuva \u00e9 coletada por todos os telhados. Depois de utlizada em pias, vasos sanit\u00e1rios e tanque de lavar roupa, ela passa por um processo biol\u00f3gico de tratamento em tanques com casca de arroz e casca de ostras para ser reaproveitada em outras \u00e1reas.<\/p>\n<p>O objetivo da Casa Eficiente \u00e9 tornar-se uma refer\u00eancia nacional para a disseminac\u00e3o dos conceitos de efici\u00eancia energ\u00e9tica, adequac\u00e3o clim\u00e1tica e uso racional da \u00e1gua, n\u00e3o s\u00f3 para a comunidade acad\u00eamica como tamb\u00e9m para os profissionais que atuam no mercado da constru\u00e7\u00e3o civil.<\/p>\n<p>Depois de visitar a Casa Eficiente, a CMA levou um grupo de aproximadamente 40 pessoas para o Centro de Pesquisa e capacita\u00e7\u00e3o em Energia Solar da UFSC para conhecer diferentes aplica\u00e7\u00f5es da tecnologia fotovoltaica em edifica\u00e7\u00f5es. O laborat\u00f3rio, que funciona como uma vitrine desta tecnologia, implantou oito sistemas em alguns estados do Brasil para testar as diferentes tecnologias, em condi\u00e7\u00f5es clim\u00e1ticas diversas.<\/p>\n<p><strong>A visita foi uma promo\u00e7\u00e3o da CMA em parceria com o Sesi Nacional\u00a0e o Senai Nacional.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Comiss\u00e3o de Meio Ambiente da C\u00e2mara Brasileira da Constru\u00e7\u00e3o Civil (CBIC) promoveu nesta quarta-feira uma visita \u00e0 Casa Eficiente, um projeto criado pelo Programa Nacional de Conserva\u00e7\u00e3o de Energia (PROCEL), em parceria com a Universidade Federal de Santa Catarina (UFSC), Eletrosul e Eletrobras.\u00a0 A [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":2427,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[97,5],"tags":[],"class_list":["post-2426","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-cbic","category-imprensa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casa modelo em efici\u00eancia energ\u00e9tica \u00e9 visitada por partipantes do 90\u00ba\u00a0ENIC - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/05\/16\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casa modelo em efici\u00eancia energ\u00e9tica \u00e9 visitada por partipantes do 90\u00ba\u00a0ENIC - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"A Comiss\u00e3o de Meio Ambiente da C\u00e2mara Brasileira da Constru\u00e7\u00e3o Civil (CBIC) promoveu nesta quarta-feira uma visita \u00e0 Casa Eficiente, um projeto criado pelo Programa Nacional de Conserva\u00e7\u00e3o de Energia (PROCEL), em parceria com a Universidade Federal de Santa Catarina (UFSC), Eletrosul e Eletrobras.\u00a0 A [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/05\/16\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-16T14:04:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/05\/554acbc0-1de4-420b-bfb6-50036a8fbd53.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1032\" \/>\n\t<meta property=\"og:image:height\" content=\"581\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"PH Freitas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"PH Freitas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/05\\\/16\\\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/05\\\/16\\\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\\\/\"},\"author\":{\"name\":\"PH Freitas\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/2cae51852e9e895aa18e04d83ad8328e\"},\"headline\":\"Casa modelo em efici\u00eancia energ\u00e9tica \u00e9 visitada por partipantes do 90\u00ba\u00a0ENIC\",\"datePublished\":\"2018-05-16T14:04:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/05\\\/16\\\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\\\/\"},\"wordCount\":374,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/05\\\/16\\\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2018\\\/05\\\/554acbc0-1de4-420b-bfb6-50036a8fbd53.jpeg\",\"articleSection\":[\"Ag\u00eancia CBIC\",\"Imprensa\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/05\\\/16\\\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/05\\\/16\\\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\\\/\",\"name\":\"Casa modelo em efici\u00eancia energ\u00e9tica \u00e9 visitada por partipantes do 90\u00ba\u00a0ENIC - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/05\\\/16\\\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/05\\\/16\\\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2018\\\/05\\\/554acbc0-1de4-420b-bfb6-50036a8fbd53.jpeg\",\"datePublished\":\"2018-05-16T14:04:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/2cae51852e9e895aa18e04d83ad8328e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/05\\\/16\\\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/05\\\/16\\\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/05\\\/16\\\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2018\\\/05\\\/554acbc0-1de4-420b-bfb6-50036a8fbd53.jpeg\",\"contentUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2018\\\/05\\\/554acbc0-1de4-420b-bfb6-50036a8fbd53.jpeg\",\"width\":1032,\"height\":581},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/05\\\/16\\\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casa modelo em efici\u00eancia energ\u00e9tica \u00e9 visitada por partipantes do 90\u00ba\u00a0ENIC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/2cae51852e9e895aa18e04d83ad8328e\",\"name\":\"PH Freitas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g\",\"caption\":\"PH Freitas\"},\"sameAs\":[\"https:\\\/\\\/cbic.org.br\"],\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/ph-freitas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casa modelo em efici\u00eancia energ\u00e9tica \u00e9 visitada por partipantes do 90\u00ba\u00a0ENIC - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/05\/16\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\/","og_locale":"pt_BR","og_type":"article","og_title":"Casa modelo em efici\u00eancia energ\u00e9tica \u00e9 visitada por partipantes do 90\u00ba\u00a0ENIC - Comiss\u00e3o de Meio Ambiente","og_description":"A Comiss\u00e3o de Meio Ambiente da C\u00e2mara Brasileira da Constru\u00e7\u00e3o Civil (CBIC) promoveu nesta quarta-feira uma visita \u00e0 Casa Eficiente, um projeto criado pelo Programa Nacional de Conserva\u00e7\u00e3o de Energia (PROCEL), em parceria com a Universidade Federal de Santa Catarina (UFSC), Eletrosul e Eletrobras.\u00a0 A [&hellip;]","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/05\/16\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2018-05-16T14:04:58+00:00","og_image":[{"width":1032,"height":581,"url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/05\/554acbc0-1de4-420b-bfb6-50036a8fbd53.jpeg","type":"image\/jpeg"}],"author":"PH Freitas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"PH Freitas","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/05\/16\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/05\/16\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\/"},"author":{"name":"PH Freitas","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/2cae51852e9e895aa18e04d83ad8328e"},"headline":"Casa modelo em efici\u00eancia energ\u00e9tica \u00e9 visitada por partipantes do 90\u00ba\u00a0ENIC","datePublished":"2018-05-16T14:04:58+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/05\/16\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\/"},"wordCount":374,"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/05\/16\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/05\/554acbc0-1de4-420b-bfb6-50036a8fbd53.jpeg","articleSection":["Ag\u00eancia CBIC","Imprensa"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/05\/16\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/05\/16\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\/","name":"Casa modelo em efici\u00eancia energ\u00e9tica \u00e9 visitada por partipantes do 90\u00ba\u00a0ENIC - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/05\/16\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/05\/16\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/05\/554acbc0-1de4-420b-bfb6-50036a8fbd53.jpeg","datePublished":"2018-05-16T14:04:58+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/2cae51852e9e895aa18e04d83ad8328e"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/05\/16\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/05\/16\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/05\/16\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\/#primaryimage","url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/05\/554acbc0-1de4-420b-bfb6-50036a8fbd53.jpeg","contentUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/05\/554acbc0-1de4-420b-bfb6-50036a8fbd53.jpeg","width":1032,"height":581},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/05\/16\/casa-modelo-em-eficiencia-energetica-e-visitada-por-partipantes-do-90o-enic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"Casa modelo em efici\u00eancia energ\u00e9tica \u00e9 visitada por partipantes do 90\u00ba\u00a0ENIC"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/2cae51852e9e895aa18e04d83ad8328e","name":"PH Freitas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g","caption":"PH Freitas"},"sameAs":["https:\/\/cbic.org.br"],"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/ph-freitas\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/2426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=2426"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/2426\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media\/2427"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=2426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=2426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=2426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}