{"id":2353,"date":"2018-03-27T20:14:17","date_gmt":"2018-03-27T23:14:17","guid":{"rendered":"https:\/\/cbic.org.br\/novo_site\/sustentabilidade\/2018\/03\/27\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\/"},"modified":"2018-03-27T20:14:17","modified_gmt":"2018-03-27T23:14:17","slug":"8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2018\/03\/27\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\/","title":{"rendered":"8\u00aa F\u00f3rum Mundial da \u00c1gua: sess\u00f5es de encerramento definem a\u00e7\u00f5es futuras"},"content":{"rendered":"<p style=\"text-align: justify\">No 8\u00ba F\u00f3rum Mundial da \u00c1gua, realizado de 18 a 23 de mar\u00e7o em Bras\u00edlia, nas seis sess\u00f5es tem\u00e1ticas (Clima, Pessoas, Desenvolvimento, Urbano, Ecossistemas e Finan\u00e7as \u2013 sendo cada tema dividido em t\u00f3picos), foram discutidas quest\u00f5es importantes voltadas aos recursos h\u00eddricos. A C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC), em correaliza\u00e7\u00e3o com o Senai Nacional, participou na coordena\u00e7\u00e3o de dois t\u00f3picos: um do tema Urbano, que tratava de crescimento inclusivo e sustent\u00e1vel, gest\u00e3o respons\u00e1vel da \u00e1gua e ind\u00fastria; e outro do Desenvolvimento, sobre \u00e1gua e cidades.<\/p>\n<p>Cada sess\u00e3o realizada gerou um relat\u00f3rio de atividades com os principais assuntos discutidos, uma lista de recomenda\u00e7\u00f5es para a\u00e7\u00f5es a serem implementadas em curto e longo prazo, bem como potenciais atores a serem envolvidos para o alcance dos objetivos. Esses relat\u00f3rios foram discutidos por tema em sess\u00f5es de encerramento realizadas na \u00faltima quinta-feira, 22 de mar\u00e7o. A CBIC participou ativamente nas discuss\u00f5es dos temas das sess\u00f5es as quais coordenou.<\/p>\n<p>Na sess\u00e3o de encerramento do tema de Desenvolvimento, concluiu-se que \u00e9 preciso encontrar novas fontes de \u00e1gua para uso industrial, principalmente por meio do reuso e da capta\u00e7\u00e3o da \u00e1gua de chuva; haver maior compartilhamento de dados p\u00fablicos e privados; e elaborar planos de gerenciamento de recursos h\u00eddricos para ind\u00fastrias, com metas e indicadores que permitam o controle e a melhoria da efici\u00eancia h\u00eddrica. Sobre esse tema, a principal mensagem de todos os t\u00f3picos foi que, para o desenvolvimento sustent\u00e1vel, s\u00e3o necess\u00e1rios a amplia\u00e7\u00e3o do di\u00e1logo entre os diferentes atores e setores (h\u00eddrico, industrial, energ\u00e9tico, etc.) e o compartilhamento de informa\u00e7\u00f5es, experi\u00eancias e dados, de forma que todos possam evoluir em conjunto.<\/p>\n<p>J\u00e1 na sess\u00e3o de encerramento do tema Urbano, os pontos cr\u00edticos e importantes foram: implementa\u00e7\u00e3o da economia circular, que inclui reuso de \u00e1gua e recupera\u00e7\u00e3o de recursos, gerando m\u00faltiplos benef\u00edcios (social, ambiental e econ\u00f4mico); integra\u00e7\u00e3o dos princ\u00edpios de consci\u00eancia h\u00eddrica ao planejamento urbano; dissemina\u00e7\u00e3o de experi\u00eancias de aprendizagem e encorajamento ao di\u00e1logo; equidade universal ao acesso dos servi\u00e7os; e facilidade de acesso aos mecanismos de financiamento. Foi apontado ainda que as cidades s\u00e3o o maior agente para a implementa\u00e7\u00e3o dos objetivos mundialmente discutidos e para a aplica\u00e7\u00e3o de a\u00e7\u00f5es integradas \u2013 isso por meio do envolvimento dos principais atores, sendo o maior deles o pr\u00f3prio cidad\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No 8\u00ba F\u00f3rum Mundial da \u00c1gua, realizado de 18 a 23 de mar\u00e7o em Bras\u00edlia, nas seis sess\u00f5es tem\u00e1ticas (Clima, Pessoas, Desenvolvimento, Urbano, Ecossistemas e Finan\u00e7as \u2013 sendo cada tema dividido em t\u00f3picos), foram discutidas quest\u00f5es importantes voltadas aos recursos h\u00eddricos. A C\u00e2mara Brasileira da [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":2346,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[97,5],"tags":[],"class_list":["post-2353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-cbic","category-imprensa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>8\u00aa F\u00f3rum Mundial da \u00c1gua: sess\u00f5es de encerramento definem a\u00e7\u00f5es futuras - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/03\/27\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"8\u00aa F\u00f3rum Mundial da \u00c1gua: sess\u00f5es de encerramento definem a\u00e7\u00f5es futuras - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"No 8\u00ba F\u00f3rum Mundial da \u00c1gua, realizado de 18 a 23 de mar\u00e7o em Bras\u00edlia, nas seis sess\u00f5es tem\u00e1ticas (Clima, Pessoas, Desenvolvimento, Urbano, Ecossistemas e Finan\u00e7as \u2013 sendo cada tema dividido em t\u00f3picos), foram discutidas quest\u00f5es importantes voltadas aos recursos h\u00eddricos. A C\u00e2mara Brasileira da [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/03\/27\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-27T23:14:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/03\/s3eedit.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"PH Freitas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"PH Freitas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/03\\\/27\\\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/03\\\/27\\\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\\\/\"},\"author\":{\"name\":\"PH Freitas\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/2cae51852e9e895aa18e04d83ad8328e\"},\"headline\":\"8\u00aa F\u00f3rum Mundial da \u00c1gua: sess\u00f5es de encerramento definem a\u00e7\u00f5es futuras\",\"datePublished\":\"2018-03-27T23:14:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/03\\\/27\\\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\\\/\"},\"wordCount\":445,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/03\\\/27\\\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2018\\\/03\\\/s3eedit.jpg\",\"articleSection\":[\"Ag\u00eancia CBIC\",\"Imprensa\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/03\\\/27\\\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/03\\\/27\\\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\\\/\",\"name\":\"8\u00aa F\u00f3rum Mundial da \u00c1gua: sess\u00f5es de encerramento definem a\u00e7\u00f5es futuras - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/03\\\/27\\\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/03\\\/27\\\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2018\\\/03\\\/s3eedit.jpg\",\"datePublished\":\"2018-03-27T23:14:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/2cae51852e9e895aa18e04d83ad8328e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/03\\\/27\\\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/03\\\/27\\\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/03\\\/27\\\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2018\\\/03\\\/s3eedit.jpg\",\"contentUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2018\\\/03\\\/s3eedit.jpg\",\"width\":1980,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/03\\\/27\\\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"8\u00aa F\u00f3rum Mundial da \u00c1gua: sess\u00f5es de encerramento definem a\u00e7\u00f5es futuras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/2cae51852e9e895aa18e04d83ad8328e\",\"name\":\"PH Freitas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g\",\"caption\":\"PH Freitas\"},\"sameAs\":[\"https:\\\/\\\/cbic.org.br\"],\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/ph-freitas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"8\u00aa F\u00f3rum Mundial da \u00c1gua: sess\u00f5es de encerramento definem a\u00e7\u00f5es futuras - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/03\/27\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\/","og_locale":"pt_BR","og_type":"article","og_title":"8\u00aa F\u00f3rum Mundial da \u00c1gua: sess\u00f5es de encerramento definem a\u00e7\u00f5es futuras - Comiss\u00e3o de Meio Ambiente","og_description":"No 8\u00ba F\u00f3rum Mundial da \u00c1gua, realizado de 18 a 23 de mar\u00e7o em Bras\u00edlia, nas seis sess\u00f5es tem\u00e1ticas (Clima, Pessoas, Desenvolvimento, Urbano, Ecossistemas e Finan\u00e7as \u2013 sendo cada tema dividido em t\u00f3picos), foram discutidas quest\u00f5es importantes voltadas aos recursos h\u00eddricos. A C\u00e2mara Brasileira da [&hellip;]","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/03\/27\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2018-03-27T23:14:17+00:00","og_image":[{"width":1980,"height":1920,"url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/03\/s3eedit.jpg","type":"image\/jpeg"}],"author":"PH Freitas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"PH Freitas","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/03\/27\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/03\/27\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\/"},"author":{"name":"PH Freitas","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/2cae51852e9e895aa18e04d83ad8328e"},"headline":"8\u00aa F\u00f3rum Mundial da \u00c1gua: sess\u00f5es de encerramento definem a\u00e7\u00f5es futuras","datePublished":"2018-03-27T23:14:17+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/03\/27\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\/"},"wordCount":445,"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/03\/27\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/03\/s3eedit.jpg","articleSection":["Ag\u00eancia CBIC","Imprensa"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/03\/27\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/03\/27\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\/","name":"8\u00aa F\u00f3rum Mundial da \u00c1gua: sess\u00f5es de encerramento definem a\u00e7\u00f5es futuras - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/03\/27\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/03\/27\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/03\/s3eedit.jpg","datePublished":"2018-03-27T23:14:17+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/2cae51852e9e895aa18e04d83ad8328e"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/03\/27\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/03\/27\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/03\/27\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\/#primaryimage","url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/03\/s3eedit.jpg","contentUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/03\/s3eedit.jpg","width":1980,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/03\/27\/8a-forum-mundial-da-agua-sessoes-de-encerramento-definem-acoes-futuras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"8\u00aa F\u00f3rum Mundial da \u00c1gua: sess\u00f5es de encerramento definem a\u00e7\u00f5es futuras"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/2cae51852e9e895aa18e04d83ad8328e","name":"PH Freitas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c678e2a96dec8d8e07f7e75e59c120bfad0280b3f5afa76056ceb02c496758f2?s=96&d=mm&r=g","caption":"PH Freitas"},"sameAs":["https:\/\/cbic.org.br"],"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/ph-freitas\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/2353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=2353"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/2353\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media\/2346"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=2353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=2353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=2353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}