{"id":2291,"date":"2018-02-28T19:56:32","date_gmt":"2018-02-28T22:56:32","guid":{"rendered":"https:\/\/cbic.org.br\/novo_site\/sustentabilidade\/?p=2291"},"modified":"2018-03-02T15:17:18","modified_gmt":"2018-03-02T18:17:18","slug":"aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2018\/02\/28\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\/","title":{"rendered":"Aberta a Chamada P\u00fablica Procel Edifica\u200b 2018"},"content":{"rendered":"<p style=\"text-align: justify\">A Centrais El\u00e9tricas Brasileiras S.A. &#8211; Eletrobras, doravante denominada ELETROBRAS, no \u00e2mbito do Programa Nacional de Conserva\u00e7\u00e3o de Energia El\u00e9trica -PROCEL, a seguir denominado simplesmente PROCEL, torna p\u00fablico o presente Edital de CHAMADA P\u00daBLICA \u2013 01\/2018 para sele\u00e7\u00e3o de Benefici\u00e1rios para 3 (tr\u00eas) Termos de Refer\u00eancia (TRs) distintos do Procel Edifica: para oTermo de Refer\u00eancia n\u00b0. 4 (TR 4) ser\u00e3o selecionados como Benefici\u00e1rios, Construtoras e\/ou Incorporadoras; para o Termo de Refer\u00eancia n\u00b0. 5 (TR 5) ser\u00e3o selecionados como Benefici\u00e1rios, Empresas de Facilities e\/ou Administradoras Prediais; e para o Termo de Refer\u00eancia n\u00b0. 6 (TR 6) ser\u00e3o selecionados como Benefici\u00e1rios, Empresas\/Institui\u00e7\u00f5es p\u00fablicas ou privadas que possuam edifica\u00e7\u00f5es horizontalizadas, nas condi\u00e7\u00f5es e exig\u00eancias abaixo estabelecidas. As inscri\u00e7\u00f5es est\u00e3o abertas\u200b e v\u00e3o at\u00e9 2 de abril de 2018, \u00e0s 17h (hor\u00e1rio de Bras\u00edlia)\u200b\u200b. \u200bA chamada p\u00fablica selecionar\u00e1 empresas e institui\u00e7\u00f5es interessadas em receber servi\u00e7os de efici\u00eancia energ\u00e9tica em edifica\u00e7\u00f5es, que ser\u00e3o prestados por outras empresas contratadas pela Eletrobras\/ Procel, por meio de processos licitat\u00f3rios distintos. As empresas e institui\u00e7\u00f5es selecionadas na chamada p\u00fablica, denominadas benefici\u00e1rias, receber\u00e3o tais servi\u00e7os de acordo com a sua atividade e est\u00e3o divididas em tr\u00eas grupos. O primeiro \u00e9 composto por empresas de constru\u00e7\u00e3o civil (construtoras ou incorporadoras) que receber\u00e3o treinamento, consultoria e assessoria para elabora\u00e7\u00e3o de projetos com Selo Procel Edifica\u00e7\u00f5es, visando promover a efici\u00eancia energ\u00e9tica em novas edifica\u00e7\u00f5es. O segundo grupo \u00e9 formado por empresas que fazem a gest\u00e3o\/ opera\u00e7\u00e3o de edifica\u00e7\u00f5es comerciais (administradoras prediais ou empresas de facilities), as quais receber\u00e3o treinamento, consultoria e assessoria para elabora\u00e7\u00e3o de Diagn\u00f3stico Energ\u00e9tico Operacional das edifica\u00e7\u00f5es, visando promover a efici\u00eancia energ\u00e9tica em edifica\u00e7\u00f5es existentes. J\u00e1 o terceiro grupo \u00e9 constitu\u00eddo por empresas\/ institui\u00e7\u00f5es que tenham edifica\u00e7\u00f5es com grande \u00e1rea de cobertura ou telhado (edifica\u00e7\u00f5es horizontalizadas) que receber\u00e3o treinamento, consultoria para elabora\u00e7\u00e3o de Diagn\u00f3stico Energ\u00e9tico Operacional das edifica\u00e7\u00f5es, projeto de retrofit de cobertura e projeto de mini\/ micro usina de gera\u00e7\u00e3o de energia fotovoltaica ou termossolar, visando promover a gera\u00e7\u00e3o distribu\u00edda associada \u00e0 efici\u00eancia energ\u00e9tica da edifica\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify\">Para mais informa\u00e7\u00f5es sobre o Edital da Chamada P\u00fablica, acesse: <a href=\"http:\/\/www.eletrobras.com\/chamadapublicaedifica\">http:\/\/www.eletrobras.com\/chamadapublicaedifica<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Centrais El\u00e9tricas Brasileiras S.A. &#8211; Eletrobras, doravante denominada ELETROBRAS, no \u00e2mbito do Programa Nacional de Conserva\u00e7\u00e3o de Energia El\u00e9trica -PROCEL, a seguir denominado simplesmente PROCEL, torna p\u00fablico o presente Edital de CHAMADA P\u00daBLICA \u2013 01\/2018 para sele\u00e7\u00e3o de Benefici\u00e1rios para 3 (tr\u00eas) Termos de [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":2297,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[97,5,7,8,98],"tags":[102,101],"class_list":["post-2291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-cbic","category-imprensa","category-institucional","category-meio-ambiente","category-sustentabilidade","tag-eletrobras","tag-procel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aberta a Chamada P\u00fablica Procel Edifica\u200b 2018 - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/02\/28\/aberta-a-chamada-publica-procel-edifica\u200b-2018\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aberta a Chamada P\u00fablica Procel Edifica\u200b 2018 - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"A Centrais El\u00e9tricas Brasileiras S.A. &#8211; Eletrobras, doravante denominada ELETROBRAS, no \u00e2mbito do Programa Nacional de Conserva\u00e7\u00e3o de Energia El\u00e9trica -PROCEL, a seguir denominado simplesmente PROCEL, torna p\u00fablico o presente Edital de CHAMADA P\u00daBLICA \u2013 01\/2018 para sele\u00e7\u00e3o de Benefici\u00e1rios para 3 (tr\u00eas) Termos de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/02\/28\/aberta-a-chamada-publica-procel-edifica\u200b-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-28T22:56:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-02T18:17:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/02\/cma.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mariana Silveira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mariana Silveira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/02\\\/28\\\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/02\\\/28\\\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\\\/\"},\"author\":{\"name\":\"Mariana Silveira\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/603bd268fcca3c96db068d487ad37a97\"},\"headline\":\"Aberta a Chamada P\u00fablica Procel Edifica\u200b 2018\",\"datePublished\":\"2018-02-28T22:56:32+00:00\",\"dateModified\":\"2018-03-02T18:17:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/02\\\/28\\\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\\\/\"},\"wordCount\":416,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/02\\\/28\\\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2018\\\/02\\\/cma.jpg\",\"keywords\":[\"ELETROBRAS\",\"PROCEL\"],\"articleSection\":[\"Ag\u00eancia CBIC\",\"Imprensa\",\"Institucional\",\"Meio Ambiente\",\"Sustentabilidade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/02\\\/28\\\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/02\\\/28\\\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\\\/\",\"name\":\"Aberta a Chamada P\u00fablica Procel Edifica\u200b 2018 - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/02\\\/28\\\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/02\\\/28\\\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2018\\\/02\\\/cma.jpg\",\"datePublished\":\"2018-02-28T22:56:32+00:00\",\"dateModified\":\"2018-03-02T18:17:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/603bd268fcca3c96db068d487ad37a97\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/02\\\/28\\\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/02\\\/28\\\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/02\\\/28\\\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2018\\\/02\\\/cma.jpg\",\"contentUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2018\\\/02\\\/cma.jpg\",\"width\":1980,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2018\\\/02\\\/28\\\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aberta a Chamada P\u00fablica Procel Edifica\u200b 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/603bd268fcca3c96db068d487ad37a97\",\"name\":\"Mariana Silveira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f6b9548cb32a896eaaa8be55dc306cac3d5af83910785081e1cbc92018986a2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f6b9548cb32a896eaaa8be55dc306cac3d5af83910785081e1cbc92018986a2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f6b9548cb32a896eaaa8be55dc306cac3d5af83910785081e1cbc92018986a2?s=96&d=mm&r=g\",\"caption\":\"Mariana Silveira\"},\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/mariana-silveira\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aberta a Chamada P\u00fablica Procel Edifica\u200b 2018 - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/02\/28\/aberta-a-chamada-publica-procel-edifica\u200b-2018\/","og_locale":"pt_BR","og_type":"article","og_title":"Aberta a Chamada P\u00fablica Procel Edifica\u200b 2018 - Comiss\u00e3o de Meio Ambiente","og_description":"A Centrais El\u00e9tricas Brasileiras S.A. &#8211; Eletrobras, doravante denominada ELETROBRAS, no \u00e2mbito do Programa Nacional de Conserva\u00e7\u00e3o de Energia El\u00e9trica -PROCEL, a seguir denominado simplesmente PROCEL, torna p\u00fablico o presente Edital de CHAMADA P\u00daBLICA \u2013 01\/2018 para sele\u00e7\u00e3o de Benefici\u00e1rios para 3 (tr\u00eas) Termos de [&hellip;]","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/02\/28\/aberta-a-chamada-publica-procel-edifica\u200b-2018\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2018-02-28T22:56:32+00:00","article_modified_time":"2018-03-02T18:17:18+00:00","og_image":[{"width":1980,"height":1920,"url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/02\/cma.jpg","type":"image\/jpeg"}],"author":"Mariana Silveira","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mariana Silveira","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/02\/28\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/02\/28\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\/"},"author":{"name":"Mariana Silveira","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/603bd268fcca3c96db068d487ad37a97"},"headline":"Aberta a Chamada P\u00fablica Procel Edifica\u200b 2018","datePublished":"2018-02-28T22:56:32+00:00","dateModified":"2018-03-02T18:17:18+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/02\/28\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\/"},"wordCount":416,"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/02\/28\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/02\/cma.jpg","keywords":["ELETROBRAS","PROCEL"],"articleSection":["Ag\u00eancia CBIC","Imprensa","Institucional","Meio Ambiente","Sustentabilidade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/02\/28\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/02\/28\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\/","name":"Aberta a Chamada P\u00fablica Procel Edifica\u200b 2018 - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/02\/28\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/02\/28\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/02\/cma.jpg","datePublished":"2018-02-28T22:56:32+00:00","dateModified":"2018-03-02T18:17:18+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/603bd268fcca3c96db068d487ad37a97"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/02\/28\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/02\/28\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/02\/28\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\/#primaryimage","url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/02\/cma.jpg","contentUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2018\/02\/cma.jpg","width":1980,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2018\/02\/28\/aberta-a-chamada-publica-procel-edifica%e2%80%8b-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"Aberta a Chamada P\u00fablica Procel Edifica\u200b 2018"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/603bd268fcca3c96db068d487ad37a97","name":"Mariana Silveira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/2f6b9548cb32a896eaaa8be55dc306cac3d5af83910785081e1cbc92018986a2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2f6b9548cb32a896eaaa8be55dc306cac3d5af83910785081e1cbc92018986a2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2f6b9548cb32a896eaaa8be55dc306cac3d5af83910785081e1cbc92018986a2?s=96&d=mm&r=g","caption":"Mariana Silveira"},"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/mariana-silveira\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/2291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=2291"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/2291\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media\/2297"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=2291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=2291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=2291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}