{"id":2220,"date":"2017-11-16T19:11:37","date_gmt":"2017-11-16T21:11:37","guid":{"rendered":"https:\/\/cbic.org.br\/novo_site\/sustentabilidade\/2017\/11\/16\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\/"},"modified":"2017-11-16T19:11:37","modified_gmt":"2017-11-16T21:11:37","slug":"diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2017\/11\/16\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\/","title":{"rendered":"Diretoria Executiva e conselheiros do Codese-DF tomam posse no pr\u00f3ximo dia 21"},"content":{"rendered":"<p>O Conselho de Desenvolvimento Econ\u00f4mico, Sustent\u00e1vel e Estrat\u00e9gico do Distrito Federal (Codese-DF) empossa no pr\u00f3ximo dia 21 de novembro, \u00e0s 19h30, no audit\u00f3rio da Confedera\u00e7\u00e3o Nacional do Com\u00e9rcio (CNC), em Bras\u00edlia, sua Diretoria Executiva e conselheiros para o bi\u00eanio 2017\/2019. A Presid\u00eancia \u00e9 ocupada pelo presidente da Ademi-DF, Paulo Muniz, e ter\u00e1 o presidente do Sinduscon-DF, Luiz Carlos Botelho, como vice-presidente. O conselho foi criado em mar\u00e7o deste ano, por iniciativa da sociedade civil organizada, com car\u00e1ter propositivo e consultivo. O objetivo principal \u00e9 participar ativamente do planejamento econ\u00f4mico sustent\u00e1vel de Bras\u00edlia e Entorno, a curto, m\u00e9dio e longo prazo.\u00a0Segundo Botelho, as expectativas s\u00e3o de entregar, ainda neste ano, um planejamento a m\u00e9dio e longo prazo para a cidade. \u201cVamos contemplar a\u00e7\u00f5es p\u00fablicas e privadas, bem como a quest\u00e3o da escolha de par\u00e2metros de controle da execu\u00e7\u00e3o desse planejamento. Teremos metas a serem atingidas, que ser\u00e3o paralelas \u00e0s atividades governamentais\u201d, afirmou. O conselho, que tem o Sinduscon-DF como sede, j\u00e1 contempla mais de 50 entidades do DF.<\/p>\n<p>Inspirado no modelo bem-sucedido da cidade de Maring\u00e1 (PR) e no Codese-Goi\u00e2nia, o conselho do DF conta com uma mesa Diretora, Conselhos, Plen\u00e1rio e 17 C\u00e2maras T\u00e9cnicas Setoriais. As atribui\u00e7\u00f5es s\u00e3o exercidas em parceria com entidades do setor produtivo, sociedade civil e universidades. A participa\u00e7\u00e3o volunt\u00e1ria, vis\u00e3o de futuro e planejamento, suporte t\u00e9cnico profissional, foco no desenvolvimento econ\u00f4mico e social, apartidarismo e representatividade da sociedade civil organizada s\u00e3o algumas de suas caracter\u00edsticas. A proposta de pensar o futuro de Bras\u00edlia nasceu do projeto \u201cO Futuro da Minha Cidade\u201d, realizado pela CBIC, Sinduscon-DF e Ademi-DF, com a correaliza\u00e7\u00e3o do Sesi Nacional e patroc\u00ednio nacional da Caixa Econ\u00f4mica Federal, com base na experi\u00eancia bem sucedida em Maring\u00e1 (PR), que tem como principal objetivo mobilizar a sociedade organizada para ser protagonista na gest\u00e3o das cidades, desenvolvendo solu\u00e7\u00f5es para a sustentabilidade urbana. A iniciativa da entidade prop\u00f5e uma estrutura de um modelo de trabalho para a implanta\u00e7\u00e3o de programas de planejamento e desenvolvimento sustent\u00e1vel envolvendo principais lideran\u00e7as do munic\u00edpio.<\/p>\n<div><em>(Com informa\u00e7\u00f5es do Codese-DF)<\/em><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho de Desenvolvimento Econ\u00f4mico, Sustent\u00e1vel e Estrat\u00e9gico do Distrito Federal (Codese-DF) empossa no pr\u00f3ximo dia 21 de novembro, \u00e0s 19h30, no audit\u00f3rio da Confedera\u00e7\u00e3o Nacional do Com\u00e9rcio (CNC), em Bras\u00edlia, sua Diretoria Executiva e conselheiros para o bi\u00eanio 2017\/2019. A Presid\u00eancia \u00e9 ocupada pelo [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":2221,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[97,5],"tags":[],"class_list":["post-2220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-cbic","category-imprensa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diretoria Executiva e conselheiros do Codese-DF tomam posse no pr\u00f3ximo dia 21 - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2017\/11\/16\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diretoria Executiva e conselheiros do Codese-DF tomam posse no pr\u00f3ximo dia 21 - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"O Conselho de Desenvolvimento Econ\u00f4mico, Sustent\u00e1vel e Estrat\u00e9gico do Distrito Federal (Codese-DF) empossa no pr\u00f3ximo dia 21 de novembro, \u00e0s 19h30, no audit\u00f3rio da Confedera\u00e7\u00e3o Nacional do Com\u00e9rcio (CNC), em Bras\u00edlia, sua Diretoria Executiva e conselheiros para o bi\u00eanio 2017\/2019. A Presid\u00eancia \u00e9 ocupada pelo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2017\/11\/16\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-16T21:11:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2017\/11\/logo-azul.png\" \/>\n\t<meta property=\"og:image:width\" content=\"377\" \/>\n\t<meta property=\"og:image:height\" content=\"102\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sandra Bezerra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sandra Bezerra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2017\\\/11\\\/16\\\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2017\\\/11\\\/16\\\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\\\/\"},\"author\":{\"name\":\"Sandra Bezerra\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\"},\"headline\":\"Diretoria Executiva e conselheiros do Codese-DF tomam posse no pr\u00f3ximo dia 21\",\"datePublished\":\"2017-11-16T21:11:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2017\\\/11\\\/16\\\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\\\/\"},\"wordCount\":393,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2017\\\/11\\\/16\\\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2017\\\/11\\\/logo-azul.png\",\"articleSection\":[\"Ag\u00eancia CBIC\",\"Imprensa\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2017\\\/11\\\/16\\\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2017\\\/11\\\/16\\\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\\\/\",\"name\":\"Diretoria Executiva e conselheiros do Codese-DF tomam posse no pr\u00f3ximo dia 21 - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2017\\\/11\\\/16\\\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2017\\\/11\\\/16\\\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2017\\\/11\\\/logo-azul.png\",\"datePublished\":\"2017-11-16T21:11:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2017\\\/11\\\/16\\\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2017\\\/11\\\/16\\\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2017\\\/11\\\/16\\\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2017\\\/11\\\/logo-azul.png\",\"contentUrl\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2017\\\/11\\\/logo-azul.png\",\"width\":377,\"height\":102},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/en_US\\\/2017\\\/11\\\/16\\\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diretoria Executiva e conselheiros do Codese-DF tomam posse no pr\u00f3ximo dia 21\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\",\"name\":\"Sandra Bezerra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"caption\":\"Sandra Bezerra\"},\"sameAs\":[\"https:\\\/\\\/cbic.org.br\"],\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/sandra-bezerra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diretoria Executiva e conselheiros do Codese-DF tomam posse no pr\u00f3ximo dia 21 - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2017\/11\/16\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\/","og_locale":"pt_BR","og_type":"article","og_title":"Diretoria Executiva e conselheiros do Codese-DF tomam posse no pr\u00f3ximo dia 21 - Comiss\u00e3o de Meio Ambiente","og_description":"O Conselho de Desenvolvimento Econ\u00f4mico, Sustent\u00e1vel e Estrat\u00e9gico do Distrito Federal (Codese-DF) empossa no pr\u00f3ximo dia 21 de novembro, \u00e0s 19h30, no audit\u00f3rio da Confedera\u00e7\u00e3o Nacional do Com\u00e9rcio (CNC), em Bras\u00edlia, sua Diretoria Executiva e conselheiros para o bi\u00eanio 2017\/2019. A Presid\u00eancia \u00e9 ocupada pelo [&hellip;]","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2017\/11\/16\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2017-11-16T21:11:37+00:00","og_image":[{"width":377,"height":102,"url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2017\/11\/logo-azul.png","type":"image\/png"}],"author":"Sandra Bezerra","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sandra Bezerra","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2017\/11\/16\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2017\/11\/16\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\/"},"author":{"name":"Sandra Bezerra","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e"},"headline":"Diretoria Executiva e conselheiros do Codese-DF tomam posse no pr\u00f3ximo dia 21","datePublished":"2017-11-16T21:11:37+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2017\/11\/16\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\/"},"wordCount":393,"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2017\/11\/16\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2017\/11\/logo-azul.png","articleSection":["Ag\u00eancia CBIC","Imprensa"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2017\/11\/16\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2017\/11\/16\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\/","name":"Diretoria Executiva e conselheiros do Codese-DF tomam posse no pr\u00f3ximo dia 21 - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2017\/11\/16\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2017\/11\/16\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2017\/11\/logo-azul.png","datePublished":"2017-11-16T21:11:37+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2017\/11\/16\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2017\/11\/16\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2017\/11\/16\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\/#primaryimage","url":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2017\/11\/logo-azul.png","contentUrl":"https:\/\/cbic.org.br\/sustentabilidade\/wp-content\/uploads\/sites\/22\/2017\/11\/logo-azul.png","width":377,"height":102},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/en_US\/2017\/11\/16\/diretoria-executiva-e-conselheiros-do-codese-df-tomam-posse-no-proximo-dia-21\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"Diretoria Executiva e conselheiros do Codese-DF tomam posse no pr\u00f3ximo dia 21"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e","name":"Sandra Bezerra","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","caption":"Sandra Bezerra"},"sameAs":["https:\/\/cbic.org.br"],"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/sandra-bezerra\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/2220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=2220"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/2220\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media\/2221"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=2220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=2220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=2220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}