{"id":1873,"date":"2017-06-13T12:04:40","date_gmt":"2017-06-13T15:04:40","guid":{"rendered":"http:\/\/www.cbic.org.br\/sustentabilidade\/?p=1873"},"modified":"2017-06-13T12:04:40","modified_gmt":"2017-06-13T15:04:40","slug":"o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/sustentabilidade\/2017\/06\/13\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\/","title":{"rendered":"O Futuro da Minha Cidade leva a sociedade organizada de Caxias do Sul (RS) a pensar como ser\u00e1 o munic\u00edpio daqui a 20 anos"},"content":{"rendered":"<p align=\"justify\">O projeto O Futuro da Minha Cidade alcan\u00e7a hoje mais um munic\u00edpio do Sul do Pa\u00eds. Nesta ter\u00e7a-feira (13\/06) \u00e9 a vez de Caxias do Sul, no Rio Grande do Sul, conhecer a iniciativa da C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC) e discutir a import\u00e2ncia de planejar o futuro das cidades. Iniciado em 2015, o projeto desenvolvido pela Comiss\u00e3o do Meio Ambiente (CMA) da CBIC, com a correaliza\u00e7\u00e3o do Sesi Nacional e patroc\u00ednio nacional da Caixa Econ\u00f4mica Federal, j\u00e1 conquistou apaixonados por todas as regi\u00f5es do Pa\u00eds, que aderiram \u00e0 iniciativa de serem protagonistas na gest\u00e3o do futuro das suas cidades. A a\u00e7\u00e3o prop\u00f5e um modelo de parceria entre a sociedade e a prefeitura do munic\u00edpio para o desenvolvendo de solu\u00e7\u00f5es que melhorem a qualidade de vida da popula\u00e7\u00e3o para os pr\u00f3ximos anos. Promovido pelo Sindicato da Ind\u00fastria da Constru\u00e7\u00e3o Civil de Caxias do Sul (Sinduscon-Caxias), o evento reunir\u00e1 lideran\u00e7as e membros da comunidade caxiense a partir das 16h, no Hotel Intercity, em Caxias.<\/p>\n<p align=\"justify\">Nacionalmente desenvolvido pela CBIC, o projeto \u00e9 localmente realizado pelos sindicatos associados \u00e0 entidade. Segundo o ex-prefeito de Maring\u00e1 (PR) e diretor presidente da Solu\u00e7\u00e3o Consultoria, Silvio Barros, um dos palestrantes do evento, o objetivo \u00e9 provocar a sociedade organizada a discutir e planejar o futuro das suas cidades. \u201cS\u00e3o as empresas de constru\u00e7\u00e3o que constroem as cidades, sejam obras p\u00fablicas, privadas, sistema de infraestrutura, abastecimento, saneamento ou sistema vi\u00e1rio, por isso a CBIC resolveu discutir isso: que cidades s\u00e3o essas que estamos construindo para o futuro? Como a sociedade gostaria que fosse e como a gente faz todos esses esfor\u00e7os convergirem, blindando o processo de descontinuidade quando mudam os prefeitos\u201d, destaca Silvio Barros, justificando a iniciativa da CBIC, que atinge hoje 19 cidades. A l\u00f3gica, segundo ele, \u00e9 que o planejamento da cidade n\u00e3o seja do poder publico, mas da sociedade organizada, como ocorre h\u00e1 20 anos em Maring\u00e1, modelo utilizado para a iniciativa. O munic\u00edpio \u00e9 destaque nacional nas \u00e1reas socioambiental, econ\u00f4mica, de responsabilidade e gest\u00e3o, atendimento e aten\u00e7\u00e3o ao cidad\u00e3o e resultados.<\/p>\n<p align=\"justify\">O evento de Caxias do Sul tamb\u00e9m contar\u00e1 com a participa\u00e7\u00e3o da arquiteta e urbanista Laura Soares, fundadora do instituto A Cidade Precisa de Voc\u00ea, que apresentar\u00e1 sua experi\u00eancia profissional com os espa\u00e7os p\u00fablicos e a import\u00e2ncia dos mesmos para a qualidade de vida da popula\u00e7\u00e3o e da sustentabilidade. Recente iniciativa da C\u00e2mara dos Vereadores de S\u00e3o Paulo segue essa linha. De acordo com o Blog Caminhadas Urbanas \u2013 Espa\u00e7os p\u00fablicos, caminhadas e urbanidade, do jornal O Estado de S.Paulo, aguarda san\u00e7\u00e3o da prefeitura do munic\u00edpio o Estatuto do Pedestre, aprovado pela C\u00e2mara de Vereadores e que visa ajudar o gestor a tomar as decis\u00f5es certas a respeito do pedestre e fazer com que \u00f3rg\u00e3os que n\u00e3o se conversam a trabalhar juntos. A cidade ter\u00e1 uma legisla\u00e7\u00e3o que envolver\u00e1 todos os setores p\u00fablicos pela mobilidade a p\u00e9. O pedestre ser\u00e1 o centro, o foco, o receptor dos investimentos, esfor\u00e7os e a\u00e7\u00f5es. Clique aqui para mais informa\u00e7\u00f5es. <\/p>\n<p align=\"justify\">Para participar do evento, cujas inscri\u00e7\u00f5es s\u00e3o gratuitas, o Sinduscon-Caxias sugeriu a doa\u00e7\u00e3o de 1k de alimento n\u00e3o perec\u00edvel que ser\u00e1 repassado ao Banco de Alimentos de Caxias do Sul.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O projeto O Futuro da Minha Cidade alcan\u00e7a hoje mais um munic\u00edpio do Sul do Pa\u00eds. Nesta ter\u00e7a-feira (13\/06) \u00e9 a vez de Caxias do Sul, no Rio Grande do Sul, conhecer a iniciativa da C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC) e discutir a [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":1874,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[5],"tags":[],"class_list":["post-1873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-imprensa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O Futuro da Minha Cidade leva a sociedade organizada de Caxias do Sul (RS) a pensar como ser\u00e1 o munic\u00edpio daqui a 20 anos - Comiss\u00e3o de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/sustentabilidade\/2017\/06\/13\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O Futuro da Minha Cidade leva a sociedade organizada de Caxias do Sul (RS) a pensar como ser\u00e1 o munic\u00edpio daqui a 20 anos - Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"O projeto O Futuro da Minha Cidade alcan\u00e7a hoje mais um munic\u00edpio do Sul do Pa\u00eds. Nesta ter\u00e7a-feira (13\/06) \u00e9 a vez de Caxias do Sul, no Rio Grande do Sul, conhecer a iniciativa da C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC) e discutir a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/sustentabilidade\/2017\/06\/13\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-13T15:04:40+00:00\" \/>\n<meta name=\"author\" content=\"Mariana Silveira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mariana Silveira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2017\\\/06\\\/13\\\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2017\\\/06\\\/13\\\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\\\/\"},\"author\":{\"name\":\"Mariana Silveira\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/603bd268fcca3c96db068d487ad37a97\"},\"headline\":\"O Futuro da Minha Cidade leva a sociedade organizada de Caxias do Sul (RS) a pensar como ser\u00e1 o munic\u00edpio daqui a 20 anos\",\"datePublished\":\"2017-06-13T15:04:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2017\\\/06\\\/13\\\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\\\/\"},\"wordCount\":604,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2017\\\/06\\\/13\\\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Imprensa\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2017\\\/06\\\/13\\\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2017\\\/06\\\/13\\\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\\\/\",\"name\":\"O Futuro da Minha Cidade leva a sociedade organizada de Caxias do Sul (RS) a pensar como ser\u00e1 o munic\u00edpio daqui a 20 anos - Comiss\u00e3o de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2017\\\/06\\\/13\\\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2017\\\/06\\\/13\\\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2017-06-13T15:04:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/603bd268fcca3c96db068d487ad37a97\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2017\\\/06\\\/13\\\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2017\\\/06\\\/13\\\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2017\\\/06\\\/13\\\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/2017\\\/06\\\/13\\\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O Futuro da Minha Cidade leva a sociedade organizada de Caxias do Sul (RS) a pensar como ser\u00e1 o munic\u00edpio daqui a 20 anos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/\",\"name\":\"Comiss\u00e3o de Meio Ambiente\",\"description\":\"CMA - Comiss\u00e3o de Meio Ambiente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/#\\\/schema\\\/person\\\/603bd268fcca3c96db068d487ad37a97\",\"name\":\"Mariana Silveira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f6b9548cb32a896eaaa8be55dc306cac3d5af83910785081e1cbc92018986a2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f6b9548cb32a896eaaa8be55dc306cac3d5af83910785081e1cbc92018986a2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f6b9548cb32a896eaaa8be55dc306cac3d5af83910785081e1cbc92018986a2?s=96&d=mm&r=g\",\"caption\":\"Mariana Silveira\"},\"url\":\"https:\\\/\\\/cbic.org.br\\\/sustentabilidade\\\/author\\\/mariana-silveira\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O Futuro da Minha Cidade leva a sociedade organizada de Caxias do Sul (RS) a pensar como ser\u00e1 o munic\u00edpio daqui a 20 anos - Comiss\u00e3o de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/sustentabilidade\/2017\/06\/13\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\/","og_locale":"pt_BR","og_type":"article","og_title":"O Futuro da Minha Cidade leva a sociedade organizada de Caxias do Sul (RS) a pensar como ser\u00e1 o munic\u00edpio daqui a 20 anos - Comiss\u00e3o de Meio Ambiente","og_description":"O projeto O Futuro da Minha Cidade alcan\u00e7a hoje mais um munic\u00edpio do Sul do Pa\u00eds. Nesta ter\u00e7a-feira (13\/06) \u00e9 a vez de Caxias do Sul, no Rio Grande do Sul, conhecer a iniciativa da C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC) e discutir a [&hellip;]","og_url":"https:\/\/cbic.org.br\/sustentabilidade\/2017\/06\/13\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\/","og_site_name":"Comiss\u00e3o de Meio Ambiente","article_published_time":"2017-06-13T15:04:40+00:00","author":"Mariana Silveira","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mariana Silveira","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/sustentabilidade\/2017\/06\/13\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/2017\/06\/13\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\/"},"author":{"name":"Mariana Silveira","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/603bd268fcca3c96db068d487ad37a97"},"headline":"O Futuro da Minha Cidade leva a sociedade organizada de Caxias do Sul (RS) a pensar como ser\u00e1 o munic\u00edpio daqui a 20 anos","datePublished":"2017-06-13T15:04:40+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/2017\/06\/13\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\/"},"wordCount":604,"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/2017\/06\/13\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\/#primaryimage"},"thumbnailUrl":"","articleSection":["Imprensa"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/sustentabilidade\/2017\/06\/13\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\/","url":"https:\/\/cbic.org.br\/sustentabilidade\/2017\/06\/13\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\/","name":"O Futuro da Minha Cidade leva a sociedade organizada de Caxias do Sul (RS) a pensar como ser\u00e1 o munic\u00edpio daqui a 20 anos - Comiss\u00e3o de Meio Ambiente","isPartOf":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/2017\/06\/13\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/2017\/06\/13\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\/#primaryimage"},"thumbnailUrl":"","datePublished":"2017-06-13T15:04:40+00:00","author":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/603bd268fcca3c96db068d487ad37a97"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/sustentabilidade\/2017\/06\/13\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/sustentabilidade\/2017\/06\/13\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/sustentabilidade\/2017\/06\/13\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/sustentabilidade\/2017\/06\/13\/o-futuro-da-minha-cidade-leva-a-sociedade-organizada-de-caxias-do-sul-rs-a-pensar-como-sera-o-municipio-daqui-a-20-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/sustentabilidade\/"},{"@type":"ListItem","position":2,"name":"O Futuro da Minha Cidade leva a sociedade organizada de Caxias do Sul (RS) a pensar como ser\u00e1 o munic\u00edpio daqui a 20 anos"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#website","url":"https:\/\/cbic.org.br\/sustentabilidade\/","name":"Comiss\u00e3o de Meio Ambiente","description":"CMA - Comiss\u00e3o de Meio Ambiente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/sustentabilidade\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/sustentabilidade\/#\/schema\/person\/603bd268fcca3c96db068d487ad37a97","name":"Mariana Silveira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/2f6b9548cb32a896eaaa8be55dc306cac3d5af83910785081e1cbc92018986a2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2f6b9548cb32a896eaaa8be55dc306cac3d5af83910785081e1cbc92018986a2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2f6b9548cb32a896eaaa8be55dc306cac3d5af83910785081e1cbc92018986a2?s=96&d=mm&r=g","caption":"Mariana Silveira"},"url":"https:\/\/cbic.org.br\/sustentabilidade\/author\/mariana-silveira\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/1873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/comments?post=1873"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/posts\/1873\/revisions"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/media?parent=1873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/categories?post=1873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/sustentabilidade\/wp-json\/wp\/v2\/tags?post=1873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}