{"id":4452,"date":"2022-10-28T18:34:36","date_gmt":"2022-10-28T21:34:36","guid":{"rendered":"https:\/\/cbic.org.br\/juridico\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\/"},"modified":"2022-10-28T18:34:36","modified_gmt":"2022-10-28T21:34:36","slug":"construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/juridico\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\/","title":{"rendered":"Construa Minas promove Congresso Jur\u00eddico Sinduscon-MG e CBIC"},"content":{"rendered":"<p style=\"text-align: justify\">A programa\u00e7\u00e3o do Construa Minas contou com a realiza\u00e7\u00e3o do Congresso Jur\u00eddico Sinduscon-MG e CBIC. O evento, que aconteceu no dia 19\/10, em Belo Horizonte, abordou os temas \u201cV\u00edcios Construtivos nas A\u00e7\u00f5es Repetitivas\u201d, \u201cIncorpora\u00e7\u00e3o de casas e Retifica\u00e7\u00e3o de \u00e1rea \u2013 Novidades e pontos controversos da Lei 14.382\/22\u201d e \u201cDistratos: panorama atual\u201d.<\/p>\n<p style=\"text-align: justify\">Durante a abertura, o presidente do Conselho Jur\u00eddico da CBIC, Jos\u00e9 Carlos Gama, reiterou que os temas tratados s\u00e3o relevantes n\u00e3o s\u00f3 para o mercado imobili\u00e1rio, mas para a sociedade brasileira. \u201cO problema que estamos enfrentando com v\u00edcios construtivos \u00e9 algo inimagin\u00e1vel. Pouqu\u00edssimos escrit\u00f3rios de advocacia est\u00e3o denegrindo a imagem da advocacia brasileira\u201d.<\/p>\n<p style=\"text-align: justify\">Gama falou ainda sobre a nova Lei 14.382. \u201cA nova Lei 14.382 foi um trabalho bel\u00edssimo feito a quatro m\u00e3os entre n\u00f3s, incorporadores, a CBIC, a ABRAINC, o SECOVI, juntos com os administradores de im\u00f3veis mostra exatamente que o mundo mudou. N\u00f3s viramos a p\u00e1gina. N\u00f3s deixamos a realidade do mundo anal\u00f3gico para o mundo digital, que precisa acontecer em Minas Gerais e em S\u00e3o Paulo, mas principalmente no interior do Amazonas, de Rond\u00f4nia, do Amap\u00e1, do meu Cear\u00e1. Isso s\u00f3 vai acontecer com o trabalho, esfor\u00e7o e dedica\u00e7\u00e3o de todos n\u00f3s. Porque juntos somos mais fortes.\u201d<\/p>\n<p style=\"text-align: justify\">A presidente do Conselho Jur\u00eddico do Sinduscon-MG, vice-presidente da Comiss\u00e3o de Loteamento do IBRADIM e diretora adjunta do IBRADIM-MG, Diana Nacur, destacou a import\u00e2ncia do debate t\u00e9cnico. \u201c\u00c9 uma oportunidade de ter um debate t\u00e9cnico do Direito Imobili\u00e1rio e do mercado imobili\u00e1rio. A gente vive um grande desafio de unificar os entendimentos pelo Brasil afora e nada melhor que o caminho do debate t\u00e9cnico e legal para construirmos pontes e criarmos o di\u00e1logo.\u201d<\/p>\n<p style=\"text-align: justify\">O presidente da CBIC, Jos\u00e9 Carlos Martins, parabenizou a organiza\u00e7\u00e3o do evento. &#8220;Voc\u00eas v\u00e3o ver temas relevantes como v\u00edcios construtivos. Foi o que mais impactou a CBIC e temos tido muitos avan\u00e7os.&#8221;<\/p>\n<p style=\"text-align: justify\">J\u00e1 o presidente do Sinduscon-MG, Renato Michel, ressaltou a parceria na elabora\u00e7\u00e3o do encontro. \u201cO Construa foi uma iniciativa nossa em parceria com a CBIC com o objetivo de aproximar os estados e pensar a for\u00e7a do nosso setor enquanto cadeia produtiva\u201d.<\/p>\n<p style=\"text-align: justify\"><b>Painel 1 | V\u00edcios Construtivos nas A\u00e7\u00f5es Repetitivas<\/b><\/p>\n<p style=\"text-align: justify\">O diretor jur\u00eddico da Emccamp Residencial e conselheiro jur\u00eddico do Sinduscon-MG e da CBIC, Felipe Boaventura, iniciou o painel apresentando um case da empresa sobre enfrentamento das a\u00e7\u00f5es de v\u00edcios construtivos. \u201cNo terceiro trimestre do ano passado, ao fechar as nossas demonstra\u00e7\u00f5es financeiras, encerramos a auditoria jur\u00eddica com 150 a\u00e7\u00f5es de v\u00edcios construtivos. Identificamos apenas nessas a\u00e7\u00f5es R$ 104 milh\u00f5es em conting\u00eancia. Vimos que todas as a\u00e7\u00f5es tinham uma indeniza\u00e7\u00e3o como pedido padr\u00e3o. N\u00e3o havia uma \u00fanica a\u00e7\u00e3o sequer com pedido de resolu\u00e7\u00e3o do problema.\u201d<\/p>\n<p style=\"text-align: justify\">De acordo com Boaventura, a empresa utilizou uma tr\u00edade de atua\u00e7\u00e3o &#8211; criminal, t\u00e9cnica e individual (caso a caso, na defesa dos interesses da companhia) &#8211; como solu\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify\">O segundo convidado do painel, o diretor jur\u00eddico da MRV e vice-presidente da Comiss\u00e3o de Advocacia Corporativa da OAB\/MG TRF, Guilherme Freitas, ressaltou a import\u00e2ncia da conscientiza\u00e7\u00e3o do Judici\u00e1rio. \u201cO que precisamos fazer? Tem o trabalho do dia a dia de batalha nos processos, mas tem outro trabalho que vamos precisar fazer que \u00e9 de conscientiza\u00e7\u00e3o do Judici\u00e1rio. Isso para que as pessoas consigam entender que o problema n\u00e3o est\u00e1 em dois, tr\u00eas ou quatro casos, o problema est\u00e1 em 85 mil a\u00e7\u00f5es espalhadas pelo Brasil inteiro\u201d, disse.<\/p>\n<p style=\"text-align: justify\">Freitas afirmou que a companhia buscou dados de forma estrat\u00e9gica com o intuito de elaborar um relat\u00f3rio sobre o tema. \u201cN\u00f3s fizemos uma estrat\u00e9gia muito acertada e buscamos dados. Eles foram coletados por n\u00f3s e a ABRAINC fez um trabalho de enriquecimento desses dados nos tribunais. Fomos atr\u00e1s de mais informa\u00e7\u00f5es para que a gente pudesse fazer um relat\u00f3rio robusto de um diagn\u00f3stico dessa situa\u00e7\u00e3o. E seguimos para uma conversa com ju\u00edzes e magistrados sobre o que estava acontecendo\u201d.<\/p>\n<p style=\"text-align: justify\">Em sua apresenta\u00e7\u00e3o, o vice-presidente do Conjur-MG, presidente da Comiss\u00e3o de Media\u00e7\u00e3o, Concilia\u00e7\u00e3o e Arbitragem da OAB\/MG e coordenador geral das Diretorias Estaduais do IBRADIM, Francisco Maia, explicou a origem de um v\u00edcio construtivo. \u201cOs v\u00edcios construtivos come\u00e7am por uma realidade. Ningu\u00e9m nega que possa haver problema com a edifica\u00e7\u00e3o, afinal de contas uma edifica\u00e7\u00e3o \u00e9 um organismo vivo bastante complexo. \u00c9 bom que a gente entenda o conceito do v\u00edcio que passa por duas quest\u00f5es: v\u00edcios construtivos se originam dos projetos, dos materiais ou da execu\u00e7\u00e3o; n\u00e3o \u00e9 v\u00edcio construtivo aquilo que decorre do mau uso ou da aus\u00eancia de manuten\u00e7\u00e3o\u201d.<\/p>\n<p style=\"text-align: justify\">Al\u00e9m disso, Maia mencionou as principais Normas da ABNT que s\u00e3o aplic\u00e1veis ao tema:<\/p>\n<ul style=\"text-align: justify\">\n<li>NBR-13.752\/96 (Per\u00edcias de engenharia na constru\u00e7\u00e3o civil)<\/li>\n<li>NBR-15.575\/13 (Edifica\u00e7\u00f5es habitacionais \u2013 Desempenho)<\/li>\n<li>NBR-14.037\/14 (Diretrizes para elabora\u00e7\u00e3o de manuais de uso, opera\u00e7\u00e3o e manuten\u00e7\u00e3o das edifica\u00e7\u00f5es \u2013 Requisitos para elabora\u00e7\u00e3o e apresenta\u00e7\u00e3o dos conte\u00fados)<\/li>\n<li>NBR-5.674\/12 (Manuten\u00e7\u00e3o de edifica\u00e7\u00f5es \u2013 requisitos para o sistema de gest\u00e3o de manuten\u00e7\u00e3o)<\/li>\n<li>NBR-5.671\/90 (Participa\u00e7\u00e3o dos intervenientes em servi\u00e7os e obras de engenharia e arquitetura)<\/li>\n<li>NBR-16747\/20 (Inspe\u00e7\u00e3o predial &#8211; Diretrizes, conceitos, terminologia e procedimento)<\/li>\n<\/ul>\n<p style=\"text-align: justify\"><b>Painel 2 | Incorpora\u00e7\u00e3o de casas e Retifica\u00e7\u00e3o de \u00e1rea &#8211; Novidades e pontos controversos da Lei 14.382\/22<\/b><\/p>\n<p style=\"text-align: justify\">Segundo o advogado especialista em Direito Imobili\u00e1rio,s\u00f3cio no Azevedo Sette Advogados e conselheiro jur\u00eddico do Sinduscon-MG, Henrique Antonelli, a retifica\u00e7\u00e3o de \u00e1rea \u00e9 um momento que antecede grande parte dos empreendimentos imobili\u00e1rios. \u201cA necessidade da retifica\u00e7\u00e3o para trazer a realidade da matr\u00edcula \u00e9 algo que traz seguran\u00e7a para todos\u201d, afirmou.<\/p>\n<p style=\"text-align: justify\">Sobre as novidades da nova Lei, Antonelli citou: exclus\u00e3o da possibilidade de anu\u00eancia exclusiva do ocupante; direitos reais e gravames &#8211; exclus\u00e3o somente dos direitos reais de garantia (credor hipotec\u00e1rio, pignorat\u00edcio e de aliena\u00e7\u00e3o fiduci\u00e1ria); e inclus\u00e3o dos detentores de direitos reais e aquisitivos dos im\u00f3veis cont\u00edguos.<\/p>\n<p style=\"text-align: justify\">No \u00e2mbito da incorpora\u00e7\u00e3o de casas, o vice-presidente de Rela\u00e7\u00f5es Institucionais do CORI-MG, diretor do IRIB e Oficial do Registro de Im\u00f3veis de Vespasiano, Luciano Camargos, apresentou pontos da nova reda\u00e7\u00e3o da Lei. S\u00e3o eles:<\/p>\n<ul style=\"text-align: justify\">\n<li>\u201cRegra do jogo\u201d definida \u2013 seguran\u00e7a jur\u00eddica (distratos, consequ\u00eancias do atraso nas obras, destitui\u00e7\u00e3o do incorporador, comiss\u00e3o de representantes);<\/li>\n<li>Necessidade de registro do memorial de incorpora\u00e7\u00e3o, simplificado em raz\u00e3o das peculiaridades dessa modalidade;<\/li>\n<li>Possibilidade de afeta\u00e7\u00e3o de patrim\u00f4nio \u2013 seguran\u00e7a para os adquirentes;<\/li>\n<li>Art. 237-A \u2013 ato \u00fanico \u2013 redu\u00e7\u00e3o de custos e competitividade;<\/li>\n<li>RET \u2013 redu\u00e7\u00e3o substancial de carga tribut\u00e1ria.<\/li>\n<\/ul>\n<p style=\"text-align: justify\"><b>Painel 3 | Distratos: panorama atual<\/b><\/p>\n<p style=\"text-align: justify\">Eduardo Cordeiro, s\u00f3cio de Ferreira Pinto, Cordeiro, Santos e Maia Advogados (MG, RJ e SP), diretor Estadual do IBRADIM-MG, Conselheiro Jur\u00eddico do Sinduscon-MG e coordenador de Constru\u00e7\u00e3o na Comiss\u00e3o de Direito Imobili\u00e1rio da OAB\/MG, tratou sobre a Lei n\u00ba 13.786\/18, que visa disciplinar a resolu\u00e7\u00e3o do contrato por inadimplemento do adquirente de unidade imobili\u00e1ria em incorpora\u00e7\u00e3o imobili\u00e1ria e em parcelamento de solo urbano.<\/p>\n<p style=\"text-align: justify\">De acordo com Cordeiro, a Lei apresenta virtudes como: previsibilidade; seguran\u00e7a jur\u00eddica; prote\u00e7\u00e3o e equil\u00edbrio ao sistema; rigor formal \u2013 quadro resumo \u2013 dever de informa\u00e7\u00e3o (Art. 35-A); est\u00edmulo \u00e0 utiliza\u00e7\u00e3o do patrim\u00f4nio de afeta\u00e7\u00e3o; bilateralidade e equival\u00eancia entre as obriga\u00e7\u00f5es do incorporador e as dos adquirentes; par\u00e2metros objetivos claros que suprem lacuna legislativa e afastam subjetivismo e interesse coletivo em detrimento do individual.<\/p>\n<p style=\"text-align: justify\">O especialista tamb\u00e9m citou os pontos de aten\u00e7\u00e3o: adequa\u00e7\u00e3o da promessa de compra e venda utilizada; altera\u00e7\u00f5es aplic\u00e1veis \u00e0s vendas de im\u00f3veis \u201cna planta\u201d posteriores \u00e0 vig\u00eancia da Lei n\u00ba 13.786\/2018; S\u00famula 543 do STJ aplic\u00e1vel a contratos antigos sujeitos ao CDC; regras espec\u00edficas quando h\u00e1 disponibiliza\u00e7\u00e3o da unidade; prazos de pagamento das restitui\u00e7\u00f5es; hip\u00f3teses de n\u00e3o incid\u00eancia da cl\u00e1usula penal e de antecipa\u00e7\u00e3o das restitui\u00e7\u00f5es e marco inicial dos juros morat\u00f3rios nas a\u00e7\u00f5es que discutem cl\u00e1usulas penais de promessas anteriores \u00e0 Lei 13.786\/2018 \u2013 Tr\u00e2nsito em julgado \u2013 Tese fixada pelo STJ no REsp. 1.740.911 &#8211; DF.<\/p>\n<p style=\"text-align: justify\">Tamb\u00e9m participaram deste painel:<\/p>\n<ul style=\"text-align: justify\">\n<li>M\u00e1rcia Bonilha Novo \u2013 Advogada, Especialista e Mestre em Processo Civil pela PUC\/SP. Possui Certifica\u00e7\u00f5es Profissionais em Compliance e integra a Comunidade ESG do Instituto Brasileiro de Governan\u00e7a Corporativa \u2013 IBGC<\/li>\n<li>Laura Henriques \u2013 Advogada formada pela UFMG e membra do Conselho Jur\u00eddico do Sinduscon\/MG (atua como Diretora Jur\u00eddica da Direcional Engenharia desde 2015)<\/li>\n<\/ul>\n<h3 style=\"text-align: justify\"><span style=\"font-size: 12pt\"><b>\u201cConstrua \u2013 Onde a Constru\u00e7\u00e3o do Brasil se encontra\u201d<\/b><\/span><\/h3>\n<p style=\"text-align: justify\">O Congresso Jur\u00eddico integrou o \u201cConstrua \u2013 Onde a Constru\u00e7\u00e3o do Brasil se encontra\u201d, programa\u00e7\u00e3o anual que pretende percorrer todos os estados e o Distrito Federal para discutir com especialistas da ind\u00fastria da constru\u00e7\u00e3o temas estrat\u00e9gicos do setor e do mercado imobili\u00e1rio em n\u00edvel nacional e estadual.<\/p>\n<p style=\"text-align: justify\">\u201cO \u2018Construa\u2019 \u00e9 a CBIC chegando aos estados para fortalecer a ind\u00fastria da constru\u00e7\u00e3o nacional, com debates sobre a agenda nacional\u201d, salienta o presidente da entidade, Jos\u00e9 Carlos Martins.<\/p>\n<p style=\"text-align: justify\">O objetivo \u00e9 unir localmente o maior n\u00famero poss\u00edvel de agentes regionais da cadeia de produ\u00e7\u00e3o de habita\u00e7\u00f5es, empresas, creches, hospitais, escolas, pr\u00e9dios, pontes, viadutos, t\u00faneis, rodovias, ferrovias e barragens para ampliar o debate sobre temas de grande relev\u00e2ncia para o setor da constru\u00e7\u00e3o e fortalecer as entidades locais associadas \u00e0 CBIC.<\/p>\n<p style=\"text-align: justify\">O evento \u00e9 uma iniciativa da C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC) e do Sindicato da Ind\u00fastria da Constru\u00e7\u00e3o Civil no Estado de Minas Gerais (Sinduscon-MG), com apoio do Sebrae.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A programa\u00e7\u00e3o do Construa Minas contou com a realiza\u00e7\u00e3o do Congresso Jur\u00eddico Sinduscon-MG e CBIC. O evento, que aconteceu no dia 19\/10, em Belo Horizonte, abordou os temas \u201cV\u00edcios Construtivos nas A\u00e7\u00f5es Repetitivas\u201d, \u201cIncorpora\u00e7\u00e3o de casas e Retifica\u00e7\u00e3o de \u00e1rea \u2013 Novidades e pontos controversos [&hellip;]<\/p>\n","protected":false},"author":1414,"featured_media":4453,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[64],"tags":[],"class_list":["post-4452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juridico-agencia-cbic"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Construa Minas promove Congresso Jur\u00eddico Sinduscon-MG e CBIC - Conselho Jur\u00eddico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/juridico\/en_US\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Construa Minas promove Congresso Jur\u00eddico Sinduscon-MG e CBIC - Conselho Jur\u00eddico\" \/>\n<meta property=\"og:description\" content=\"A programa\u00e7\u00e3o do Construa Minas contou com a realiza\u00e7\u00e3o do Congresso Jur\u00eddico Sinduscon-MG e CBIC. O evento, que aconteceu no dia 19\/10, em Belo Horizonte, abordou os temas \u201cV\u00edcios Construtivos nas A\u00e7\u00f5es Repetitivas\u201d, \u201cIncorpora\u00e7\u00e3o de casas e Retifica\u00e7\u00e3o de \u00e1rea \u2013 Novidades e pontos controversos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/juridico\/en_US\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\/\" \/>\n<meta property=\"og:site_name\" content=\"Conselho Jur\u00eddico\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-28T21:34:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbic.org.br\/juridico\/wp-content\/uploads\/sites\/24\/2022\/10\/whatsapp-image-2022-10-28-at-185036.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"719\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jornalistacbic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jornalistacbic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\\\/\"},\"author\":{\"name\":\"jornalistacbic\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/#\\\/schema\\\/person\\\/654b120bcd86d07c9f9dc286ecc91681\"},\"headline\":\"Construa Minas promove Congresso Jur\u00eddico Sinduscon-MG e CBIC\",\"datePublished\":\"2022-10-28T21:34:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\\\/\"},\"wordCount\":1688,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2022\\\/10\\\/whatsapp-image-2022-10-28-at-185036.jpeg\",\"articleSection\":[\"Jur\u00eddico\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\\\/\",\"name\":\"Construa Minas promove Congresso Jur\u00eddico Sinduscon-MG e CBIC - Conselho Jur\u00eddico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2022\\\/10\\\/whatsapp-image-2022-10-28-at-185036.jpeg\",\"datePublished\":\"2022-10-28T21:34:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/#\\\/schema\\\/person\\\/654b120bcd86d07c9f9dc286ecc91681\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2022\\\/10\\\/whatsapp-image-2022-10-28-at-185036.jpeg\",\"contentUrl\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2022\\\/10\\\/whatsapp-image-2022-10-28-at-185036.jpeg\",\"width\":1600,\"height\":719},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Construa Minas promove Congresso Jur\u00eddico Sinduscon-MG e CBIC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/\",\"name\":\"Conselho Jur\u00eddico\",\"description\":\"CONJUR - Conselho Jur\u00eddico\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/#\\\/schema\\\/person\\\/654b120bcd86d07c9f9dc286ecc91681\",\"name\":\"jornalistacbic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa24f0ed442729cb89355c4b9cd7ab747f7f3fa236417c2717409c63e87c39e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa24f0ed442729cb89355c4b9cd7ab747f7f3fa236417c2717409c63e87c39e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa24f0ed442729cb89355c4b9cd7ab747f7f3fa236417c2717409c63e87c39e?s=96&d=mm&r=g\",\"caption\":\"jornalistacbic\"},\"url\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/author\\\/jornalistacbic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Construa Minas promove Congresso Jur\u00eddico Sinduscon-MG e CBIC - Conselho Jur\u00eddico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/juridico\/en_US\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\/","og_locale":"pt_BR","og_type":"article","og_title":"Construa Minas promove Congresso Jur\u00eddico Sinduscon-MG e CBIC - Conselho Jur\u00eddico","og_description":"A programa\u00e7\u00e3o do Construa Minas contou com a realiza\u00e7\u00e3o do Congresso Jur\u00eddico Sinduscon-MG e CBIC. O evento, que aconteceu no dia 19\/10, em Belo Horizonte, abordou os temas \u201cV\u00edcios Construtivos nas A\u00e7\u00f5es Repetitivas\u201d, \u201cIncorpora\u00e7\u00e3o de casas e Retifica\u00e7\u00e3o de \u00e1rea \u2013 Novidades e pontos controversos [&hellip;]","og_url":"https:\/\/cbic.org.br\/juridico\/en_US\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\/","og_site_name":"Conselho Jur\u00eddico","article_published_time":"2022-10-28T21:34:36+00:00","og_image":[{"width":1600,"height":719,"url":"https:\/\/cbic.org.br\/juridico\/wp-content\/uploads\/sites\/24\/2022\/10\/whatsapp-image-2022-10-28-at-185036.jpeg","type":"image\/jpeg"}],"author":"jornalistacbic","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jornalistacbic","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/juridico\/en_US\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/juridico\/en_US\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\/"},"author":{"name":"jornalistacbic","@id":"https:\/\/cbic.org.br\/juridico\/en_US\/#\/schema\/person\/654b120bcd86d07c9f9dc286ecc91681"},"headline":"Construa Minas promove Congresso Jur\u00eddico Sinduscon-MG e CBIC","datePublished":"2022-10-28T21:34:36+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/juridico\/en_US\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\/"},"wordCount":1688,"commentCount":0,"image":{"@id":"https:\/\/cbic.org.br\/juridico\/en_US\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/juridico\/wp-content\/uploads\/sites\/24\/2022\/10\/whatsapp-image-2022-10-28-at-185036.jpeg","articleSection":["Jur\u00eddico"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cbic.org.br\/juridico\/en_US\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/juridico\/en_US\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\/","url":"https:\/\/cbic.org.br\/juridico\/en_US\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\/","name":"Construa Minas promove Congresso Jur\u00eddico Sinduscon-MG e CBIC - Conselho Jur\u00eddico","isPartOf":{"@id":"https:\/\/cbic.org.br\/juridico\/en_US\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/juridico\/en_US\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/juridico\/en_US\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/juridico\/wp-content\/uploads\/sites\/24\/2022\/10\/whatsapp-image-2022-10-28-at-185036.jpeg","datePublished":"2022-10-28T21:34:36+00:00","author":{"@id":"https:\/\/cbic.org.br\/juridico\/en_US\/#\/schema\/person\/654b120bcd86d07c9f9dc286ecc91681"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/juridico\/en_US\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/juridico\/en_US\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/juridico\/en_US\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\/#primaryimage","url":"https:\/\/cbic.org.br\/juridico\/wp-content\/uploads\/sites\/24\/2022\/10\/whatsapp-image-2022-10-28-at-185036.jpeg","contentUrl":"https:\/\/cbic.org.br\/juridico\/wp-content\/uploads\/sites\/24\/2022\/10\/whatsapp-image-2022-10-28-at-185036.jpeg","width":1600,"height":719},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/juridico\/en_US\/construa-minas-promove-congresso-juridico-sinduscon-mg-e-cbic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/juridico\/"},{"@type":"ListItem","position":2,"name":"Construa Minas promove Congresso Jur\u00eddico Sinduscon-MG e CBIC"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/juridico\/en_US\/#website","url":"https:\/\/cbic.org.br\/juridico\/en_US\/","name":"Conselho Jur\u00eddico","description":"CONJUR - Conselho Jur\u00eddico","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/juridico\/en_US\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/juridico\/en_US\/#\/schema\/person\/654b120bcd86d07c9f9dc286ecc91681","name":"jornalistacbic","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/5aa24f0ed442729cb89355c4b9cd7ab747f7f3fa236417c2717409c63e87c39e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5aa24f0ed442729cb89355c4b9cd7ab747f7f3fa236417c2717409c63e87c39e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5aa24f0ed442729cb89355c4b9cd7ab747f7f3fa236417c2717409c63e87c39e?s=96&d=mm&r=g","caption":"jornalistacbic"},"url":"https:\/\/cbic.org.br\/juridico\/author\/jornalistacbic\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/juridico\/wp-json\/wp\/v2\/posts\/4452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/juridico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/juridico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/juridico\/wp-json\/wp\/v2\/users\/1414"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/juridico\/wp-json\/wp\/v2\/comments?post=4452"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/juridico\/wp-json\/wp\/v2\/posts\/4452\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/juridico\/wp-json\/wp\/v2\/media\/4453"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/juridico\/wp-json\/wp\/v2\/media?parent=4452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/juridico\/wp-json\/wp\/v2\/categories?post=4452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/juridico\/wp-json\/wp\/v2\/tags?post=4452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}