{"id":3740,"date":"2020-03-12T12:18:32","date_gmt":"2020-03-12T15:18:32","guid":{"rendered":"https:\/\/cbic.org.br\/juridico\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\/"},"modified":"2020-03-12T12:18:46","modified_gmt":"2020-03-12T15:18:46","slug":"conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/juridico\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\/","title":{"rendered":"Conselho Jur\u00eddico debate medidas cartor\u00e1rias que impactam o setor"},"content":{"rendered":"<p>Os provimentos 88 e 89 do Conselho Nacional de Justi\u00e7a (CNJ), que tratam sobre regulamenta\u00e7\u00e3o das medidas de combate \u00e0 lavagem de dinheiro, modificando como devem ser feitos os atos imobili\u00e1rios que repercutam nos cart\u00f3rios, al\u00e9m da regulamenta\u00e7\u00e3o do C\u00f3digo Nacional de Matr\u00edculas (CNM), foram os destaques da reuni\u00e3o de ter\u00e7a-feira (10) do Conselho Jur\u00eddico (Conjur) da C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC).<\/p>\n<p>Bernardo Chezzi, do Sindicato da Ind\u00fastria da Constru\u00e7\u00e3o Civil da Bahia (Sinduscon-BA), atualizou os associados sobre o Provimento 88 do CNJ \u2013 que busca regulamentar para os cart\u00f3rios as medidas exigidas pela lei federal 9.613 de 1998, do combate \u00e0 lavagem de dinheiro, modificando como devem ser feitos os atos imobili\u00e1rios que repercutam nos cart\u00f3rios. \u201cA Caixa j\u00e1 come\u00e7ou a mudar os contratos. Alguns cart\u00f3rios d\u00e3o notas de exig\u00eancia da origem do dinheiro, mas esse n\u00e3o \u00e9 meu entendimento\u201d, frisou.<\/p>\n<p>Representante do Sindicato da Ind\u00fastria Constru\u00e7\u00e3o Civil do Cear\u00e1 (Sinduscon-CE), Victor Reis fez uma apresenta\u00e7\u00e3o sobre o provimento 89 do CNJ, que regulamenta o C\u00f3digo Nacional de Matr\u00edculas (CNM), e explicou que o objetivo do provimento \u00e9 facilitar interc\u00e2mbio de informa\u00e7\u00f5es. \u201cO acesso ser\u00e1 disponibilizado de qualquer lugar do pa\u00eds, mas vale destacar que n\u00e3o necessariamente \u00e9 onde se protocola que o processo ser\u00e1 analisado\u201d.<\/p>\n<p>Reis informou que as mudan\u00e7as ser\u00e3o v\u00e1lidas para matr\u00edculas ap\u00f3s implanta\u00e7\u00e3o do Sistema de Registro Eletr\u00f4nico de Im\u00f3veis (SREI). \u201cO sistema busca universalizar as atividades de registro p\u00fablico imobili\u00e1rio, garantir a seguran\u00e7a da informa\u00e7\u00e3o e promover a interconex\u00e3o das serventias\u201d. J\u00e1 sobre o Servi\u00e7o de Atendimento Eletr\u00f4nico Compartilhado (SAEC) as consultas de informa\u00e7\u00f5es sobre a rela\u00e7\u00e3o de cart\u00f3rios, circunscri\u00e7\u00e3o e tabela de custas ser\u00e3o p\u00fablicas.<\/p>\n<p>\u201cDessa forma \u00e9 poss\u00edvel mensurar o valor das custas em qualquer estado do Pa\u00eds\u201d, complementou Reis. Em rela\u00e7\u00e3o ao estatuto do Operador Nacional do Sistema de Registro Eletr\u00f4nico (ONR), Reis afirmou que o instituto ainda n\u00e3o est\u00e1 institu\u00eddo e precisa ser aprovado pelos oficiais de registro de im\u00f3veis de todo territ\u00f3rio nacional, em assembleia geral, que em breve ser\u00e1 agendada.<\/p>\n<p>Arthur Rios J\u00fanior, do Sindicato da Ind\u00fastria da Constru\u00e7\u00e3o Civil de Goi\u00e1s (Sinduscon-GO), abordou um estudo sobre a possibilidade ou n\u00e3o de aplica\u00e7\u00e3o de recupera\u00e7\u00e3o judicial em caso de patrim\u00f4nio de afeta\u00e7\u00e3o. Segundo o advogado, &#8220;n\u00e3o h\u00e1 norma expl\u00edcita sobre a participa\u00e7\u00e3o ou n\u00e3o da sociedade empres\u00e1ria com regime de patrim\u00f4nio de afeta\u00e7\u00e3o na recupera\u00e7\u00e3o judicial, mas se na fal\u00eancia n\u00e3o participa, na mesma linha, na recupera\u00e7\u00e3o n\u00e3o deve participar tamb\u00e9m\u201d.<\/p>\n<p>Segundo o presidente do Conjur, Jos\u00e9 Carlos Gama, o conselho atua h\u00e1 5 anos fomentando o debate para atualizar os associados em rela\u00e7\u00e3o a assuntos de grande relev\u00e2ncia para a ind\u00fastria da constru\u00e7\u00e3o e em rela\u00e7\u00e3o a recupera\u00e7\u00e3o judicial questiona se seria justo uma sociedade empres\u00e1ria ter patrim\u00f4nio de afeta\u00e7\u00e3o e n\u00e3o poder fazer recupera\u00e7\u00e3o judicial. Vamos buscar uma resposta sobre essa quest\u00e3o e apresent\u00e1-la para o setor durante o Encontro Nacional da Ind\u00fastria da Constru\u00e7\u00e3o (ENIC)\u201d, reiterou Gama.<\/p>\n<p>Ao fazer uma an\u00e1lise da influ\u00eancia e repercuss\u00f5es da lei de prote\u00e7\u00e3o de dados em rela\u00e7\u00e3o \u00e0s matr\u00edculas e certid\u00f5es cartoriais, Carlos Augusto Leal, do Sindicato da Ind\u00fastria da Constru\u00e7\u00e3o Civil do Esp\u00edrito Santo (Sinduscon-ES), destacou que a Lei Geral de Prote\u00e7\u00e3o de Dados dialoga com facilidade com os cart\u00f3rios, desde que sigam o princ\u00edpio da publicidade. \u201cOs titulares de cart\u00f3rios de notas e of\u00edcios de registro de im\u00f3veis submetidos \u00e0s regras de prote\u00e7\u00e3o de dados, devem fornecer as informa\u00e7\u00f5es as partes quando solicitadas\u201d.<\/p>\n<p>Leal acredita que, apesar do tema ser importante, nem as empresas privadas nem os cart\u00f3rios t\u00eam tido essa preocupa\u00e7\u00e3o. \u201cPrecisamos saber que medidas foram implementadas para prover a prote\u00e7\u00e3o dos dados, j\u00e1 que a estrutura\u00e7\u00e3o de verifica\u00e7\u00e3o de seguran\u00e7a envolve a localiza\u00e7\u00e3o, compartilhamento e armazenamento \u2013 mapeamento de tratamento de dados, al\u00e9m da pol\u00edtica interna para prote\u00e7\u00e3o\u201d, afirmou.<\/p>\n<p>Luiz Felipe Cunha, da Associa\u00e7\u00e3o de Empresas do Mercado Imobili\u00e1rio de Pernambuco (Ademi-PE), esclareceu sobre autentica\u00e7\u00e3o de c\u00f3pia de documentos, afirmando ser poss\u00edvel a declara\u00e7\u00e3o de autenticidade por advogado em alguns casos. \u201cHoje \u00e9 legal um advogado declarar a autenticidade de documentos perante procedimentos administrativos nos Cart\u00f3rios de Im\u00f3veis. Apesar de n\u00e3o pretender usurpar a compet\u00eancia dos tabeli\u00e3es \u00e9 not\u00f3rio que os Poderes Legislativo e Judici\u00e1rio, por meio de jurisprud\u00eancia, conferem essa prerrogativa para os advogados, no sentido de que possam sim conferir autenticidade \u00e0s c\u00f3pias de documentos, passando estas a produzirem efic\u00e1cia como se originais fossem, responsabilizando-os em caso de falsidade\u201d, explicou Cunha.<\/p>\n<p>Cunha esclareceu tamb\u00e9m que o reconhecimento de firma para atos praticados por pessoa f\u00edsica junto aos cart\u00f3rios n\u00e3o \u00e9 mais necess\u00e1rio. \u201cO legislador literalmente extinguiu a exig\u00eancia de reconhecimento de firma em processos administrativos perante os \u00f3rg\u00e3os p\u00fablicos. Entende o assessor jur\u00eddico que os Cart\u00f3rios de Im\u00f3veis s\u00e3o prestadores de servi\u00e7os p\u00fablicos por delega\u00e7\u00e3o, logo, equipar\u00e1veis a um \u00f3rg\u00e3o p\u00fablico, ent\u00e3o n\u00e3o haveria sentido em manter a exig\u00eancia de reconhecimento de firmas para procedimentos administrativos que tramitarem nessas serventias\u201d, informou.<\/p>\n<p>Danila Oleinik, da Associa\u00e7\u00e3o Brasileira de Incorporadoras Imobili\u00e1rias de S\u00e3o Paulo (Abrainc-SP), tratou sobre rescis\u00e3o de aliena\u00e7\u00e3o fiduci\u00e1ria. \u201c\u00c9 preocupante como essa tem\u00e1tica tem sido enfraquecida com decis\u00f5es judiciais que est\u00e3o reconhecendo a possibilidade de rescis\u00e3o dos contratos de compra e venda de im\u00f3veis garantidos por pacto de aliena\u00e7\u00e3o fiduci\u00e1ria, com a consequente devolu\u00e7\u00e3o de parcelas pagas aos consumidores\u201d, afirmou Oleinki, destacando tamb\u00e9m os principais desafios enfrentados pelas empresas nos tribunais, que devem ser trabalhados no Superior Tribunal de Justi\u00e7a (STJ).<\/p>\n<p>Os assuntos tratados na reuni\u00e3o t\u00eam interface com o projeto \u2018Di\u00e1logos Tem\u00e1ticos CBIC\u2019 em correaliza\u00e7\u00e3o com o Servi\u00e7o Nacional de Aprendizagem Industrial (Senai Nacional).<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Conhe\u00e7a o Conjur\/CBIC<\/strong><\/h2>\n<figure id=\"attachment_46837\" aria-describedby=\"caption-attachment-46837\" style=\"width: 2560px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-46837 size-full\" src=\"https:\/\/cbic.org.br\/wp-content\/uploads\/2020\/03\/Conjur-scaled.jpg\" alt=\"\" \/><figcaption id=\"caption-attachment-46837\" class=\"wp-caption-text\">Membros do Conjur\/CBIC, durante reuni\u00e3o do dia 10\/03, em Bras\u00edlia (Foto: PH Freitas)<\/figcaption><\/figure>\n<p>O Conselho Jur\u00eddico \u00e9 uma das comiss\u00f5es tem\u00e1ticas da CBIC. Integrado por advogados e assessores jur\u00eddicos das entidades filiadas, tem como objetivo desenvolver estudos, debates e discuss\u00f5es quanto aos aspectos jur\u00eddicos das quest\u00f5es nacionais de interesse do setor da constru\u00e7\u00e3o e do setor imobili\u00e1rio. Re\u00fane-se trimestralmente para discutir quest\u00f5es jur\u00eddicas relevantes surgidas com as publica\u00e7\u00f5es de leis, medidas provis\u00f3rias e decretos do Poder Executivo Federal, com a institui\u00e7\u00e3o de planos econ\u00f4micos, e com a ado\u00e7\u00e3o de medidas administrativas e Judiciais que envolvam direta ou indiretamente o setor da constru\u00e7\u00e3o civil.<\/p>\n<p>O Conjur\/CBIC engloba grupos espec\u00edficos de trabalho que atuam nos mais diversos ramos do direito, assim definidos:<\/p>\n<ul>\n<li>Grupo de Trabalho Administrativo\/Constitucional<\/li>\n<li>Grupo de Trabalho Ambiental\/Imobili\u00e1rio<\/li>\n<li>Grupo de Trabalho Civil\/Consumidor<\/li>\n<li>Grupo de Trabalho Trabalhista\/Previdenci\u00e1rio<\/li>\n<li>Grupo de Trabalho Tribut\u00e1rio<\/li>\n<\/ul>\n<p>As \u00e1reas de discuss\u00e3o podem englobar qualquer ramo do direito, especialmente, direito civil, administrativo, constitucional, tribut\u00e1rio, previdenci\u00e1rio, ambiental, trabalhista, entre outros, a depender da pauta espec\u00edfica da reuni\u00e3o e da especialidade dos participantes na mat\u00e9ria envolvida.<\/p>\n<p>As conclus\u00f5es dos debates e estudos desenvolvidos seja no \u00e2mbito dos GTS, seja na composi\u00e7\u00e3o plen\u00e1ria do Conjur s\u00e3o condensadas em relat\u00f3rios e pareceres que ser\u00e3o utilizados pelas comiss\u00f5es tem\u00e1ticas da CBIC ou encaminhados para as afiliadas, assim como disponibilizados no site da CBIC.<\/p>\n<p>Veja as <a href=\"https:\/\/www.flickr.com\/photos\/cbicfotos\/albums\/72157713441292738\/with\/49645871716\/\">fotos da reuni\u00e3o no Flickr da CBIC<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os provimentos 88 e 89 do Conselho Nacional de Justi\u00e7a (CNJ), que tratam sobre regulamenta\u00e7\u00e3o das medidas de combate \u00e0 lavagem de dinheiro, modificando como devem ser feitos os atos imobili\u00e1rios que repercutam nos cart\u00f3rios, al\u00e9m da regulamenta\u00e7\u00e3o do&#8230;<\/p>\n","protected":false},"author":10,"featured_media":3739,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[51,64],"tags":[132],"class_list":["post-3740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-cbic","category-juridico-agencia-cbic","tag-cartorios"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conselho Jur\u00eddico debate medidas cartor\u00e1rias que impactam o setor - Conselho Jur\u00eddico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/juridico\/es_ES\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conselho Jur\u00eddico debate medidas cartor\u00e1rias que impactam o setor - Conselho Jur\u00eddico\" \/>\n<meta property=\"og:description\" content=\"Os provimentos 88 e 89 do Conselho Nacional de Justi\u00e7a (CNJ), que tratam sobre regulamenta\u00e7\u00e3o das medidas de combate \u00e0 lavagem de dinheiro, modificando como devem ser feitos os atos imobili\u00e1rios que repercutam nos cart\u00f3rios, al\u00e9m da regulamenta\u00e7\u00e3o do...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/juridico\/es_ES\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Conselho Jur\u00eddico\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-12T15:18:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-12T15:18:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbic.org.br\/juridico\/wp-content\/uploads\/sites\/24\/2020\/03\/Reuni\u00e3o_Conjur2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sandra Bezerra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sandra Bezerra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/es_ES\\\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/es_ES\\\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\\\/\"},\"author\":{\"name\":\"Sandra Bezerra\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\"},\"headline\":\"Conselho Jur\u00eddico debate medidas cartor\u00e1rias que impactam o setor\",\"datePublished\":\"2020-03-12T15:18:32+00:00\",\"dateModified\":\"2020-03-12T15:18:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/es_ES\\\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\\\/\"},\"wordCount\":1378,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/es_ES\\\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2020\\\/03\\\/Reuni\u00e3o_Conjur2-scaled.jpg\",\"keywords\":[\"cart\u00f3rios\"],\"articleSection\":[\"Ag\u00eancia CBIC\",\"Jur\u00eddico\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/es_ES\\\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/es_ES\\\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/es_ES\\\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\\\/\",\"name\":\"Conselho Jur\u00eddico debate medidas cartor\u00e1rias que impactam o setor - Conselho Jur\u00eddico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/es_ES\\\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/es_ES\\\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2020\\\/03\\\/Reuni\u00e3o_Conjur2-scaled.jpg\",\"datePublished\":\"2020-03-12T15:18:32+00:00\",\"dateModified\":\"2020-03-12T15:18:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/es_ES\\\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/es_ES\\\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/es_ES\\\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2020\\\/03\\\/Reuni\u00e3o_Conjur2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2020\\\/03\\\/Reuni\u00e3o_Conjur2-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/es_ES\\\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conselho Jur\u00eddico debate medidas cartor\u00e1rias que impactam o setor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/\",\"name\":\"Conselho Jur\u00eddico\",\"description\":\"CONJUR - Conselho Jur\u00eddico\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/en_US\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\",\"name\":\"Sandra Bezerra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"caption\":\"Sandra Bezerra\"},\"sameAs\":[\"https:\\\/\\\/cbic.org.br\"],\"url\":\"https:\\\/\\\/cbic.org.br\\\/juridico\\\/author\\\/sandra-bezerra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conselho Jur\u00eddico debate medidas cartor\u00e1rias que impactam o setor - Conselho Jur\u00eddico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/juridico\/es_ES\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Conselho Jur\u00eddico debate medidas cartor\u00e1rias que impactam o setor - Conselho Jur\u00eddico","og_description":"Os provimentos 88 e 89 do Conselho Nacional de Justi\u00e7a (CNJ), que tratam sobre regulamenta\u00e7\u00e3o das medidas de combate \u00e0 lavagem de dinheiro, modificando como devem ser feitos os atos imobili\u00e1rios que repercutam nos cart\u00f3rios, al\u00e9m da regulamenta\u00e7\u00e3o do...","og_url":"https:\/\/cbic.org.br\/juridico\/es_ES\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\/","og_site_name":"Conselho Jur\u00eddico","article_published_time":"2020-03-12T15:18:32+00:00","article_modified_time":"2020-03-12T15:18:46+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/cbic.org.br\/juridico\/wp-content\/uploads\/sites\/24\/2020\/03\/Reuni\u00e3o_Conjur2-scaled.jpg","type":"image\/jpeg"}],"author":"Sandra Bezerra","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sandra Bezerra","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/juridico\/es_ES\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/juridico\/es_ES\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\/"},"author":{"name":"Sandra Bezerra","@id":"https:\/\/cbic.org.br\/juridico\/en_US\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e"},"headline":"Conselho Jur\u00eddico debate medidas cartor\u00e1rias que impactam o setor","datePublished":"2020-03-12T15:18:32+00:00","dateModified":"2020-03-12T15:18:46+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/juridico\/es_ES\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\/"},"wordCount":1378,"commentCount":0,"image":{"@id":"https:\/\/cbic.org.br\/juridico\/es_ES\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/juridico\/wp-content\/uploads\/sites\/24\/2020\/03\/Reuni\u00e3o_Conjur2-scaled.jpg","keywords":["cart\u00f3rios"],"articleSection":["Ag\u00eancia CBIC","Jur\u00eddico"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cbic.org.br\/juridico\/es_ES\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/juridico\/es_ES\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\/","url":"https:\/\/cbic.org.br\/juridico\/es_ES\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\/","name":"Conselho Jur\u00eddico debate medidas cartor\u00e1rias que impactam o setor - Conselho Jur\u00eddico","isPartOf":{"@id":"https:\/\/cbic.org.br\/juridico\/en_US\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/juridico\/es_ES\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/juridico\/es_ES\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/juridico\/wp-content\/uploads\/sites\/24\/2020\/03\/Reuni\u00e3o_Conjur2-scaled.jpg","datePublished":"2020-03-12T15:18:32+00:00","dateModified":"2020-03-12T15:18:46+00:00","author":{"@id":"https:\/\/cbic.org.br\/juridico\/en_US\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/juridico\/es_ES\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/juridico\/es_ES\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/juridico\/es_ES\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\/#primaryimage","url":"https:\/\/cbic.org.br\/juridico\/wp-content\/uploads\/sites\/24\/2020\/03\/Reuni\u00e3o_Conjur2-scaled.jpg","contentUrl":"https:\/\/cbic.org.br\/juridico\/wp-content\/uploads\/sites\/24\/2020\/03\/Reuni\u00e3o_Conjur2-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/juridico\/es_ES\/conselho-juridico-debate-medidas-cartorarias-que-impactam-o-setor-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/juridico\/"},{"@type":"ListItem","position":2,"name":"Conselho Jur\u00eddico debate medidas cartor\u00e1rias que impactam o setor"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/juridico\/en_US\/#website","url":"https:\/\/cbic.org.br\/juridico\/en_US\/","name":"Conselho Jur\u00eddico","description":"CONJUR - Conselho Jur\u00eddico","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/juridico\/en_US\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/juridico\/en_US\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e","name":"Sandra Bezerra","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","caption":"Sandra Bezerra"},"sameAs":["https:\/\/cbic.org.br"],"url":"https:\/\/cbic.org.br\/juridico\/author\/sandra-bezerra\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/juridico\/wp-json\/wp\/v2\/posts\/3740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/juridico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/juridico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/juridico\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/juridico\/wp-json\/wp\/v2\/comments?post=3740"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/juridico\/wp-json\/wp\/v2\/posts\/3740\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/juridico\/wp-json\/wp\/v2\/media\/3739"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/juridico\/wp-json\/wp\/v2\/media?parent=3740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/juridico\/wp-json\/wp\/v2\/categories?post=3740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/juridico\/wp-json\/wp\/v2\/tags?post=3740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}