{"id":1498,"date":"2020-09-10T18:12:03","date_gmt":"2020-09-10T21:12:03","guid":{"rendered":"https:\/\/cbic.org.br\/habitacao-interesse-social\/2020\/09\/10\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\/"},"modified":"2020-09-10T19:42:34","modified_gmt":"2020-09-10T22:42:34","slug":"governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2","status":"publish","type":"post","link":"https:\/\/cbic.org.br\/habitacao-interesse-social\/2020\/09\/10\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\/","title":{"rendered":"Governo reduz juros para ampliar acesso ao cr\u00e9dito no Norte e Nordeste"},"content":{"rendered":"<p>O Conselho Curador do Fundo de Garantia do Tempo de Servi\u00e7o (FGTS) aprovou no dia 8\/9, por unanimidade, a redu\u00e7\u00e3o de juros no cr\u00e9dito imobili\u00e1rio popular no Norte e Nordeste. O objetivo \u00e9 promover o acesso de mais fam\u00edlias ao financiamento habitacional nessas duas regi\u00f5es, que t\u00eam, historicamente, baixos \u00edndices de contrata\u00e7\u00e3o de financiamento habitacional. Nos \u00faltimos cinco anos, dos recursos disponibilizados para o Nordeste, 23% n\u00e3o foram utilizados por falta de demanda. No caso do Norte, o percentual chega a 78%.<\/p>\n<p>\u201c\u00c9 preciso dar um tratamento diferenciado para essas regi\u00f5es onde o \u00cdndice de Desenvolvimento Humano \u00e9 menor. Por orienta\u00e7\u00e3o do presidente Bolsonaro, estamos buscando meios para alavancar o financiamento habitacional no Norte e Nordeste, de maneira a atender essa parcela da popula\u00e7\u00e3o brasileira que mais precisa\u201d, destaca o ministro do Desenvolvimento Regional, Rog\u00e9rio Marinho.<\/p>\n<p>As mudan\u00e7as na sistem\u00e1tica de financiamentos na \u00e1rea de habita\u00e7\u00e3o popular v\u00e3o possibilitar que o FGTS tenha mais recursos dispon\u00edveis para novas contrata\u00e7\u00f5es. Em linhas gerais, prop\u00f5e-se a redu\u00e7\u00e3o da parcela de\u00a0<em>spread<\/em>\u00a0banc\u00e1rio pago pelo Fundo aos agentes financeiros operadores do programa, sem comprometer, contudo, a sustentabilidade das opera\u00e7\u00f5es.<\/p>\n<p>As regi\u00f5es Norte e Nordeste ser\u00e3o contempladas com a redu\u00e7\u00e3o de juros em at\u00e9 0,5 ponto percentual para fam\u00edlias com renda at\u00e9 R$ 2 mil mensais. Os juros poder\u00e3o chegar a 4,25% ao ano para cotistas do FGTS e, nas demais, a 4,5%, ofertando a menor taxa de juros na hist\u00f3ria num programa habitacional. Com isso, as fam\u00edlias ter\u00e3o uma menor presta\u00e7\u00e3o mensal na aquisi\u00e7\u00e3o de novos im\u00f3veis pelo programa. Veja o detalhamento das taxas de juros no quadro abaixo.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Parcelas suspensas<\/strong><\/h2>\n<p>Em apoio \u00e0s institui\u00e7\u00f5es financeiras respons\u00e1veis pelas opera\u00e7\u00f5es de cr\u00e9dito do setor de habita\u00e7\u00e3o popular nos contratos com pessoas f\u00edsicas, o Conselho Gestor do FGTS decidiu suspender, por at\u00e9 seis meses, o pagamento dos financiamentos contratados por meio dos programas Carta de Cr\u00e9dito Individual, Apoio \u00e0 Produ\u00e7\u00e3o de Habita\u00e7\u00f5es, Carta de Cr\u00e9dito Associativo. A proposta, apresentada pelo Minist\u00e9rio do Desenvolvimento Regional (MDR), foi aprovada nesta ter\u00e7a-feira (8) por unanimidade pelo Conselho Curador do Fundo.<\/p>\n<p>A iniciativa \u00e9 parte do conjunto de medidas da Uni\u00e3o para apoiar setores produtivos afetados pela pandemia da Covid-19. As opera\u00e7\u00f5es de cr\u00e9dito foram realizadas com recursos do FGTS. Pleitos similares j\u00e1 foram atendidos em maio e junho deste ano, em raz\u00e3o de demandas dos setores de saneamento b\u00e1sico e mobilidade urbana.<\/p>\n<p>A expectativa \u00e9 gerar, durante o per\u00edodo de suspens\u00e3o, um al\u00edvio para os agentes financeiros de at\u00e9 R$ 3 bilh\u00f5es, contemplando os contratos de financiamento vigentes dos mutu\u00e1rios de pessoa f\u00edsica. A decis\u00e3o n\u00e3o gera preju\u00edzos ao FGTS, j\u00e1 que n\u00e3o significa o cancelamento, mas apenas a posterga\u00e7\u00e3o das parcelas e a dilui\u00e7\u00e3o do d\u00e9bito ao longo do per\u00edodo residual dos contratos. Os pagamentos ser\u00e3o realizados de forma parcelada, com a atualiza\u00e7\u00e3o financeira devida, considerando que o in\u00edcio do ressarcimento ao Fundo se dar\u00e1 a partir de janeiro de 2021.<\/p>\n<p><em>(Com informa\u00e7\u00f5es da Ascom\/MDR)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho Curador do Fundo de Garantia do Tempo de Servi\u00e7o (FGTS) aprovou no dia 8\/9, por unanimidade, a redu\u00e7\u00e3o de juros no cr\u00e9dito imobili\u00e1rio popular no Norte e Nordeste. O objetivo \u00e9 promover o acesso de mais fam\u00edlias ao financiamento habitacional nessas duas regi\u00f5es, [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":1497,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[5,6,7],"tags":[78,21],"class_list":["post-1498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-cbic","category-habitacao-de-interesse-social-agencia-cbic","category-industria-imobiliaria-agencia-cbic","tag-casa-verde-e-amarela","tag-ccfgts"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Governo reduz juros para ampliar acesso ao cr\u00e9dito no Norte e Nordeste - Comiss\u00e3o de Habita\u00e7\u00e3o de Interesse Social<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbic.org.br\/habitacao-interesse-social\/en_US\/2020\/09\/10\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governo reduz juros para ampliar acesso ao cr\u00e9dito no Norte e Nordeste - Comiss\u00e3o de Habita\u00e7\u00e3o de Interesse Social\" \/>\n<meta property=\"og:description\" content=\"O Conselho Curador do Fundo de Garantia do Tempo de Servi\u00e7o (FGTS) aprovou no dia 8\/9, por unanimidade, a redu\u00e7\u00e3o de juros no cr\u00e9dito imobili\u00e1rio popular no Norte e Nordeste. O objetivo \u00e9 promover o acesso de mais fam\u00edlias ao financiamento habitacional nessas duas regi\u00f5es, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbic.org.br\/habitacao-interesse-social\/en_US\/2020\/09\/10\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Comiss\u00e3o de Habita\u00e7\u00e3o de Interesse Social\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-10T21:12:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-10T22:42:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbic.org.br\/habitacao-interesse-social\/wp-content\/uploads\/sites\/30\/2020\/09\/7022ccdc-edd5-4a82-a082-6f4f0ff850c3.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sandra Bezerra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sandra Bezerra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/en_US\\\/2020\\\/09\\\/10\\\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/en_US\\\/2020\\\/09\\\/10\\\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\\\/\"},\"author\":{\"name\":\"Sandra Bezerra\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/es_ES\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\"},\"headline\":\"Governo reduz juros para ampliar acesso ao cr\u00e9dito no Norte e Nordeste\",\"datePublished\":\"2020-09-10T21:12:03+00:00\",\"dateModified\":\"2020-09-10T22:42:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/en_US\\\/2020\\\/09\\\/10\\\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\\\/\"},\"wordCount\":556,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/en_US\\\/2020\\\/09\\\/10\\\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2020\\\/09\\\/7022ccdc-edd5-4a82-a082-6f4f0ff850c3.jpeg\",\"keywords\":[\"Casa Verde e Amarela\",\"CCFGTS\"],\"articleSection\":[\"Ag\u00eancia CBIC\",\"Habita\u00e7\u00e3o de Interesse Social\",\"Ind\u00fastria Imobili\u00e1ria\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/en_US\\\/2020\\\/09\\\/10\\\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/en_US\\\/2020\\\/09\\\/10\\\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\\\/\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/en_US\\\/2020\\\/09\\\/10\\\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\\\/\",\"name\":\"Governo reduz juros para ampliar acesso ao cr\u00e9dito no Norte e Nordeste - Comiss\u00e3o de Habita\u00e7\u00e3o de Interesse Social\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/es_ES\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/en_US\\\/2020\\\/09\\\/10\\\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/en_US\\\/2020\\\/09\\\/10\\\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2020\\\/09\\\/7022ccdc-edd5-4a82-a082-6f4f0ff850c3.jpeg\",\"datePublished\":\"2020-09-10T21:12:03+00:00\",\"dateModified\":\"2020-09-10T22:42:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/es_ES\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/en_US\\\/2020\\\/09\\\/10\\\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/en_US\\\/2020\\\/09\\\/10\\\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/en_US\\\/2020\\\/09\\\/10\\\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2020\\\/09\\\/7022ccdc-edd5-4a82-a082-6f4f0ff850c3.jpeg\",\"contentUrl\":\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2020\\\/09\\\/7022ccdc-edd5-4a82-a082-6f4f0ff850c3.jpeg\",\"width\":768,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/en_US\\\/2020\\\/09\\\/10\\\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/es_ES\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Governo reduz juros para ampliar acesso ao cr\u00e9dito no Norte e Nordeste\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/es_ES\\\/#website\",\"url\":\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/es_ES\\\/\",\"name\":\"Comiss\u00e3o de Habita\u00e7\u00e3o de Interesse Social\",\"description\":\"CHIS - Comiss\u00e3o de Habita\u00e7\u00e3o de Interesse Social\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/es_ES\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/es_ES\\\/#\\\/schema\\\/person\\\/6640434d1b9631ab33657d2efa75fe9e\",\"name\":\"Sandra Bezerra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g\",\"caption\":\"Sandra Bezerra\"},\"sameAs\":[\"https:\\\/\\\/cbic.org.br\"],\"url\":\"https:\\\/\\\/cbic.org.br\\\/habitacao-interesse-social\\\/author\\\/sandra-bezerra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governo reduz juros para ampliar acesso ao cr\u00e9dito no Norte e Nordeste - Comiss\u00e3o de Habita\u00e7\u00e3o de Interesse Social","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbic.org.br\/habitacao-interesse-social\/en_US\/2020\/09\/10\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Governo reduz juros para ampliar acesso ao cr\u00e9dito no Norte e Nordeste - Comiss\u00e3o de Habita\u00e7\u00e3o de Interesse Social","og_description":"O Conselho Curador do Fundo de Garantia do Tempo de Servi\u00e7o (FGTS) aprovou no dia 8\/9, por unanimidade, a redu\u00e7\u00e3o de juros no cr\u00e9dito imobili\u00e1rio popular no Norte e Nordeste. O objetivo \u00e9 promover o acesso de mais fam\u00edlias ao financiamento habitacional nessas duas regi\u00f5es, [&hellip;]","og_url":"https:\/\/cbic.org.br\/habitacao-interesse-social\/en_US\/2020\/09\/10\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\/","og_site_name":"Comiss\u00e3o de Habita\u00e7\u00e3o de Interesse Social","article_published_time":"2020-09-10T21:12:03+00:00","article_modified_time":"2020-09-10T22:42:34+00:00","og_image":[{"width":768,"height":512,"url":"https:\/\/cbic.org.br\/habitacao-interesse-social\/wp-content\/uploads\/sites\/30\/2020\/09\/7022ccdc-edd5-4a82-a082-6f4f0ff850c3.jpeg","type":"image\/jpeg"}],"author":"Sandra Bezerra","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sandra Bezerra","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbic.org.br\/habitacao-interesse-social\/en_US\/2020\/09\/10\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\/#article","isPartOf":{"@id":"https:\/\/cbic.org.br\/habitacao-interesse-social\/en_US\/2020\/09\/10\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\/"},"author":{"name":"Sandra Bezerra","@id":"https:\/\/cbic.org.br\/habitacao-interesse-social\/es_ES\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e"},"headline":"Governo reduz juros para ampliar acesso ao cr\u00e9dito no Norte e Nordeste","datePublished":"2020-09-10T21:12:03+00:00","dateModified":"2020-09-10T22:42:34+00:00","mainEntityOfPage":{"@id":"https:\/\/cbic.org.br\/habitacao-interesse-social\/en_US\/2020\/09\/10\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\/"},"wordCount":556,"commentCount":0,"image":{"@id":"https:\/\/cbic.org.br\/habitacao-interesse-social\/en_US\/2020\/09\/10\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/habitacao-interesse-social\/wp-content\/uploads\/sites\/30\/2020\/09\/7022ccdc-edd5-4a82-a082-6f4f0ff850c3.jpeg","keywords":["Casa Verde e Amarela","CCFGTS"],"articleSection":["Ag\u00eancia CBIC","Habita\u00e7\u00e3o de Interesse Social","Ind\u00fastria Imobili\u00e1ria"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cbic.org.br\/habitacao-interesse-social\/en_US\/2020\/09\/10\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cbic.org.br\/habitacao-interesse-social\/en_US\/2020\/09\/10\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\/","url":"https:\/\/cbic.org.br\/habitacao-interesse-social\/en_US\/2020\/09\/10\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\/","name":"Governo reduz juros para ampliar acesso ao cr\u00e9dito no Norte e Nordeste - Comiss\u00e3o de Habita\u00e7\u00e3o de Interesse Social","isPartOf":{"@id":"https:\/\/cbic.org.br\/habitacao-interesse-social\/es_ES\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbic.org.br\/habitacao-interesse-social\/en_US\/2020\/09\/10\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\/#primaryimage"},"image":{"@id":"https:\/\/cbic.org.br\/habitacao-interesse-social\/en_US\/2020\/09\/10\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cbic.org.br\/habitacao-interesse-social\/wp-content\/uploads\/sites\/30\/2020\/09\/7022ccdc-edd5-4a82-a082-6f4f0ff850c3.jpeg","datePublished":"2020-09-10T21:12:03+00:00","dateModified":"2020-09-10T22:42:34+00:00","author":{"@id":"https:\/\/cbic.org.br\/habitacao-interesse-social\/es_ES\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e"},"breadcrumb":{"@id":"https:\/\/cbic.org.br\/habitacao-interesse-social\/en_US\/2020\/09\/10\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbic.org.br\/habitacao-interesse-social\/en_US\/2020\/09\/10\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cbic.org.br\/habitacao-interesse-social\/en_US\/2020\/09\/10\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\/#primaryimage","url":"https:\/\/cbic.org.br\/habitacao-interesse-social\/wp-content\/uploads\/sites\/30\/2020\/09\/7022ccdc-edd5-4a82-a082-6f4f0ff850c3.jpeg","contentUrl":"https:\/\/cbic.org.br\/habitacao-interesse-social\/wp-content\/uploads\/sites\/30\/2020\/09\/7022ccdc-edd5-4a82-a082-6f4f0ff850c3.jpeg","width":768,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/cbic.org.br\/habitacao-interesse-social\/en_US\/2020\/09\/10\/governo-reduz-juros-para-ampliar-acesso-ao-credito-no-norte-e-nordeste-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbic.org.br\/habitacao-interesse-social\/es_ES\/"},{"@type":"ListItem","position":2,"name":"Governo reduz juros para ampliar acesso ao cr\u00e9dito no Norte e Nordeste"}]},{"@type":"WebSite","@id":"https:\/\/cbic.org.br\/habitacao-interesse-social\/es_ES\/#website","url":"https:\/\/cbic.org.br\/habitacao-interesse-social\/es_ES\/","name":"Comiss\u00e3o de Habita\u00e7\u00e3o de Interesse Social","description":"CHIS - Comiss\u00e3o de Habita\u00e7\u00e3o de Interesse Social","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbic.org.br\/habitacao-interesse-social\/es_ES\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/cbic.org.br\/habitacao-interesse-social\/es_ES\/#\/schema\/person\/6640434d1b9631ab33657d2efa75fe9e","name":"Sandra Bezerra","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3310d7e668c719cc4171f3cb4d8a9e2f8de8c9923e5adc11dfb0e3b47198332e?s=96&d=mm&r=g","caption":"Sandra Bezerra"},"sameAs":["https:\/\/cbic.org.br"],"url":"https:\/\/cbic.org.br\/habitacao-interesse-social\/author\/sandra-bezerra\/"}]}},"_links":{"self":[{"href":"https:\/\/cbic.org.br\/habitacao-interesse-social\/wp-json\/wp\/v2\/posts\/1498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbic.org.br\/habitacao-interesse-social\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbic.org.br\/habitacao-interesse-social\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/habitacao-interesse-social\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/habitacao-interesse-social\/wp-json\/wp\/v2\/comments?post=1498"}],"version-history":[{"count":0,"href":"https:\/\/cbic.org.br\/habitacao-interesse-social\/wp-json\/wp\/v2\/posts\/1498\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbic.org.br\/habitacao-interesse-social\/wp-json\/wp\/v2\/media\/1497"}],"wp:attachment":[{"href":"https:\/\/cbic.org.br\/habitacao-interesse-social\/wp-json\/wp\/v2\/media?parent=1498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbic.org.br\/habitacao-interesse-social\/wp-json\/wp\/v2\/categories?post=1498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbic.org.br\/habitacao-interesse-social\/wp-json\/wp\/v2\/tags?post=1498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}